{"id":46550,"date":"2017-07-17T06:26:56","date_gmt":"2017-07-17T09:26:56","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=46550"},"modified":"2017-07-15T01:59:35","modified_gmt":"2017-07-15T04:59:35","slug":"match-day-flamengo-e-gremio","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2017\/07\/match-day-flamengo-e-gremio\/","title":{"rendered":"Match Day \u2013 Flamengo x Gr\u00eamio"},"content":{"rendered":"<p style=\"text-align: justify;\">Na \u00faltima quinta-feira, antes da partida entre Flamengo e Gr\u00eamio pelo Campeonato Brasileiro, participei de uma das a\u00e7\u00f5es do plano de S\u00f3cio-Torcedor do Flamengo: o match day.<\/p>\n<p style=\"text-align: justify;\">A associa\u00e7\u00e3o ao plano d\u00e1 direito de concorrer ao que se chama de \u201cexperi\u00eancias\u201d: cada a\u00e7\u00e3o (compra de ingressos, entrada no site, atualiza\u00e7\u00e3o de cadastro, renova\u00e7\u00e3o) gera uma quantidade de pontos que, acumulada, pode ser trocada na p\u00e1gina correspondente por uma s\u00e9rie de experi\u00eancias.<\/p>\n<p style=\"text-align: justify;\">Entre as experi\u00eancias, uma delas \u00e9 a chamada \u201cMatch Day\u201d. Na Ilha do Urubu, onde o Flamengo tem mandado suas partidas, \u00e9 uma vers\u00e3o simplificada da ocorrida anteriormente no Maracan\u00e3, devido \u00e0s limita\u00e7\u00f5es de espa\u00e7o.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174236.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-46552\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174236-453x340.jpg\" alt=\"\" width=\"593\" height=\"445\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174236-453x340.jpg 453w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174236-300x225.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174236-768x576.jpg 768w\" sizes=\"auto, (max-width: 593px) 100vw, 593px\" \/><\/a>Com pontos acumulados desde janeiro e sem nunca ter participado de nenhuma promo\u00e7\u00e3o, j\u00e1 vinha h\u00e1 algumas partidas tentando uma vaga. Mas nunca conseguia sucesso.<\/p>\n<p style=\"text-align: justify;\">At\u00e9 que, na noite de segunda feira passada, enquanto esperava a \u00e1rea de Contabilidade no meu trabalho dar o o.k. a algumas informa\u00e7\u00f5es que havia enviado, vejo tweet do perfil do programa avisando que estava aberto para a partida da \u00faltima quinta.<\/p>\n<p style=\"text-align: justify;\">Em quest\u00e3o de segundos, abri o site do programa e consegui fazer rapidamente minha inscri\u00e7\u00e3o. Pura sorte, como veria posteriormente. A promo\u00e7\u00e3o envolveria a \u201cvisita aos bastidores\u201d e um ingresso para a partida, originalmente no Setor Sul.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_173552.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-46553\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_173552-453x340.jpg\" alt=\"\" width=\"592\" height=\"444\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_173552-453x340.jpg 453w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_173552-300x225.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_173552-768x576.jpg 768w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/a>Inscri\u00e7\u00e3o feita, recebemos um e-mail de confirma\u00e7\u00e3o com instru\u00e7\u00f5es \u2013 bem sucintas, ali\u00e1s, poderia ser mais detalhado \u2013 para a chegada ao port\u00e3o principal, bem como algumas regras. Por exemplo, n\u00e3o se pode utilizar da promo\u00e7\u00e3o para criticar jogadores, entre outras. E, sinceramente, n\u00e3o \u00e9 o momento para tal.<\/p>\n<p style=\"text-align: justify;\">Eu me organizei para sair um pouco mais cedo do trabalho, devido ao tr\u00e2nsito. Passei em casa, deixei meu carro, comi algo e parti para a Ilha do Urubu, que fica a uns 15 minutos de caminhada (sem pressa) da minha casa.<\/p>\n<p style=\"text-align: justify;\">Cheguei com alguma anteced\u00eancia \u2013 fora pedido de que estiv\u00e9ssemos duas horas antes do in\u00edcio da partida &#8211; e j\u00e1 estava o pessoal do clube nos esperando. Algumas regras adicionais foram colocadas ali, como por exemplo n\u00e3o pedir fotos aos jogadores no momento da chegada ao campo \u2013 para n\u00e3o atrapalhar a concentra\u00e7\u00e3o \u2013 e evitar pisar no gramado.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174548.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-46555\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174548-453x340.jpg\" alt=\"\" width=\"592\" height=\"444\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174548-453x340.jpg 453w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174548-300x225.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174548-768x576.jpg 768w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/a>Tamb\u00e9m fica claro o porqu\u00ea de ser t\u00e3o dif\u00edcil conseguir: s\u00e3o apenas cinco vagas, devido \u00e0s limita\u00e7\u00f5es de espa\u00e7o. N\u00f3s ir\u00edamos aos vesti\u00e1rios, depois ao gramado e fechar\u00edamos recepcionando o time na chegada \u00e0 Ilha do Governador.<\/p>\n<p style=\"text-align: justify;\">Anteriormente havia intera\u00e7\u00e3o com os jogadores ao final da partida, mas neste momento est\u00e1 suspenso. Segundo me explicaram, pela indefini\u00e7\u00e3o ocorrida de se autorizar ou n\u00e3o o contato dependendo do resultado e dos humores p\u00f3s-jogo.<\/p>\n<p style=\"text-align: justify;\">Coloca-se a credencial e pulseira obrigat\u00f3rias, a camisa do programa \u00e9 dada quando chegamos e entramos no est\u00e1dio pelo setor Oeste. Atravessamos as cadeiras e descemos \u00e0 \u00e1rea dos vesti\u00e1rios, para a primeira parte da visita.<\/p>\n<p style=\"text-align: justify;\">O vesti\u00e1rio do time \u00e9 dividido em duas \u00e1reas: na primeira, fica o pessoal da retaguarda com a estrutura necess\u00e1ria e, na segunda, o vesti\u00e1rio propriamente dito, onde os jogadores se arrumam.<\/p>\n<p><iframe loading=\"lazy\" title=\"Match Day s\u00f3cio torcedor Fla e Gr\u00eamio - Vesti\u00e1rio do Flamengo\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/luv-roJLGlY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">Este \u00e9 bem pequeno, como podem ver no v\u00eddeo acima. Imaginar 22 jogadores se trocando ao mesmo tempo naquele espa\u00e7o de uns 30 metros quadrados deve ser algo bem confuso. Na outra sala ficam os uniformes da Comiss\u00e3o T\u00e9cnica, as bolas e demais apetrechos necess\u00e1rios ao trabalho de aquecimento (feito no campo de jogo), as mesas de fisioterapia\/cuidados m\u00e9dicos e uma mesa com salada de frutas e garrafas t\u00e9rmicas \u2013 acredito que de suco, leite e caf\u00e9.<\/p>\n<p style=\"text-align: justify;\">Cada jogador tem sua \u201cbaia\u201d com o material de jogo. Camisas (primeiro e segundo tempo), cal\u00e7\u00e3o, roupa t\u00e9rmica, chuteiras (tr\u00eas ou quatro pares para cada jogador), chinelos e um par de t\u00eanis. Por algum motivo que n\u00e3o saberia explicar, na baia do jogador Par\u00e1 havia uma camisa do Gr\u00eamio personalizada, ele que \u00e9 ex-jogador da equipe.<\/p>\n<p style=\"text-align: justify;\">O momento em sequ\u00eancia \u00e9 a passagem ao campo, na qual reproduzimos o caminho tomado pelos jogadores. Todo aficionado por futebol sonha poder fazer isso um dia, mesmo que n\u00e3o v\u00e1 jogar. E a sensa\u00e7\u00e3o \u00e9 muito legal: sai do vesti\u00e1rio, d\u00e1 alguns passos, atravessa o t\u00fanel infl\u00e1vel e sai ao campo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174611.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-46557\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174611-453x340.jpg\" alt=\"\" width=\"593\" height=\"445\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174611-453x340.jpg 453w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174611-300x225.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174611-768x576.jpg 768w\" sizes=\"auto, (max-width: 593px) 100vw, 593px\" \/><\/a>Da escurid\u00e3o \u00e0 claridade.<\/p>\n<p style=\"text-align: justify;\">Por incr\u00edvel quanto pare\u00e7a, tenho 42 anos,<a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2010\/06\/visita-a-arena-da-baixada\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"> mas a \u00fanica vez em que estive na beira de um gramado na vida tinha sido quando fiz o tour de visita\u00e7\u00e3o na antiga Arena da Baixada, em 2010<\/span><\/a>. E me senti uma crian\u00e7a quando adentramos esta \u00e1rea.<\/p>\n<p><iframe loading=\"lazy\" title=\"Match Day s\u00f3cio torcedor Fla e Gr\u00eamio - Campo\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/O4sw7Sgs82g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">Teoricamente n\u00e3o se pode pisar no gramado propriamente dito, a pedido dos organizadores, mas deu para sentir este gostinho na \u00e1rea \u00e0 esquerda das tribunas de imprensa. Caminhei perto do banco de reservas e da \u00e1rea t\u00e9cnica, at\u00e9 para ter uma no\u00e7\u00e3o do campo de vis\u00e3o do treinador.<\/p>\n<p style=\"text-align: justify;\">Tiramos fotos com o mascote no centro do campo e fomos ao gol \u00e0 esquerda registrar imagens com a bandeira do clube na marca do escanteio e no escudo.<\/p>\n<p style=\"text-align: justify;\">Algo que chama a aten\u00e7\u00e3o \u00e9 a proximidade da linha de fundo com o Setor Norte. Com o est\u00e1dio vazio como naquele momento j\u00e1 \u00e9 algo intimidador. Fico imaginando com ele cheio durante uma partida. Voc\u00ea consegue visualizar os rostos das pessoas, n\u00e3o \u00e9 algo amorfo como no Maracan\u00e3, por exemplo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_175303.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-46551\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_175303-453x340.jpg\" alt=\"\" width=\"592\" height=\"444\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_175303-453x340.jpg 453w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_175303-300x225.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_175303-768x576.jpg 768w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/a>Ainda me permiti uma gracinha ao pedir para ser fotografado beijando a bandeira \u00e0 moda das escolas de samba e, antes, ajoelhado na grama. Fiz quest\u00e3o de ir at\u00e9 a baliza, tocar nas traves e na rede, sentir a energia do local.<\/p>\n<p style=\"text-align: justify;\">Sa\u00edmos correndo, porque a delega\u00e7\u00e3o do Flamengo chegou um pouco antes do previsto. Fizemos um corredor para recepcionar o time e pudemos ver um a um. Primeiro desceram o presidente Bandeira de Mello (que fez quest\u00e3o de cumprimentar todas as pessoas), o diretor de futebol Rodrigo Caetano e o t\u00e9cnico Z\u00e9 Ricardo.<\/p>\n<p><iframe loading=\"lazy\" title=\"Fla e Gr\u00eamio - Chegada do Flamengo\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/8DoG8CY-YYE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">Depois os jogadores foram descendo, uns passando mais r\u00e1pido, outros mais devagar. Pede-se no regulamento que n\u00e3o tiremos fotos com eles (apenas deles), para n\u00e3o atrapalhar a concentra\u00e7\u00e3o, bem como limitar as palavras a gestos de incentivos.<\/p>\n<p style=\"text-align: justify;\">Ainda assim, o estreante Geuv\u00e2nio parou e trocou duas ou tr\u00eas palavras conosco. Nada digno de registro, mas vale elogiar o gesto \u2013 ele n\u00e3o tinha obriga\u00e7\u00e3o de fazer isso.<\/p>\n<p style=\"text-align: justify;\">Sendo uma vers\u00e3o encurtada da experi\u00eancia, para n\u00f3s acabou ali. Subimos de volta, fizemos a foto oficial e devido a uma quest\u00e3o operacional eu troquei meu ingresso do Setor Sul para o Oeste, onde assisti \u00e0 partida. Durou uns 40 minutos no total, mais ou menos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174917.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-46558\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174917-453x340.jpg\" alt=\"\" width=\"592\" height=\"444\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174917-453x340.jpg 453w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174917-300x225.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174917-768x576.jpg 768w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/a>Resumindo: os leitores sabem que acho a rela\u00e7\u00e3o custo\/benef\u00edcio deste plano de S\u00f3cio Torcedor do Flamengo bastante inadequada. Eu s\u00f3 me associei porque, com a Ilha do Urubu ao lado de casa, passei a ir muito mais vezes ao est\u00e1dio.<\/p>\n<p style=\"text-align: justify;\">Entretanto, este tipo de experi\u00eancia oferecido, ainda que em uma vers\u00e3o encurtada devido \u00e0 estrutura do est\u00e1dio, vale muito a pena, sendo uma \u00f3tima iniciativa por parte do clube e do programa. Se tiverem oportunidade, recomendo bastante.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174500.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-46559\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174500-453x340.jpg\" alt=\"\" width=\"592\" height=\"444\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174500-453x340.jpg 453w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174500-300x225.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174500-768x576.jpg 768w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/a>A equipe dos respons\u00e1veis pela visita tamb\u00e9m foi bastante atenciosa e est\u00e1 de parab\u00e9ns pelo trabalho bem feito.<\/p>\n<p style=\"text-align: justify;\">Fiquei me sentindo uma crian\u00e7a que ganhou um presente. E mesmo a derrota posterior (pelo amor de Deus, um goleiro) n\u00e3o conseguiu me deixar chateado. Foi muito legal.<\/p>\n<p style=\"text-align: justify;\">D\u00favidas, perguntas, utilizem a \u00e1rea de coment\u00e1rios.<\/p>\n<p><strong>Imagens: Ouro de Tolo<\/strong><\/p>\n<p><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174446.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-46554\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174446-453x340.jpg\" alt=\"\" width=\"593\" height=\"445\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174446-453x340.jpg 453w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174446-300x225.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/07\/20170713_174446-768x576.jpg 768w\" sizes=\"auto, (max-width: 593px) 100vw, 593px\" \/><\/a><\/p>\n<p>[related_posts limit=&#8221;3&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima quinta-feira, antes da partida entre Flamengo e Gr\u00eamio pelo Campeonato Brasileiro, participei de uma das a\u00e7\u00f5es do plano de S\u00f3cio-Torcedor do Flamengo: oTour Details<\/p>\n","protected":false},"author":2,"featured_media":46561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[41,42,37],"class_list":["post-46550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pedro-migao","tag-esporte","tag-flamengo","tag-futebol"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/46550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=46550"}],"version-history":[{"count":5,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/46550\/revisions"}],"predecessor-version":[{"id":46577,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/46550\/revisions\/46577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media\/46561"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=46550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=46550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=46550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}