{"id":46304,"date":"2017-06-05T07:30:10","date_gmt":"2017-06-05T10:30:10","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=46304"},"modified":"2017-06-23T08:55:24","modified_gmt":"2017-06-23T11:55:24","slug":"nenhuma-religiao-e-lei","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2017\/06\/nenhuma-religiao-e-lei\/","title":{"rendered":"Nenhuma religi\u00e3o \u00e9 lei"},"content":{"rendered":"<p style=\"text-align: justify;\">Na Suprema Corte, o crucifixo fica acima do presidente da casa. No Congresso, ele est\u00e1 junto ao presidente e as salas de comiss\u00f5es s\u00e3o verdadeiros palcos para cultos de determinadas religi\u00f5es. No Planalto, bispos se revezam para dar a ben\u00e7\u00e3o ao presidente e tirar dele a fama de \u201cpacto com o diabo\u201d. A Funda\u00e7\u00e3o onde dois m\u00e9diuns incorporam o esp\u00edrito de um cacique e assina contratos com governos para interferir no clima. Isso sem falar nos milhares de vereadores e prefeitos pastores espalhados pelo pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">A bancada evang\u00e9lica, no Congresso, \u00e9 composta de mais de 80 deputados. Se fosse um partido, seria a terceira maior e perderia apenas para o PMDB e PT. Da direita para a esquerda, quase todos os partidos tem membros na Frente Parlamentar Evang\u00e9lica (FPE), que \u00e9 presidida pelo deputado federal Jo\u00e3o Campos (PSDB). Isso sem falar nos cat\u00f3licos que s\u00e3o eleitos gra\u00e7as a ajuda das igrejas, TVs e r\u00e1dios de funda\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Uma bancada grande como a FPE j\u00e1 mostrou suas garras e seus poderes ao interferir em pol\u00edticas p\u00fablicas para a educa\u00e7\u00e3o, sa\u00fade e direitos humanos.<\/p>\n<p style=\"text-align: justify;\">Se o pa\u00eds hoje consegue realizar pesquisa com c\u00e9lulas-tronco e reconhece o casamento entre pessoas do mesmo sexo, devemos isso ao Supremo Tribunal Federal e n\u00e3o ao Congresso Nacional onde, mesmo aqueles que n\u00e3o fazem parte de bancadas religiosas, acabam votando contra projetos que colocam em xeque a laicidade do Estado com medo de perder voto na pr\u00f3xima elei\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O discurso de \u00f3dio e de quebra do Estado laico j\u00e1 avan\u00e7ou a um ponto de perdermos direitos assegurados. Se at\u00e9 dois anos atr\u00e1s discut\u00edamos o casamento gay, o nome social para transexuais, hoje discutimos se a Terra \u00e9 realmente plana (?). N\u00e3o voltamos ao s\u00e9culo XIX. Regredimos \u00e0 \u00e9poca de Galileu.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-46305\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/06\/parada-lgbt-sp-700x321-300x138.jpg\" alt=\"\" width=\"300\" height=\"138\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/06\/parada-lgbt-sp-700x321-300x138.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/06\/parada-lgbt-sp-700x321-550x252.jpg 550w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/06\/parada-lgbt-sp-700x321.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\">Por\u00e9m, para toda a\u00e7\u00e3o h\u00e1 uma rea\u00e7\u00e3o e no pr\u00f3ximo dia 18, milhares de pessoas ir\u00e3o \u00e0s ruas da maior cidade do pa\u00eds protestar pelo Estado Laico. Com o tema: \u201cIndependente de nossas cren\u00e7as, nenhuma religi\u00e3o \u00e9 Lei! Todas e todos por um Estado Laico\u201d, a 21\u00aa Parada do Orgulho LGBT de S\u00e3o Paulo vai lotar a Avenida Paulista prometendo um protesto com luta, mas sem perder a alegria e com muita m\u00fasica, caracter\u00edsticas que j\u00e1 se tornaram da Parada.<\/p>\n<p style=\"text-align: justify;\">\u00c9 justamente a luta por um Estado que d\u00ea direitos a todas as pessoas que os organizadores buscam com a parada do pr\u00f3ximo dia 18, segundo presidenta da APOGLBT-SP, Cl\u00e1udia Regina: <em>\u201cnossos principais inimigos hoje s\u00e3o os fundamentalistas religiosos, grupos de pessoas dentro de algumas religi\u00f5es que insistem em nos condenar e retirar direitos j\u00e1 adquiridos. No Congresso Nacional, por exemplo, o debate sobre a criminaliza\u00e7\u00e3o da LGBTFobia \u00e9 repleto de ataques de parlamentares da bancada religiosa e conservadora, muito dos quais utilizando-se de suas imunidades parlamentares para disseminar o \u00f3dio a uma parcela da popula\u00e7\u00e3o. Seus argumentos? Alguns citam suas vis\u00f5es de f\u00e9, como se estivessem em seus p\u00falpitos e n\u00e3o em uma institui\u00e7\u00e3o que deveria garantir e se orientar pela laicidade, preconizada na Constitui\u00e7\u00e3o Federal de 88.\u201d<\/em><\/p>\n<p style=\"text-align: justify;\">A Parada j\u00e1 foi criticada, em 2015, quando uma transexual foi \u201ccrucificada\u201d representando os milhares de mortos pela transfobia no pa\u00eds e que j\u00e1 falei <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2015\/06\/na-paulista-nao-era-cristo\/\" target=\"_blank\" rel=\"noopener noreferrer\">aqui<\/a><\/span>. A FPE usou do Congresso Nacional para exalar todo o seu \u00f3dio contra a atriz e os LGBTs.<\/p>\n<p style=\"text-align: justify;\">Ter, ou n\u00e3o ter, uma religi\u00e3o, uma cren\u00e7a, uma f\u00e9 \u00e9 direito assegurado pela Constitui\u00e7\u00e3o Federal para todos os cidad\u00e3os brasileiros e cada eleitor tem o direito de votar naquilo que ele ache que \u00e9 o melhor para o pa\u00eds, mas \u00e9 preciso lembrar, em pleno s\u00e9culo XXI, que nossa lei m\u00e1xima n\u00e3o \u00e9 a B\u00edblia e sim a Constitui\u00e7\u00e3o Federal do pa\u00eds. N\u00e3o devemos aceitar que palavras escritas h\u00e1 dois mil anos e que parte da popula\u00e7\u00e3o n\u00e3o acredita, seja tratada como lei m\u00e1xima de um pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">Nem cat\u00f3lica, nem judaica, nem evang\u00e9lica, nem candombl\u00e9. Nenhuma religi\u00e3o \u00e9 lei.<\/p>\n<p style=\"text-align: justify;\"><em>com colabora\u00e7\u00e3o da assessoria de imprensa da 21\u00aa Parada do Orgulho LGBT de S\u00e3o Paulo<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>SERVI\u00c7O:<\/strong><\/p>\n<p style=\"text-align: justify;\">21\u00aa Edi\u00e7\u00e3o da Parada do Orgulho LGBT de S\u00e3o Paulo<br \/>\n\u2013 Tema: \u201cIndependente de nossas cren\u00e7as, nenhuma religi\u00e3o \u00e9 lei! Todas e todos por um Estado Laico\u201d<br \/>\n\u2013 Hor\u00e1rio: das 10h \u00e0s 18h<br \/>\n\u2013 Concentra\u00e7\u00e3o: Em frente ao Masp, na Avenida Paulista \u2013 S\u00e3o Paulo\/SP<br \/>\n\u2013 Realiza\u00e7\u00e3o: APOGLBT<br \/>\n\u2013 Patroc\u00ednio: Skol, Uber e Doritos<br \/>\n\u2013 Apoio: Microsoft<br \/>\n\u2013 Apoio institucional: Prefeitura de S\u00e3o Paulo<br \/>\n\u2013 Agenda completa da APOGLBT:\u00a0<span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"http:\/\/paradasp.org.br\/agenda2017\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/paradasp.org.br\/agenda2017<\/a><\/span><br \/>\n\u2013 Evento oficial no Facebook:\u00a0<span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"https:\/\/www.facebook.com\/events\/105978123240834\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/events\/105978123240834<\/a><\/span><\/p>\n<p style=\"text-align: justify;\">[related_posts limit=&#8221;3&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na Suprema Corte, o crucifixo fica acima do presidente da casa. No Congresso, ele est\u00e1 junto ao presidente e as salas de comiss\u00f5es s\u00e3o verdadeirosTour Details<\/p>\n","protected":false},"author":36,"featured_media":46306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[719],"tags":[60,1252,1253,949,24,364,9],"class_list":["post-46304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-devaneios","tag-brasil","tag-estado-laico","tag-luta","tag-parada-lgbt","tag-politica","tag-protesto","tag-religiao"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/46304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=46304"}],"version-history":[{"count":6,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/46304\/revisions"}],"predecessor-version":[{"id":46312,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/46304\/revisions\/46312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media\/46306"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=46304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=46304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=46304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}