{"id":42066,"date":"2016-06-22T06:49:14","date_gmt":"2016-06-22T09:49:14","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=42066"},"modified":"2016-08-01T08:21:07","modified_gmt":"2016-08-01T11:21:07","slug":"dicas-de-mobilidade-urbana-para-a-rio-2016-ii","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2016\/06\/dicas-de-mobilidade-urbana-para-a-rio-2016-ii\/","title":{"rendered":"Dicas de Mobilidade Urbana para a Rio 2016 (II)"},"content":{"rendered":"<p style=\"text-align: justify;\">Ontem, <a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2016\/06\/dicas-de-mobilidade-urbana-para-a-rio-2016-i\/\" target=\"_blank\"><span style=\"color: #ff6600;\">na primeira parte do artigo com dicas de mobilidade urbana para a Rio 2016<\/span><\/a>, mostramos um resumo dos bloqueios de tr\u00e2nsito e altera\u00e7\u00f5es vi\u00e1rias na cidade durante o per\u00edodo dos Jogos Ol\u00edmpicos e Paral\u00edmpicos do Rio de Janeiro, bem como dos hor\u00e1rios de funcionamento dos meios de transporte durante as competi\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Hoje, na segunda parte, o objetivo \u00e9 mostrar algumas op\u00e7\u00f5es de roteiros saindo de diversos pontos da cidade at\u00e9 os principais Parques Ol\u00edmpicos determinados como sede das instala\u00e7\u00f5es, bem como a previs\u00e3o de tempo entre as mesmas. Opto sempre por todo o trajeto em transporte coletivo, a n\u00e3o ser que isso seja imposs\u00edvel.<\/p>\n<p style=\"text-align: justify;\">Tamb\u00e9m tomo como dado que o Metr\u00f4 Linha 4 estar\u00e1 inaugurado e funcionando durante o per\u00edodo das competi\u00e7\u00f5es, bem como a Transol\u00edmpica e o rabicho da Transoeste entre o Jardim Oce\u00e2nico e o Parque Ol\u00edmpico. A esta\u00e7\u00e3o do BRT Madureira considerada \u00e9 a Madureira\/Manac\u00e9ia.<\/p>\n<p style=\"text-align: justify;\">Para quem vem de Niter\u00f3i, a caminhada entre as barcas e a esta\u00e7\u00e3o Carioca do metr\u00f4 \u00e9 de 800 metros, por\u00e9m as barcas s\u00e3o um tanto isoladas dos outros modais de massa e a caminhada ainda \u00e9 o melhor meio de se chegar ao metr\u00f4. A solu\u00e7\u00e3o desse problema ser\u00e1 a linha 2 do VLT, mas que com previs\u00e3o de conclus\u00e3o apenas em dezembro, \u00e9 certo que n\u00e3o ficar\u00e1 pronta a tempo dos Jogos Ol\u00edmpicos.<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160612_091011.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-42029\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160612_091011-550x309.jpg\" alt=\"20160612_091011\" width=\"550\" height=\"309\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160612_091011-550x309.jpg 550w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160612_091011-300x169.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160612_091011-768x432.jpg 768w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a>1 &#8211; Parque Ol\u00edmpico de Jacarepagu\u00e1\/Riocentro<\/strong><\/p>\n<p style=\"text-align: justify;\">Em termos de mobilidade, estas duas subsedes podem ser tratadas como uma somente, pois a dist\u00e2ncia entre elas \u00e9 de aproximadamente dois quil\u00f4metros &#8211; ou uma esta\u00e7\u00e3o do BRT. O Parque Ol\u00edmpico ir\u00e1 se utilizar das esta\u00e7\u00f5es Rio II e Centro Ol\u00edmpico, enquanto o Riocentro ter\u00e1 como op\u00e7\u00f5es as esta\u00e7\u00f5es Riocentro, Olof Palme e Morro do Outeiro.<\/p>\n<p style=\"text-align: justify;\">A princ\u00edpio os estacionamentos dos shoppings Via Parque e Barra Shopping podem ser uma op\u00e7\u00e3o de estacionamento, mas, como alertado ontem, os bloqueios de tr\u00e2nsito tendem a deixar o tr\u00e1fego insuport\u00e1vel nesta regi\u00e3o.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><em>Do Centro\/Zona Sul:<\/em> Metr\u00f4 Linha 1, transbordo na esta\u00e7\u00e3o General Os\u00f3rio, Metr\u00f4 Linha 4, transbordo na esta\u00e7\u00e3o Jardim Oce\u00e2nico, BRT servi\u00e7o especial Centro Ol\u00edmpico, destino final nesta esta\u00e7\u00e3o. Lembrete: todos os transbordos e desembarques neste caso s\u00e3o em esta\u00e7\u00f5es terminais &#8211; finais de linha.<\/li>\n<li style=\"text-align: justify;\"><em>Zona Norte (Sub\u00farbios da Central)<\/em>: trem, esta\u00e7\u00e3o Madureira, transbordo, BRT servi\u00e7o especial Centro Ol\u00edmpico, descida nesta esta\u00e7\u00e3o;<\/li>\n<li style=\"text-align: justify;\">Zona Norte (Tijuca, Graja\u00fa, Andara\u00ed); o mesmo que o recomendado para o Centro e Zona Sul;<\/li>\n<li style=\"text-align: justify;\"><em>Zona Norte (Sub\u00farbios da Leopoldina):<\/em> aqui h\u00e1 duas op\u00e7\u00f5es. A primeira \u00e9 pegar o BRT parador e descer na esta\u00e7\u00e3o Rio II, sem transbordo &#8211; mas esta \u00e9 uma alternativa\u00a0mais longa. A segunda \u00e9 pegar o BRT parador, descer em Vicente de Carvalho e pegar o servi\u00e7o ol\u00edmpico especial expresso at\u00e9 as esta\u00e7\u00f5es Centro Ol\u00edmpico ou Riocentro.<\/li>\n<li style=\"text-align: justify;\"><em>Ilha do Governador\/Aeroporto do Gale\u00e3o:<\/em> aqui nem tem o que se pensar. Venha de carro, t\u00e1xi ou \u00f4nibus at\u00e9 o Gale\u00e3o <a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2016\/02\/evento-teste-copa-do-mundo-de-saltos-ornamentais\/\" target=\"_blank\"><span style=\"color: #ff6600;\">ou \u00e0 esta\u00e7\u00e3o do Fund\u00e3o<\/span><\/a>, pegue o BRT direto at\u00e9 Vicente de Carvalho, des\u00e7a e na mesma esta\u00e7\u00e3o pegue o servi\u00e7o ol\u00edmpico expresso at\u00e9 a esta\u00e7\u00e3o Centro Ol\u00edmpico ou Riocentro, dependendo do ingresso. Na volta, a \u00fanica diferen\u00e7a \u00e9 que talvez seja melhor descer do servi\u00e7o especial em Madureira (n\u00e3o em Vicente de Carvalho) e de l\u00e1 pegar o expresso at\u00e9 o Gale\u00e3o.<\/li>\n<li style=\"text-align: justify;\"><em>Zona Oeste:<\/em> aqui tamb\u00e9m h\u00e1 duas op\u00e7\u00f5es. Nas localidades atendidas pelo BRT Transoeste, a alternativa \u00e9 descer na Alvorada e pegar o BRT Semi-Expresso sentido Gale\u00e3o. Descer na Esta\u00e7\u00e3o Rio 2. Para as localidades atendidas pelo trem, a alternativa \u00e9 descer em Magalh\u00e3es Bastos e pegar o BRT Transol\u00edmpico direto at\u00e9 a esta\u00e7\u00e3o Morro do Outeiro.<\/li>\n<li style=\"text-align: justify;\"><em>Baixada Fluminense<\/em>: aqui\u00a0h\u00e1 tr\u00eas op\u00e7\u00f5es. Para quem vem de S\u00e3o Jo\u00e3o de Meriti, a alternativa \u00e9 pegar a Linha 2 do Metr\u00f4 na Pavuna (lembrando que esta linha ir\u00e1 fechar \u00e0 meia noite), descer em Vicente de Carvalho e utilizar o servi\u00e7o especial do BRT at\u00e9 o Terminal Centro Ol\u00edmpico ou a esta\u00e7\u00e3o Riocentro. Para as localidades atendidas pelo trem, descer em Madureira e utilizar o mesmo servi\u00e7o especial do BRT. Para quem vem da Dutra ou da Washington Luiz, venha de \u00f4nibus, des\u00e7a no Fund\u00e3o e siga o itiner\u00e1rio dos moradores da Ilha do Governador.<\/li>\n<li style=\"text-align: justify;\"><em>Niter\u00f3i<\/em>: barca, ande at\u00e9 a esta\u00e7\u00e3o Carioca do Metr\u00f4 e siga o itiner\u00e1rio de quem vai do Centro\/Zona Sul.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/03\/rio2016_marco_ArenaDeodoro_Deodoro_012_0605_-c-2016_AndreMotta_HeusiAction.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40768\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/03\/rio2016_marco_ArenaDeodoro_Deodoro_012_0605_-c-2016_AndreMotta_HeusiAction-510x340.jpg\" alt=\"Arena Deodoro\" width=\"510\" height=\"340\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/03\/rio2016_marco_ArenaDeodoro_Deodoro_012_0605_-c-2016_AndreMotta_HeusiAction-510x340.jpg 510w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/03\/rio2016_marco_ArenaDeodoro_Deodoro_012_0605_-c-2016_AndreMotta_HeusiAction-300x200.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/03\/rio2016_marco_ArenaDeodoro_Deodoro_012_0605_-c-2016_AndreMotta_HeusiAction-768x512.jpg 768w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/a>2 &#8211; Deodoro<\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><em>Do Centro\/Zona Sul\/Tijuca:<\/em> Metr\u00f4 Linha 1, transbordo na esta\u00e7\u00e3o Central, trem, descida nas esta\u00e7\u00f5es Vila Militar, Magalh\u00e3es Bastos ou Ricardo de Albuquerque, dependendo da esta\u00e7\u00e3o. As duas primeiras esta\u00e7\u00f5es s\u00e3o do ramal Santa Cruz dos trens, enquanto que a terceira pertence ao ramal Japeri.<\/li>\n<li style=\"text-align: justify;\"><em>Zona Norte (Sub\u00farbios da Central):\u00a0<\/em>trem, descer nas esta\u00e7\u00f5es recomendadas acima;<\/li>\n<li style=\"text-align: justify;\"><em>Zona Norte (Sub\u00farbios da Leopoldina):\u00a0<\/em>BRT Transcarioca, descer em Madureira, trem, descer nas esta\u00e7\u00f5es recomendadas;<\/li>\n<li style=\"text-align: justify;\"><em>Ilha do Governador\/Aeroporto do Gale\u00e3o:<\/em> BRT no Gale\u00e3o ou no Fund\u00e3o (expresso), descer em Madureira, trem, descer nas esta\u00e7\u00f5es recomendadas;<\/li>\n<li style=\"text-align: justify;\"><em>Zona Oeste:<\/em>\u00a0trem, descer nas esta\u00e7\u00f5es recomendadas acima. Vale lembrar que caso a esta\u00e7\u00e3o seja Ricardo de Albuquerque, des\u00e7a em Magalh\u00e3es Bastos e utilize o servi\u00e7o de \u00f4nibus especial que est\u00e1 previsto.<\/li>\n<li style=\"text-align: justify;\"><em>Baixada Fluminense<\/em>: trem, descer nas esta\u00e7\u00f5es recomendadas acima. Caso as esta\u00e7\u00f5es sejam Magalh\u00e3es Bastos ou Vila Militar, h\u00e1 a necessidade de troca dos ramais na esta\u00e7\u00e3o de Deodoro.<\/li>\n<li style=\"text-align: justify;\"><em>Niter\u00f3i<\/em>: barca, ande at\u00e9 a esta\u00e7\u00e3o Carioca do Metr\u00f4 e siga o itiner\u00e1rio de quem vai do Centro\/Zona Sul;<\/li>\n<li style=\"text-align: justify;\"><em>Barra da Tijuca<\/em>: BRT (Alvorada ou Jardim Oce\u00e2nico), descer na esta\u00e7\u00e3o Morro do Outeiro\u00a0e pegar o BRT especial Transol\u00edmpico at\u00e9 Magalh\u00e3es Bastos.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/07\/20150719_134315.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-36379\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/07\/20150719_134315-550x309.jpg\" alt=\"20150719_134315\" width=\"550\" height=\"309\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/07\/20150719_134315-550x309.jpg 550w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/07\/20150719_134315-300x169.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a>3 &#8211; Maracan\u00e3\/Maracan\u00e3zinho<\/strong><\/p>\n<p style=\"text-align: justify;\">Para esta \u00e1rea um lembrete se faz necess\u00e1rio: <strong><span style=\"color: #800080;\">\u00e0 exce\u00e7\u00e3o dos dias 5 e 21<\/span><\/strong>, dias de cerim\u00f4nias e onde tanto o Metr\u00f4 Linha 2 como os trens ir\u00e3o funcionar at\u00e9 as duas da manh\u00e3, nos dias de v\u00f4lei as op\u00e7\u00f5es para quem ir\u00e1 assistir os jogos do Brasil (\u00faltima sess\u00e3o) que incluem estes modais <strong><span style=\"color: #800080;\">N\u00c3O<\/span><\/strong> poder\u00e3o ser utilizadas.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><em>Do Centro\/Zona Sul:\u00a0<\/em>Metr\u00f4 Linha 1, transbordo em Botafogo, Metr\u00f4 Linha 2, descida nas esta\u00e7\u00f5es S\u00e3o Crist\u00f3v\u00e3o ou Maracan\u00e3. Ou pegar a Linha 1 e descer nas esta\u00e7\u00f5es S\u00e3o Francisco Xavier ou Saens Pe\u00f1a &#8211; a dist\u00e2ncia \u00e9 praticamente a mesma e esta op\u00e7\u00e3o poder\u00e1 ser utilizada \u00e0 noite, embora seja bem mais longe do Maracan\u00e3zinho\u00a0que as esta\u00e7\u00f5es da Linha 2.<\/li>\n<li style=\"text-align: justify;\"><em>Zona Norte (Sub\u00farbios da Central), Zona Oeste, Baixada Fluminense:\u00a0<\/em>trem, descer nas esta\u00e7\u00f5es Maracan\u00e3 ou S\u00e3o Crist\u00f3v\u00e3o. No retorno noturno, a \u00fanica op\u00e7\u00e3o ser\u00e1 os \u00f4nibus &#8211; esperamos que haja refor\u00e7o no n\u00famero de carros. E lembrando que os moradores da Zona Oeste ou da Baixada ainda precisar\u00e3o trocar de coletivo na Leopoldina ou na Cidade Nova, que n\u00e3o s\u00e3o exatamente o lugar mais seguro do mundo na madrugada&#8230;<\/li>\n<li style=\"text-align: justify;\"><em>Zona Norte (Sub\u00farbios da Leopoldina):\u00a0<\/em>trem (ramal Saracuruna), descer na esta\u00e7\u00e3o S\u00e3o Crist\u00f3v\u00e3o. Nas sess\u00f5es noturnas do v\u00f4lei, a op\u00e7\u00e3o ser\u00e1 os \u00f4nibus igualmente.<\/li>\n<li style=\"text-align: justify;\"><em>Ilha do Governador\/Aeroporto do Gale\u00e3o:<\/em> BRT no Gale\u00e3o ou no Fund\u00e3o (expresso), descer em Madureira, trem, descer nas esta\u00e7\u00f5es recomendadas (Maracan\u00e3 ou S\u00e3o Crist\u00f3v\u00e3o). No retorno noturno, a op\u00e7\u00e3o seria pegar um \u00f4nibus, descer na Leopoldina ou na Cidade Nova e pegar outro coletivo. Mas com a limitad\u00edssima oferta de linhas para a regi\u00e3o, especialmente de madrugada, a sugest\u00e3o \u00e9 sair da \u00e1rea de bloqueio de tr\u00e2nsito e optar por um t\u00e1xi ou Uber. \u00c0queles que n\u00e3o forem a jogos do Brasil ou outros noturnos a sugest\u00e3o \u00e9 deixar o carro no shopping Nova Am\u00e9rica e pegar o Metr\u00f4 Linha 2 na esta\u00e7\u00e3o de mesmo nome.<\/li>\n<li style=\"text-align: justify;\"><em>Niter\u00f3i<\/em>: barca, ande at\u00e9 a esta\u00e7\u00e3o Carioca do Metr\u00f4 e siga o itiner\u00e1rio de quem vai do Centro\/Zona Sul. No retorno noturno, a op\u00e7\u00e3o \u00e9 pegar um \u00f4nibus na Leopoldina, porque o servi\u00e7o de barcas tamb\u00e9m fecha cedo;<\/li>\n<li style=\"text-align: justify;\"><em>Barra da Tijuca\/Recreio<\/em>: BRT (servi\u00e7os especiais, Transoeste ou Transcarioca, dependendo de onde se estiver). Se o leitor estiver mais pr\u00f3ximo do Jardim Oce\u00e2nico, pegue o Metr\u00f4 linha 4 e siga o itiner\u00e1rio de quem ir\u00e1 da Zona Sul (inclusive no retorno noturno). Se estiver mais pelos lados do Parque Ol\u00edmpico, pegue o BRT servi\u00e7o especial na esta\u00e7\u00e3o Centro Ol\u00edmpico, des\u00e7a em Madureira e v\u00e1 de trem.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160514_162704.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-42070\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160514_162704-550x309.jpg\" alt=\"20160514_162704\" width=\"550\" height=\"309\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160514_162704-550x309.jpg 550w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160514_162704-300x169.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160514_162704-768x432.jpg 768w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a>4 &#8211; Engenh\u00e3o<\/strong><\/p>\n<p style=\"text-align: justify;\">Curiosamente, o itiner\u00e1rio \u00e9 o mesmo que as op\u00e7\u00f5es para Deodoro. A diferen\u00e7a \u00e9 que a esta\u00e7\u00e3o a descer \u00e9 a do Engenho de Dentro &#8211; e n\u00e3o h\u00e1 necessidade de troca do trem pois todos os ramais atendem a esta esta\u00e7\u00e3o. A exce\u00e7\u00e3o \u00e9 para quem vem da Barra da Tijuca, que dever\u00e1 pegar o BRT Transcarioca expresso at\u00e9 Madureira e l\u00e1 tomar\u00a0o trem sentido Central do Brasil at\u00e9 o Engenho de Dentro.<\/p>\n<p style=\"text-align: justify;\">Ressaltando que o Engenh\u00e3o \u00e9 mais distante para quem vem da Zona Oeste e da Baixada Fluminense e mais perto para quem vem do Centro\/Zona Sul\/Tijuca.<\/p>\n<p style=\"text-align: justify;\"><strong>5 &#8211; Arena do V\u00f4lei de Praia<\/strong><\/p>\n<p style=\"text-align: justify;\">Aqui um outro lembrete se faz necess\u00e1rio: o Metr\u00f4 deixa bem distante, a mais de 1 quil\u00f4metro. E nas sess\u00f5es noturnas, haver\u00e1 o mesmo problema da inexist\u00eancia de trens e do Metr\u00f4 Linha 2 &#8211; e a regi\u00e3o onde fica a arena precisar\u00e1 de um grande refor\u00e7o de seguran\u00e7a neste hor\u00e1rio.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><em>Do Centro\/Zona Sul\/Tijuca:\u00a0<\/em>Metr\u00f4 Linha 1, descer na esta\u00e7\u00e3o Cardeal Arcoverde.<\/li>\n<li style=\"text-align: justify;\"><em>Zona Norte (Central\/Leopoldina), Zona Oeste, Baixada<\/em>: Trem, descer na Central,\u00a0Metr\u00f4 Linha 1, descer na esta\u00e7\u00e3o Cardeal Arcoverde. No retorno noturno, descer do Metr\u00f4 no Centro ou na Tijuca e tomar um \u00f4nibus;<\/li>\n<li style=\"text-align: justify;\"><em>Ilha do Governador\/Aeroporto do Gale\u00e3o:<\/em> BRT no Gale\u00e3o ou no Fund\u00e3o (expresso), descer em Madureira, trem,\u00a0descer na Central,\u00a0Metr\u00f4 Linha 1, descer na esta\u00e7\u00e3o Cardeal Arcoverde.\u00a0\u00c0queles que n\u00e3o forem a jogos com encerramento previsto para depois das 11 da noite a sugest\u00e3o \u00e9 deixar o carro no shopping Nova Am\u00e9rica e pegar o Metr\u00f4 Linha 2 na esta\u00e7\u00e3o de mesmo nome, trocando para a Linha 1 na esta\u00e7\u00e3o de Botafogo.<\/li>\n<li style=\"text-align: justify;\"><em>Niter\u00f3i<\/em>: barca, ande at\u00e9 a esta\u00e7\u00e3o Carioca do Metr\u00f4 e siga o itiner\u00e1rio de quem vai do Centro\/Zona Sul.<\/li>\n<li style=\"text-align: justify;\"><em>Barra da Tijuca\/Recreio<\/em>: BRT at\u00e9 o Jardim Oce\u00e2nico, Metr\u00f4 linha 4 e siga o itiner\u00e1rio de quem ir\u00e1 da Zona Sul, trocando de trem do metr\u00f4 na esta\u00e7\u00e3o General Os\u00f3rio.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160612_090643.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-42071\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160612_090643-550x309.jpg\" alt=\"20160612_090643\" width=\"550\" height=\"309\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160612_090643-550x309.jpg 550w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160612_090643-300x169.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/06\/20160612_090643-768x432.jpg 768w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a>6 &#8211; Entre Arenas<\/strong><\/p>\n<p style=\"text-align: justify;\">Aqui algumas sugest\u00f5es de itiner\u00e1rio entre arenas. Os tempos determinados n\u00e3o contam o processo de sa\u00edda e entrada de instala\u00e7\u00f5es, nem de espera por transporte. Para o itiner\u00e1rio inverso, basta trocar a ordem apresentada.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><em>Parque Ol\u00edmpico &#8211; Maracan\u00e3\/Maracan\u00e3zinho<\/em>: aqui h\u00e1 duas op\u00e7\u00f5es, mas acredito que pegar o servi\u00e7o especial do BRT na esta\u00e7\u00e3o Centro Ol\u00edmpico, descer em Madureira e pegar o trem ser\u00e1 mais r\u00e1pido. Uma hora e 30 de deslocamento, talvez.<\/li>\n<li style=\"text-align: justify;\"><em>Parque Ol\u00edmpico &#8211; Deodoro<\/em>: pegar o BRT Transol\u00edmpica na esta\u00e7\u00e3o Morro do Outeiro e descer em Magalh\u00e3es Bastos. Cerca de 40 minutos;<\/li>\n<li style=\"text-align: justify;\"><em>Parque Ol\u00edmpico &#8211; Engenh\u00e3o:<\/em>\u00a0servi\u00e7o especial do BRT na esta\u00e7\u00e3o Centro Ol\u00edmpico, descer em Madureira e pegar o trem. Aproximadamente\u00a050 minutos;<\/li>\n<li style=\"text-align: justify;\"><em>Engenh\u00e3o &#8211; Maracan\u00e3zinho\/Maracan\u00e3<\/em>: trem no Engenho de Dentro, descer em Maracan\u00e3 ou S\u00e3o Crist\u00f3v\u00e3o. 20 minutos.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Claro que o objetivo aqui n\u00e3o foi esgotar as op\u00e7\u00f5es. O Moovit, aplicativo de celular que ser\u00e1 o oficial de rotas de transporte coletivo para a Rio 2016, dever\u00e1 ajudar bastante.<\/p>\n<p style=\"text-align: justify;\">Entretanto, ainda que o argumento seja de que a esmagadora maioria dos detentores de ingressos para o v\u00f4lei seja da Zona Sul e da Barra, espero que reconsiderem ao menos a decis\u00e3o de encerrar o servi\u00e7o de trens antes do t\u00e9rmino das sess\u00f5es noturnas, porque deixar extensas \u00e1reas da cidade e da Regi\u00e3o Metropolitana dependendo do servi\u00e7o de \u00f4nibus me parece bem temer\u00e1rio, para se dizer o menos. O caso da Linha 2 do Metr\u00f4, segundo consta, \u00e9 definitiva a decis\u00e3o &#8211; inclusive no dia da final do v\u00f4lei feminino.<\/p>\n<p style=\"text-align: justify;\">D\u00favidas? Utilize a \u00e1rea de coment\u00e1rios.<\/p>\n<p style=\"text-align: justify;\"><em>Atualiza\u00e7\u00e3o: este blog acabou voltando ao assunto em artigo de 1\u00ba de agosto:\u00a0<span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2016\/08\/rio-2016-ingressos-mobilidade-outras-coisas\/\" target=\"_blank\">http:\/\/www.pedromigao.com.br\/ourodetolo\/2016\/08\/rio-2016-ingressos-mobilidade-outras-coisas\/<\/a><\/span> <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Comentem l\u00e1, por gentileza &#8211; a \u00e1rea de coment\u00e1rios deste foi fechada.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Imagens: Arquivo Ouro de Tolo<\/strong><\/p>\n<p style=\"text-align: justify;\">[related_posts limit=&#8221;3&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ontem, na primeira parte do artigo com dicas de mobilidade urbana para a Rio 2016, mostramos um resumo dos bloqueios de tr\u00e2nsito e altera\u00e7\u00f5es vi\u00e1riasTour Details<\/p>\n","protected":false},"author":2,"featured_media":42073,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[41,665,94,70,105],"class_list":["post-42066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pedro-migao","tag-esporte","tag-jogos-olimpicos-2016","tag-rio-2016","tag-rio-de-janeiro","tag-transito"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/42066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=42066"}],"version-history":[{"count":0,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/42066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media\/42073"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=42066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=42066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=42066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}