{"id":37217,"date":"2015-09-17T13:24:27","date_gmt":"2015-09-17T16:24:27","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=37217"},"modified":"2015-09-17T13:24:28","modified_gmt":"2015-09-17T16:24:28","slug":"esta-e-uma-otima-hora-para-comecar-a-acompanhar-a-mlb","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2015\/09\/esta-e-uma-otima-hora-para-comecar-a-acompanhar-a-mlb\/","title":{"rendered":"Esta \u00e9 uma \u00f3tima hora para come\u00e7ar a acompanhar a MLB"},"content":{"rendered":"<p style=\"text-align: justify;\">Por que essa \u00e9 uma \u00f3tima hora para come\u00e7ar a acompanhar a MLB?<\/p>\n<p style=\"text-align: justify;\">Bem, qualquer hora \u00e9 uma \u00f3tima hora, mas eu posso estar sendo um pouco parcial ao dizer isso pois defendo que o beisebol \u00e9 o melhor esporte que h\u00e1. Entretanto a MLB atualmente passa por um processo de transi\u00e7\u00e3o entre as j\u00e1 envelhecidas estrelas e as jovens e futuras promessas de estrelas que valem a pena acompanhar. Estas novas estrelas jogar\u00e3o pelos pr\u00f3ximos quinze a vinte anos e \u00e9 um privil\u00e9gio ter a oportunidade de acompanhar carreiras t\u00e3o promissoras desde o princ\u00edpio.<\/p>\n<p style=\"text-align: justify;\">Para se ter uma ideia, muitos escritores renomados dizem que este \u00e9 o \u201cano do novato\u201d, mas isso n\u00e3o diz tudo, pois algumas destas jovens estrelas j\u00e1 s\u00e3o considerados bem veteranos \u2013 Mike Trout que o diga. Essa express\u00e3o existe pelo fato de que h\u00e1 diversas jovens promessas j\u00e1 jogando por seus respectivos clubes e que est\u00e3o causando um grande impacto. Sejam eles jogadores de linha ou arremessadores, estes novatos s\u00e3o grandes respons\u00e1veis por seus times estarem brigando por vagas nos playoffs.<\/p>\n<figure id=\"attachment_37234\" aria-describedby=\"caption-attachment-37234\" style=\"width: 511px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2015\/09\/esta-e-uma-otima-hora-para-comecar-a-acompanhar-a-mlb\/chicago-cubs-photo-day\/\" rel=\"attachment wp-att-37234\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-37234\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/09\/032515_kris_bryant_tr-511x340.jpg\" alt=\"MESA, AZ - MARCH 2:  Kris Bryant #76 of the Chicago Cubs poses for a portrait during Photo Day on March 2, 2015 at Sloan Park in Mesa, Arizona.  (Photo by Rich Pilling\/Getty Images)\" width=\"511\" height=\"340\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/09\/032515_kris_bryant_tr-511x340.jpg 511w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/09\/032515_kris_bryant_tr-300x200.jpg 300w\" sizes=\"auto, (max-width: 511px) 100vw, 511px\" \/><\/a><figcaption id=\"caption-attachment-37234\" class=\"wp-caption-text\">MESA, AZ &#8211; MARCH 2: Kris Bryant #76 of the Chicago Cubs poses for a portrait during Photo Day on March 2, 2015 at Sloan Park in Mesa, Arizona. (Photo by Rich Pilling\/Getty Images)<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">O Chicago Cubs, que n\u00e3o ganha nada h\u00e1 mais de cem \u2013 sim, voc\u00ea leu corretamente \u2013 anos. O Houston Astros ficava entre os piores times da liga h\u00e1 v\u00e1rias temporadas seguidas. O Minnesota Twins que v\u00ea uma luz no fim do t\u00fanel depois de v\u00e1rias temporadas de irrelev\u00e2ncia. O New York Mets, o Toronto Blue Jays, o Washington Nationals e outros tiveram importante contribui\u00e7\u00e3o dos seus novatos para fazerem as \u00f3timas campanhas que est\u00e3o tendo.<\/p>\n<p style=\"text-align: justify;\">Come\u00e7ando pelo mais antigo na fila de t\u00edtulos, os Cubs podem ser os que mais dependeram de seus novatos para chegar onde chegaram. Com a sexta melhor campanha dentro toda a liga, eles garantiram a primeira temporada com mais vit\u00f3rias que derrotas desde nem lembro quando&#8230; Dentre os principais, o terceira-base Kris Bryant e o segunda-base\/shortstop Addison Russell foram os maiores respons\u00e1veis pelo sucesso do time. E como esquecer do catcher\/campo-externo Kyle Schwarber?<\/p>\n<p style=\"text-align: justify;\">Todos estes come\u00e7aram o ano nas categorias de base, mas cedo j\u00e1 estavam causando impacto e aquela \u201cboa dor de cabe\u00e7a\u201d ao t\u00e9cnico Joe Maddon, considerado um dos melhores da liga. Maddon logo teve que arrumar espa\u00e7o para acomodar todos no alinhamento e impor medo aos advers\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">O Minnesota Twins v\u00ea seu futuro, a longo prazo e imediato, nas m\u00e3os de Miguel Sano e Byron Buxton. Chamados ao time principal durante esta temporada, eles foram aquela fagulha que o time precisava para engrenar e brigar por playoffs. O primeiro, jogador de terceira-base, tem um enorme potencial de for\u00e7a no bast\u00e3o e promete ser daqueles jogadores que rebatem bolas para a galera; a cada apari\u00e7\u00e3o dele \u00e9 de se esperar uma bola rebatida a 500 p\u00e9s do home plate. J\u00e1 o segundo, jogador de campo-externo, tem na velocidade sua maior arma. A velocidade o faz ser um defensor acima da media, requerido para a posi\u00e7\u00e3o, e o torna uma amea\u00e7a ao chegar em base.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2015\/09\/esta-e-uma-otima-hora-para-comecar-a-acompanhar-a-mlb\/28bd5b7309f2379ac149ff9a3ed47c6c_crop_north\/\" rel=\"attachment wp-att-37235\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-37235\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/09\/28bd5b7309f2379ac149ff9a3ed47c6c_crop_north-510x340.png\" alt=\"28bd5b7309f2379ac149ff9a3ed47c6c_crop_north\" width=\"510\" height=\"340\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/09\/28bd5b7309f2379ac149ff9a3ed47c6c_crop_north-510x340.png 510w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/09\/28bd5b7309f2379ac149ff9a3ed47c6c_crop_north-300x200.png 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/09\/28bd5b7309f2379ac149ff9a3ed47c6c_crop_north.png 630w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/a>O Houston Astros conta com o shortstop dominicano Carlos Correa. Correa, um ex-primeira escolha de draft, j\u00e1 chegou mostrando que \u00e9 o melhor shortstop da Liga Americana e na briga para ser o melhor de toda a MLB. \u00d3timas ferramentas no bast\u00e3o, consegue chegar em base t\u00e3o bem quanto conseguir rebatidas de for\u00e7a \u2013 duplas, home runs \u2013 e combina isso com \u00f3tima desenvoltura ao lidar com os trabalhos defensivos na posi\u00e7\u00e3o mais importante do campo interno.<\/p>\n<p style=\"text-align: justify;\">O Cleveland Indians do brasileiro Yan Gomes tamb\u00e9m tem sua jovem promessa. Francisco Lindor \u00e9 considerado h\u00e1 algum tempo j\u00e1 o melhor shortstop defensivo das categorias de base dentre todos os times, mas sua habilidade no bast\u00e3o n\u00e3o era boa o suficiente para o n\u00edvel mais alto de beisebol do mundo. Ele n\u00e3o deve rebater 30 home runs por temporada, ele n\u00e3o deve liderar a liga em rebatidas, mas ele deve fazer tudo com consist\u00eancia o suficiente para ser um dos melhores por bastante tempo.<\/p>\n<p style=\"text-align: justify;\">E que tal os Mets? Numa temporada surpreendente e ancorada por um grande corpo de arremessadores, eles tamb\u00e9m t\u00eam sua parcela de novatos. Noah Syndergaard, mais conhecido como \u201cO Thor\u201d pela sua semelhan\u00e7a com o ator do filme, vem destru\u00edndo os rebatedores que enfrenta. Steven Matz, tamb\u00e9m arremessador novato, tamb\u00e9m vem tendo destaque. Apesar de ter passado a maior parte da temporada na lista dos contundidos, ele ganhou tr\u00eas\u00a0 dos quatro jogos em que jogou.<\/p>\n<p style=\"text-align: justify;\">Quando se fala do Los Angeles Dodgers todos j\u00e1 imaginam sua gigantesca folha salarial de, aproximadamente, 300 milh\u00f5es de d\u00f3lares \u2013 sim, isso mesmo, mas na MLB pode por n\u00e3o ter um teto salarial \u2013, mas eles tamb\u00e9m contaram com novatos para estar onde est\u00e3o. Joc Pederson e, mais recentemente, Corey Seager s\u00e3o os nomes da vez pelos lados de Los Angeles. O primeiro chegou bastante badalado \u2013 <em>quem n\u00e3o chega? Afinal de contas \u00e9 LA!<\/em> \u2013 e fez valer tanta expectativa ao rebater home runs monstruosos e \u00f3timas jogadas defensivas, mas diminuiu de produtividade ultimamente. J\u00e1 Seager, desde que chegou, vem rebatendo absurdos 43,2% no bast\u00e3o. Insustent\u00e1vel, mas ele est\u00e1 mostrando a que veio.<\/p>\n<p style=\"text-align: justify;\">Como falar de jovens estrelas sem falar de Mike Trout e Bryce Harper. O primeiro j\u00e1 teve n\u00e3o uma, n\u00e3o duas, mas TR\u00caS temporadas dignas de ganhar a premia\u00e7\u00e3o de melhor jogador do ano e ele tem apenas 24 anos. J\u00e1 Bryce Harper \u00e9 badalado desde quando tinha 16 anos de idade, mas n\u00e3o alcan\u00e7ou as expectativas nos \u00faltimos dois anos, algo que n\u00e3o aconteceu nesta temporada. Com 39 home runs e liderando a Liga Nacional em aproveitamento no bast\u00e3o \u2013 at\u00e9 esta ter\u00e7a-feira(15) \u2013 ele est\u00e1 mostrando que \u00e9 isso tudo sim que os olheiros sempre falaram dele e ele tem 22 anos.<\/p>\n<p style=\"text-align: justify;\">Joey Gallo, Eduardo Rodriguez, Carlos Rodon, Joe Ross, Michael A. Taylor, Greg Bird, Maikel Franco&#8230; Eu poderia fazer um par\u00e1grafo para cada um destes jogadores, mas o texto ficaria muito extenso, cansativo e repetitivo; mas isso n\u00e3o quer dizer que eles n\u00e3o merecessem pelo menos um par\u00e1grafo cada. Fica aqui a dica para acompanha-los no dia a dia da liga: eles prometem ser muito bons.<\/p>\n<p style=\"text-align: justify;\">At\u00e9 mais!<\/p>\n<p style=\"text-align: justify;\"><strong>Imagens: Getty Imagens, AP, Bleacher Report<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por que essa \u00e9 uma \u00f3tima hora para come\u00e7ar a acompanhar a MLB? Bem, qualquer hora \u00e9 uma \u00f3tima hora, mas eu posso estar sendoTour Details<\/p>\n","protected":false},"author":44,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[954],"tags":[400,41,590,44],"class_list":["post-37217","post","type-post","status-publish","format-standard","hentry","category-major-leagues","tag-baseball","tag-esporte","tag-esportes-americanos","tag-eua"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/37217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=37217"}],"version-history":[{"count":0,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/37217\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=37217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=37217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=37217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}