{"id":16942,"date":"2013-03-18T07:10:24","date_gmt":"2013-03-18T10:10:24","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=16942"},"modified":"2013-03-14T07:13:47","modified_gmt":"2013-03-14T10:13:47","slug":"os-nerds-na-vida-real-redes-sociais-parte-i","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2013\/03\/os-nerds-na-vida-real-redes-sociais-parte-i\/","title":{"rendered":"Os Nerds na Vida Real: &#8220;Redes Sociais &#8211; Parte I&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/03\/twitter-logo-hashtag.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-16943\" alt=\"twitter-logo-hashtag\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/03\/twitter-logo-hashtag-453x340.jpg\" width=\"453\" height=\"340\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/03\/twitter-logo-hashtag-453x340.jpg 453w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/03\/twitter-logo-hashtag-300x225.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/03\/twitter-logo-hashtag.jpg 756w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><\/a><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Hoje a<strong> coluna \u201cOs Nerds na Vida Real\u201d, do analista de sistemas e webmaster deste blog Rodrigo Felga<\/strong>, come\u00e7a a falar de um assunto muito familiar aos leitores: as redes sociais.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Pessoalmente, praticamente s\u00f3 utilizo o Twitter. At\u00e9 tenho Facebook mas muito pouco o vejo \u2013 agora, com esta hist\u00f3ria de estar envolvido com a pol\u00edtica portelense, tenho usado um pouquinho mais.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Vamos ao texto.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"text-decoration: underline;\"><em><strong><span style=\"color: #000080; text-decoration: underline;\">Redes Sociais &#8211; Parte I<\/span><\/strong><\/em><\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Ol\u00e1 amigos! A coluna desse m\u00eas falar\u00e1 um pouco sobre Redes Sociais. Veremos que essas redes podem ser utilizadas tanto para o bem quanto para o mal &#8211; e a influ\u00eancia que isso tem em nossas vidas.<!--more--><\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Quando se fala de rede social nos dias de hoje, acredito que para a maioria dos leitores o que vem \u00e0 mente s\u00e3o Twitter e Facebook. Essas s\u00e3o, na minha vis\u00e3o, as principais redes sociais atualmente e possuem um grande n\u00famero de usu\u00e1rios brasileiros. O praticamente finado Orkut era a principal rede social no Brasil mas aos poucos foi perdendo espa\u00e7o e foi completamente dominado pelo Facebook &#8211; principalmente por conta da alta polui\u00e7\u00e3o audiovisual e por quest\u00f5es de privacidade.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">\u00c9 interessante notar a (falta de) voca\u00e7\u00e3o da gigante Google com redes sociais. A \u00faltima rede social lan\u00e7ada pelo Google, a Google Plus, parece n\u00e3o cair no gosto popular &#8211; assim como os seus antecessores. A \u00fanica rede social da gigante de Montain View que fez relativo sucesso foi o Orkut, que acabou perdendo espa\u00e7o por quest\u00f5es de privacidade, outro &#8220;ponto fraco&#8221; da empresa.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">As redes sociais podem ser utilizadas para diversos fins e depende do usu\u00e1rio fazer o bom uso dela ou n\u00e3o. Eu uso o Twitter principalmente para acompanhar not\u00edcias e temas de meu interesse, principalmente esportes, e vejo como grande vantagem dessa rede a sua agilidade, permitindo ter not\u00edcias em primeira m\u00e3o e alguns &#8220;furos&#8221; de reportagem.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Acredito no Twitter como uma grande ferramenta para aproximar pessoas p\u00fablicas de seus f\u00e3s e vejo este como o grande diferencial da ferramenta: podemos estar sempre diretamente conectados aos assuntos de nosso interesse.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">J\u00e1 o Facebook vejo como uma boa ferramenta para relacionamento interpessoal e networking profissional (para uma rede exclusivamente profissional, o ideal \u00e9 o LinkedIn). Vejo a ferramenta como uma boa pedida para manter contato com aquele amigo que agora est\u00e1 distante, morando em outro pa\u00eds, ou mesmo aquele amigo que mora ao lado mas que voc\u00ea quase n\u00e3o v\u00ea pois ele trabalha o dia todo.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Uma coisa que vale tanto para o Facebook quanto para o Twitter (e para todas as redes sociais) \u00e9 o bom senso.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Em ambas as redes sociais existem pessoas que fazem seguidas postagens sem conte\u00fado algum e acabam inundando a nossa \u2018timeline\u2019 com coisas banais ou que n\u00e3o nos interessem. Eu n\u00e3o quero saber a que horas voc\u00ea vai ao banheiro, eu n\u00e3o quero ver fotos de gente despeda\u00e7ada na minha timeline, eu simplesmente n\u00e3o me interesso por essas informa\u00e7\u00f5es.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">\u00c9 claro que nem sempre as pessoas que seguimos v\u00e3o ter informa\u00e7\u00f5es relevantes para a gente, mas se uma pessoa s\u00f3 te inunda com coisas in\u00fateis a \u00fanica sa\u00edda \u00e9 o unfollow ou o block.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Outra quest\u00e3o importante sobre as redes sociais \u00e9 quest\u00e3o da seguran\u00e7a: existem pessoas que postam em tempo real sua localiza\u00e7\u00e3o, o dia todo. Essas informa\u00e7\u00f5es s\u00e3o um prato cheio para bandidos que podem estar planejando invadir a sua casa, por exemplo.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Eles ficar\u00e3o extremamente felizes em saber que voc\u00ea vai passar uma semana de f\u00e9rias em Macei\u00f3 e que sua casa estar\u00e1 sozinha durante todo esse per\u00edodo. Portanto, muito cuidado com as informa\u00e7\u00f5es que posta nas redes sociais: pode ser que a pessoa que esteja vendo n\u00e3o seja s\u00f3 seu amigo.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Ainda sobre seguran\u00e7a, deve ser dada uma aten\u00e7\u00e3o especial \u00e0 utiliza\u00e7\u00e3o das mesmas por crian\u00e7as e adolescentes. Essas pessoas s\u00e3o muito vulner\u00e1veis e devem, sempre que poss\u00edvel, ser supervisionadas na utiliza\u00e7\u00e3o das ferramentas.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">Em minha opini\u00e3o crian\u00e7as nem deveriam utilizar tais recursos: crian\u00e7as devem se preocupar em brincar e n\u00e3o ficar 12 horas do dia sentadas na frente de um computador. J\u00e1 no caso dos adolescentes vale uma supervis\u00e3o para ver o tipo de conte\u00fado que andam postando e dar as devidas orienta\u00e7\u00f5es.<\/span><\/p>\n<p style=\"font-family: Verdana,Arial,Helvetica,sans-serif; text-align: justify;\"><span style=\"color: #000080;\">M\u00eas que vem continuarei falando sobre redes sociais, mais especificamente sobre sites de encontro e relacionamento extraconjugais. At\u00e9 l\u00e1!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje a coluna \u201cOs Nerds na Vida Real\u201d, do analista de sistemas e webmaster deste blog Rodrigo Felga, come\u00e7a a falar de um assunto muitoTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[32,6],"class_list":["post-16942","post","type-post","status-publish","format-standard","hentry","category-nerds","tag-tecnologia","tag-vida-cotidiana"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/16942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=16942"}],"version-history":[{"count":1,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/16942\/revisions"}],"predecessor-version":[{"id":16949,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/16942\/revisions\/16949"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=16942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=16942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=16942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}