{"id":16166,"date":"2013-01-23T07:43:04","date_gmt":"2013-01-23T09:43:04","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=16166"},"modified":"2013-01-23T07:43:05","modified_gmt":"2013-01-23T09:43:05","slug":"jogo-misto-lira-neto-o-biografo-de-getulio-vargas","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2013\/01\/jogo-misto-lira-neto-o-biografo-de-getulio-vargas\/","title":{"rendered":"Jogo Misto &#8211; Lira Neto, o bi\u00f3grafo de Get\u00falio Vargas"},"content":{"rendered":"<p style=\"text-align: center\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/01\/era-vargas-resumo-getulio-vargas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-16167\" alt=\"era-vargas-resumo-getulio-vargas\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/01\/era-vargas-resumo-getulio-vargas.jpg\" width=\"600\" height=\"431\" srcset=\"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/01\/era-vargas-resumo-getulio-vargas.jpg 857w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/01\/era-vargas-resumo-getulio-vargas-300x215.jpg 300w, https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/01\/era-vargas-resumo-getulio-vargas-473x340.jpg 473w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p style=\"text-align: center\">\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Ap\u00f3s longo interregno, a coluna de entrevistas deste blog est\u00e1 de volta. O blog, na figura do colunista Fabr\u00edcio Gomes, entrevistou Lira Neto, autor da rec\u00e9m lan\u00e7ada biografia (tomo 1) de Get\u00falio Vargas, <a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/06\/historia-outros-assuntos-a-biografia-historica-da-esfinge-que-transformou-o-brasil\/\" target=\"_blank\"><span style=\"color: #000080\">resenhada pelo colunista neste espa\u00e7o<\/span><\/a>.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Na entrevista &#8211; que contou com minha colabora\u00e7\u00e3o na elabora\u00e7\u00e3o das quest\u00f5es &#8211; Lira Neto fala sobre Get\u00falio, sobre a biografia &#8211; cujo segundo volume est\u00e1 em elabora\u00e7\u00e3o &#8211; e sobre Lula.<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Vamos a ela ent\u00e3o.<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><em><span style=\"color: #000080\">1) O sr. \u00e9 autor de algumas importantes biografias de personagens bastante conhecidos de nossa hist\u00f3ria: Castello Branco, Padre C\u00edcero, Rodolfo Te\u00f3filo, Jos\u00e9 de Alencar&#8230; O que o motivou, em sua vida, a escrever biografias?\u00a0<\/span><\/em><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">LN &#8211; Sou jornalista de forma\u00e7\u00e3o. Escrever biografias me possibilitou unir duas grandes paix\u00f5es pessoais: o jornalismo e a hist\u00f3ria. Al\u00e9m disso, o exerc\u00edcio do jornalismo di\u00e1rio, devido \u00e0s press\u00f5es naturais de tempo e de espa\u00e7o para desenvolver a apura\u00e7\u00e3o de um determinado fato ou assunto, sempre me deixava em um estado de inquieta\u00e7\u00e3o e de insatisfa\u00e7\u00e3o permanentes. <\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Os jornalistas t\u00eam cada vez menos tempo para apurar e menos espa\u00e7o f\u00edsico para escrever nas p\u00e1ginas dos jornais e das revistas. Ao migrar para o livro, posso me dar ao luxo de me dedicar a uma \u201cpauta\u201d por v\u00e1rios anos, e, em vez de uma breve not\u00edcia, escrever mais de 500 p\u00e1ginas a partir do material colhido durante a investiga\u00e7\u00e3o.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><em><span style=\"color: #000080\">2) Porqu\u00ea escrever uma biografia de Getulio Vargas?\u00a0<\/span><\/em><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">LN &#8211; Exatamente por aquilo que voc\u00ea bem salientou em sua resenha sobre o livro, publicada aqui no blog: apesar de ser o personagem mais importante da hist\u00f3ria brasileira, Get\u00falio ainda n\u00e3o fora alvo de uma biografia no sentido estrito do termo.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><em><span style=\"color: #000080\">3) Getulio Vargas foi uma das mais importantes personagens da vida p\u00fablica brasileira, e que participou de momentos decisivos da nossa hist\u00f3ria, como a Revolu\u00e7\u00e3o de 1930, o Estado Novo, sendo respons\u00e1vel por leis sociais fundamentais para a vida dos brasileiros, e que depois do per\u00edodo de reclus\u00e3o em S\u00e3o Borja, retornou \u00e0 vida pol\u00edtica elegendo-se presidente de forma avassaladora, deixando o legado do trabalhismo para Jo\u00e3o Goulart, considerado seu herdeiro pol\u00edtico. At\u00e9 na hora de sua morte, fez uma jogada de mestre, jogando seu cad\u00e1ver aos seus inimigos pol\u00edticos. Alguns historiadores afirmam que Getulio foi um verdadeiro &#8220;camale\u00e3o&#8221;, por suas distintas fases (revolucion\u00e1rio, ditador, democrata, trabalhista). O sr. concorda com isso? Existe uma s\u00f3 defini\u00e7\u00e3o para Getulio Vargas ou podemos afirmar que ele viveu fases distintas? <\/span><\/em><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><em><span style=\"color: #000080\">Pergunto isso porque numa biografia hist\u00f3rica ocorre sempre o perigo da ilus\u00e3o biogr\u00e1fica (termo criado por Pierre Bourdieu) &#8211; uma hist\u00f3ria de vida, regrada por acontecimentos cronol\u00f3gicos (in\u00edcio, meio e fim), a tentativa de se dar coer\u00eancia a uma vida, principalmente porque inevitavelmente j\u00e1 sabemos o que ir\u00e1 acontecer com a personagem que biografamos.\u00a0<\/span><\/em><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">LN &#8211; Get\u00falio sabia combinar um extraordin\u00e1rio senso de oportunidade \u00e0 uma elevada dose de paci\u00eancia hist\u00f3rica, caracter\u00edsticas que nos ajudam a explicar sua longevidade no poder. Ele conseguiu adaptar e ressignificar sua atua\u00e7\u00e3o p\u00fablica dentro do complexo quadro de transforma\u00e7\u00f5es pol\u00edticas, econ\u00f4micas e sociais que o pr\u00f3prio regime comandado por ele ajudou a implementar no pa\u00eds. Ele mesmo citava Darwin para dizer que vencer n\u00e3o significa derrotar o oponente, mas sim adaptar-se \u00e0s circunst\u00e2ncias e aos ambientes. <\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">N\u00e3o h\u00e1 d\u00favida de que todo bi\u00f3grafo corre o risco de cair na armadilha denunciada por Bordieu. Ou de fazer profecia do passado, isto \u00e9, de explicar um fen\u00f4meno a partir do que se sabe que ir\u00e1 acontecer posteriormente com o biografado. Procuro estar sempre atento a isso. Outro pecado comum \u00e9 o do anacronismo, quando bi\u00f3grafos procuram retratar e explicar determinado epis\u00f3dio com as lentes de hoje, sem levar em conta o contexto hist\u00f3rico da \u00e9poca retratada.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><em><span style=\"color: #000080\">4) \u00c9 comum, quando se analisa uma ditadura, as pessoas colocarem a culpa total no ditador. Portanto, para muitos, Getulio comandou com m\u00e3o de ferro o Estado Novo, o povo foi bastante oprimido, n\u00e3o existia democracia e a censura do DIP era constante. O sr. concorda com essa tese de um Getulio totalit\u00e1rio e onipresente? O Prof. Jorge Ferreira, da UFF, escreveu em 1997 um c\u00e9lebre livro (&#8220;Trabalhadores do Brasil: o imagin\u00e1rio popular &#8211; 1930-1945&#8221;), onde apresenta a participa\u00e7\u00e3o popular no Estado Novo, muitas pessoas de baixa renda enviando cartas para a Secretaria de Comunica\u00e7\u00e3o da Presid\u00eancia. Nessas cartas, trabalhadores comuns participavam ativamente, cobrando a\u00e7\u00f5es do presidente, pedindo coisas, elogiando&#8230; O que demonstra, de certo modo, uma ditadura legitimada. O que o Sr. pensa \u00e0 respeito disso?\u00a0<\/span><\/em><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">LN &#8211; N\u00e3o existe boa ou m\u00e1 ditatura. <\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">As ditaduras s\u00e3o, por defini\u00e7\u00e3o, perversas. O Estado Novo, nesse sentido, foi uma das mais tr\u00e1gicas experi\u00eancias da vida pol\u00edtica brasileira. A grande quest\u00e3o que se coloca \u00e9 justamente a de discutirmos se os ineg\u00e1veis avan\u00e7os da chamada Era Vargas nos planos social, econ\u00f4mico e pol\u00edtico n\u00e3o poderiam ter se dado em um ambiente efetivamente democr\u00e1tico. <\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">E nos cabe p\u00f4r em evid\u00eancia, tamb\u00e9m, os fatores hist\u00f3ricos que nos ajudam a compreender a op\u00e7\u00e3o getulista por governos fortes, autocr\u00e1ticos, centralizadores. Creio que o primeiro volume da biografia, que narra a g\u00eanese pol\u00edtica e os anos de forma\u00e7\u00e3o do biografado &#8212; herdeiro do positivismo e do borgismo-castilhismo ga\u00facho &#8211; lan\u00e7a algumas luzes nesse sentido.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><em><span style=\"color: #000080\">5) Qual foi (e tem sido, j\u00e1 que o Sr. continua a escrever a biografia) a maior dificuldade encontrada para escrever a biografia de Getulio Dornelles Vargas?\u00a0<\/span><\/em><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">LN &#8211; Meu of\u00edcio de jornalista me traz a preocupa\u00e7\u00e3o permanente com a recep\u00e7\u00e3o. Escrevo para um p\u00fablico heterog\u00eaneo. Tenho que provocar a reflex\u00e3o dos especialistas e, ao mesmo tempo, despertar o interesse dos leitores n\u00e3o familiarizados com o assunto. Acredito, sobretudo, no poder da informa\u00e7\u00e3o aliado ao prazer do texto.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\"><em>6) O Sr. \u00e9 um jornalista. Enfrentou alguma dificuldade (ou preconceito) no sentido de entrar numa seara onde existem alguns historiadores que n\u00e3o v\u00eaem com bons olhos jornalistas que escrevem esse tipo de livro? O que o Sr. pensa a respeito disso?<\/em>\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">LN &#8211; Creio que essa \u00e9 uma discuss\u00e3o datada, bizantina. \u00c9 verdade que ainda existem certos historiadores enclausurados nos pr\u00f3prios preconceitos e circunscritos ao mon\u00f3logo acad\u00eamico. <\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Contudo, cada vez mais, cresce no ambiente universit\u00e1rio e acad\u00eamico a percep\u00e7\u00e3o do g\u00eanero biogr\u00e1fico como algo relevante e essencial para o conhecimento hist\u00f3rico. Basta citar os nomes dos acad\u00eamicos e especialistas que, at\u00e9 aqui, escreveram resenhas positivas a respeito do livro: Boris Fausto, Maria Celina D\u2019Ara\u00fajo, Marly Motta etc. Do mesmo modo, existe muita contrafa\u00e7\u00e3o jornal\u00edstica publicada sob o r\u00f3tulo de biografia. H\u00e1 certas obras que estariam mais \u00e0 vontade nas prateleiras de romances hist\u00f3ricos.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><em><span style=\"color: #000080\">7) O Sr. considera o ex-presidente Lu\u00eds In\u00e1cio Lula da Silva um herdeiro do getulismo? Caso afirmativo, porqu\u00ea?\u00a0<\/span><\/em><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">LN &#8211; Lula era, originalmente, um antigetulista, pelo fato de n\u00e3o concordar com a tutela sindical imposta aos trabalhadores por Get\u00falio. Depois, ao chegar ao poder, passou a associar \u00e0 sua imagem pessoal certos matizes do getulismo. Como diria Darwin, vencer \u00e9 adaptar-se&#8230;\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\"><em>8) Como Getulio Vargas faria pol\u00edtica no Brasil de hoje, na era da internet e das redes sociais?<\/em><br \/>\n<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">LN &#8211; Get\u00falio \u2013 lastreado no famigerado DIP &#8211; sabia realmente utilizar todo o poder de comunica\u00e7\u00e3o oferecido pela tecnologia dispon\u00edvel \u00e0 \u00e9poca, especialmente o r\u00e1dio e o cinema. At\u00e9 para n\u00e3o cair em alguma esp\u00e9cie de anacronismo, n\u00e3o me aventuro a imaginar Get\u00falio no momento presente. S\u00e3o contextos diferentes e qualquer tentativa de tentar aproxim\u00e1-los seria apenas isso: uma aventura.<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Tentei ser objetivo, dada \u00e0 circunst\u00e2ncia de estar atarefado com o trabalho de reda\u00e7\u00e3o do segundo volume da biografia. Obrigad\u00edssimo pela generosa resenha.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s longo interregno, a coluna de entrevistas deste blog est\u00e1 de volta. O blog, na figura do colunista Fabr\u00edcio Gomes, entrevistou Lira Neto, autor daTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[35,106,80,24],"class_list":["post-16166","post","type-post","status-publish","format-standard","hentry","category-cacique-de-ramos","tag-historia","tag-jogo-misto","tag-lula","tag-politica"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/16166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=16166"}],"version-history":[{"count":0,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/16166\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=16166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=16166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=16166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}