{"id":12822,"date":"2012-10-01T17:04:00","date_gmt":"2012-10-01T19:04:00","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/10\/ninguem-e-triste-no-vento-leste\/"},"modified":"2012-10-01T17:04:00","modified_gmt":"2012-10-01T19:04:00","slug":"ninguem-e-triste-no-vento-leste","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/10\/ninguem-e-triste-no-vento-leste\/","title":{"rendered":"NINGU\u00c9M \u00c9 TRISTE NO VENTO LESTE"},"content":{"rendered":"<div align=\"justify\">Minha av\u00f3, quando veio de Pernambuco, recebeu de sua <span>Yalorix\u00e1<\/span> a permiss\u00e3o para abrir uma ro\u00e7a de\u00a0santo no Rio de Janeiro. Aqui chegando, comprou uns terrenos nos arredores de Rosa dos Ventos, um bairro de Nova <span>Igua\u00e7u<\/span>, onde plantou o <span>ax\u00e9<\/span> e criou sua casa de <span>Xamb\u00e1 &#8211; o candombl\u00e9 do Recife &#8211; e onde se cultuavam tamb\u00e9m\u00a0os encantados do Tambor de Mina<\/span>. <\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">Foi\u00a0l\u00e1 que eu, menino, convivi com algumas figuras extraordin\u00e1rias. Dentre elas havia um sujeito  humilde, que tomava cerveja e cacha\u00e7a\u00a0na <span>birosca<\/span>\u00a0da encruzilhada da Rua Castor, \u00e1rea conhecida como\u00a0Esquina do Pecado\u00a0(chamada deste jeito porque era um ponto de desova do esquadr\u00e3o que agia na Baixada Fluminense e assinava crimes em nome de certo\u00a0M\u00e3o Branca). <\/p>\n<p>Normalmente descal\u00e7o, o cabra\u00a0falava pouco e gostava de ver a molecada jogando bola na rua. De vez em quando assistia a <span>curimba<\/span>. N\u00e3o me lembro que desse intimidade a muita gente. Era fechado. Conversava com meu av\u00f4, o velho <span>Luiz<\/span> Grosso, <span>nordestino<\/span> que, como ele, era chegado numa cana firme.<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">Trazia um olhar <span>emba\u00e7ado<\/span>, profundamente triste e, para algumas crian\u00e7as, amea\u00e7ador. Se sorriu alguma vez, eu nunca vi. \u00a0Lembro-me\u00a0que uma velha amiga de minha av\u00f3, Maria do Carmo, parecia ser a \u00fanica por ali\u00a0a saber\u00a0que o sujeito era artista. Ela vivia dizendo isso :\u00a0&#8211; Ele \u00e9 compositor; tem at\u00e9 m\u00fasicas famosas.<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">Ningu\u00e9m acreditava, at\u00e9 porque essa Maria do Carmo tinha fama de ser doida varrida.<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">Meus av\u00f3s mantinham a casa em Nova Igua\u00e7u e\u00a0alugavam um apartamento modesto em Laranjeiras, <span>pertinho<\/span> do <span>Catete<\/span>, onde <span>pass\u00e1vamos<\/span> a semana.\u00a0\u00c0s sextas o\u00a0meu tio dirigia a <span>Kombi<\/span> da fam\u00edlia e todo mundo <span>ia<\/span> pra <span>macumba<\/span>.<\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">Foi em Laranjeiras que um amigo me chamou um dia &#8211; eu devia ter uns dezesseis anos &#8211; para ir a uma casa de m\u00fasica que tinha aberto na rua do Catete e era baratinha. S\u00f3 tocava m\u00fasica brasileira, o que pra n\u00f3s, docemente xen\u00f3fobos, era obrigat\u00f3rio. Fomos.<\/div>\n<div align=\"justify\">Nesta casa &#8211; o Forr\u00f3 Forrado &#8211;\u00a0descobri que o\u00a0preto triste e zangado\u00a0de Nova Igua\u00e7u era, de fato, artista. E tinha cada m\u00fasica bonita de doer. Passei a ir quase toda semana ao forr\u00f3, mas nunca falei pro homem que o conhecia. <\/div>\n<div align=\"justify\">Ele nunca reparou na minha exist\u00eancia. Continuou morando em Rosa dos Ventos, tomando as canas na mesma birosca, convivendo com os mesmos cacha\u00e7as. Mas eu sabia, como a doida\u00a0Maria do Carmo, que o homem era artista maior, um poeta do povo. <\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">Um dia,\u00a0depois de doen\u00e7a ingrata, \u00a0morreu \u00e0 m\u00edngua, pobre de marr\u00e9-de-si. <\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">Hoje lembrei do cabra e tomei a primeira gelada.\u00a0Escutei uns cantos bonitos que ele fazia, feito o da estrela mi\u00fada que alumeia o mar &#8211; li\u00e7\u00e3o que, cada vez mais desconfiado de estrelas imensas,\u00a0tento aprender e reproduzir nos meus afetos e of\u00edcios.<\/p>\n<p>\u00c0s margens do rio Maracan\u00e3, o da minha aldeia,\u00a0este arrazoado vai\u00a0na inten\u00e7\u00e3o do poeta que um dia subiu nos ares e foi brincar, encantado brasileiro,\u00a0na asa do\u00a0vento leste. Dizem que l\u00e1 ningu\u00e9m \u00e9 triste.\u00a0Mojub\u00e1,\u00a0Jo\u00e3o do Vale.<\/p>\n<p><a href=\"http:\/\/www.blogger.com\/%3Ciframe%20width=%22420%22%20height=%22315%22%20src=%22http:\/\/www.youtube.com\/embed\/PsY_rdXJQhs%22%20frameborder=%220%22%20allowfullscreen%3E%3C\/iframe%3E\"><\/a><\/p>\n<p>Abra\u00e7os<\/p><\/div>\n<div align=\"justify\">\u00a0<\/div>\n<div align=\"justify\">\n<div>\u00a0<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Minha av\u00f3, quando veio de Pernambuco, recebeu de sua Yalorix\u00e1 a permiss\u00e3o para abrir uma ro\u00e7a de\u00a0santo no Rio de Janeiro. Aqui chegando, comprou unsTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[292],"tags":[],"class_list":["post-12822","post","type-post","status-publish","format-standard","hentry","category-historias-brasileiras"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/12822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=12822"}],"version-history":[{"count":0,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/12822\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=12822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=12822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=12822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}