{"id":12554,"date":"2009-07-28T17:09:00","date_gmt":"2009-07-28T19:09:00","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2009\/07\/casamento-oficiante-e-amizade\/"},"modified":"2009-07-28T17:09:00","modified_gmt":"2009-07-28T19:09:00","slug":"casamento-oficiante-e-amizade","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2009\/07\/casamento-oficiante-e-amizade\/","title":{"rendered":"Casamento, Oficiante e Amizade"},"content":{"rendered":"<p><a href=\"http:\/\/1.bp.blogspot.com\/_KYflagr2MuI\/Sm9LvsMFwsI\/AAAAAAAAAfg\/mKzfDw6o0TI\/s1600-h\/Casamento+do+Guilherme_Jul_2009+001.jpg\"><img decoding=\"async\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2009\/07\/Casamento+do+Guilherme_Jul_2009+001.jpg\" alt=\"\" border=\"0\"><\/a>Domingo eu fui oficiante no casamento do Guilherme, amigo meu e que dedicou comigo nos cursos para a Juventude Messi\u00e2nica anos atr\u00e1s.<\/p>\n<p>Explicando a quem n\u00e3o \u00e9 messi\u00e2nico: oficiantes s\u00e3o rapazes ou mo\u00e7as que auxiliam nas celebra\u00e7\u00f5es de cultos, casamentos e batizados. A fun\u00e7\u00e3o deles \u00e9 colocar as oferendas no Altar e auxiliar nos demais rituais que comp\u00f5em a celebra\u00e7\u00e3o.<\/p>\n<div>Isto posto, queria dizer que fiquei muito feliz com o convite. Primeiro pela lembran\u00e7a ap\u00f3s dois anos afastado dele, mais por culpa minha &#8211; eu precisei dar aten\u00e7\u00e3o \u00e0s meninas ap\u00f3s o nascimento, natural. Segundo pelo Ministro oficiante ser o Marcelo, meu amigo de longa data. Terceiro, por finalmente fechar um ciclo de 8 anos como oficiante (1997 a 2005) e que havia ficado meio que em aberto.<a href=\"http:\/\/4.bp.blogspot.com\/_KYflagr2MuI\/Sm9L48APQOI\/AAAAAAAAAfo\/QyoOZVa2SpY\/s1600-h\/Casamento+do+Guilherme_Jul_2009+012.jpg\"><img decoding=\"async\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2009\/07\/Casamento+do+Guilherme_Jul_2009+012.jpg\" alt=\"\" border=\"0\"><\/a><\/div>\n<p>Pela primeira vez participei de um casamento messi\u00e2nico ao ar livre. O local era bem legal, apesar de longe &#8211; Vargem Grande. As pessoas que nos apoiaram o fizeram sem o menor estresse. O Eduardo, outro oficiante, excelente de se lidar.<\/p>\n<p>A cerim\u00f4nia correu bem, sem sobressaltos, e a festa depois foi \u00f3tima. Consegui me divertir bastante, at\u00e9 porque, desta vez, fomos apenas eu e a Daniele, minha esposa &#8211; \u00e9 a segunda vez que isso acontece desde que nasceu a Maria Clara&#8230;<\/p>\n<p><a href=\"http:\/\/3.bp.blogspot.com\/_KYflagr2MuI\/Sm9MGajQqLI\/AAAAAAAAAfw\/c4OEI64ZSUg\/s1600-h\/Casamento+do+Guilherme_Jul_2009+017.jpg\"><img decoding=\"async\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2009\/07\/Casamento+do+Guilherme_Jul_2009+017.jpg\" alt=\"\" border=\"0\"><\/a>Todavia, nem era nisso que queria falar, mas, sim, das amizades de toda uma vida. Acho que sou um sortudo ao chegar aos 34 anos com pelo menos meia d\u00fazia de amizades que beiram os 20 anos. Pessoas de quem voc\u00ea at\u00e9 fica um tempo afastado, mas sabe que querem o seu bem e que voc\u00ea pode contar em todas horas, como se de sangue fossem. N\u00e3o cito nomes aqui, pois seria injusto.<\/p>\n<p>Infelizmente o mundo de hoje d\u00e1 muito pouco valor a coisas como amizade, longo prazo, doa\u00e7\u00e3o, altru\u00edsmo. Queimam-se relacionamentos de 10, 20 anos por uma migalha que represente a menor vantagem que seja. Primeiro eu, depois eu e em terceiro eu. \u00c9tica ? Hoje atrapalha.<br \/><a href=\"http:\/\/4.bp.blogspot.com\/_KYflagr2MuI\/Sm9MQy1rP9I\/AAAAAAAAAf4\/-OEJxkhut4k\/s1600-h\/Casamento+do+Guilherme_Jul_2009+019.jpg\"><img decoding=\"async\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2009\/07\/Casamento+do+Guilherme_Jul_2009+019.jpg\" alt=\"\" border=\"0\"><\/a><br \/>Seria tudo bem melhor se as pessoas dessem valor \u00e0 amizade. As cultivassem como cultivam um p\u00e9 de caf\u00e9 ou como a longa vida de uma tartaruga marinha. Sempre entendendo que um amigo verdadeiro faz n\u00e3o o que voc\u00ea quer, mas o que voc\u00ea precisa.<\/p>\n<p>Em tempo: como bem disse o Ministro Marcelo na cerim\u00f4nia, &#8220;o que Deus uniu, o homem n\u00e3o separa&#8221;.<\/p>\n<p><span>Fotos:<\/span><br \/><span>1 &#8211; Altar Itinerante usado na cerim\u00f4nia;<\/span><br \/><span>2 &#8211; In\u00edcio da Cerim\u00f4nia;<\/span><br \/><span>3 e 4 &#8211; Cerim\u00f4nia do Brinde;<\/span><br \/><span>5 &#8211; Da esquerda para a direita: eu, Daniele, Eduardo, Fernanda, M\u00e1rcia e Marcelo.<\/span><\/p>\n<p><a href=\"http:\/\/2.bp.blogspot.com\/_KYflagr2MuI\/Sm9Mdzjh3DI\/AAAAAAAAAgA\/u5f9dF-AUUc\/s1600-h\/Casamento+do+Guilherme_Jul_2009+023.jpg\"><img decoding=\"async\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2009\/07\/Casamento+do+Guilherme_Jul_2009+023.jpg\" alt=\"\" border=\"0\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domingo eu fui oficiante no casamento do Guilherme, amigo meu e que dedicou comigo nos cursos para a Juventude Messi\u00e2nica anos atr\u00e1s. Explicando a quemTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[10,7,9],"class_list":["post-12554","post","type-post","status-publish","format-standard","hentry","category-pedro-migao","tag-igreja-messianica","tag-reflexoes","tag-religiao"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/12554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=12554"}],"version-history":[{"count":0,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/12554\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=12554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=12554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=12554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}