{"id":12118,"date":"2010-02-24T07:35:00","date_gmt":"2010-02-24T09:35:00","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2010\/02\/demagogia\/"},"modified":"2010-02-24T07:35:00","modified_gmt":"2010-02-24T09:35:00","slug":"demagogia","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2010\/02\/demagogia\/","title":{"rendered":"Demagogia"},"content":{"rendered":"<div><a href=\"http:\/\/1.bp.blogspot.com\/_KYflagr2MuI\/S4QEFDPuI4I\/AAAAAAAAByo\/xbf71nCRquQ\/s1600-h\/mendigos.jpg\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"139\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2010\/02\/mendigos.jpg\" width=\"200\"><\/a><\/div>\n<div>Leio no jornal <a href=\"http:\/\/www.odia.com.br\/\">O Dia<\/a> de ontem que a prefeitura est\u00e1 instalando pedras embaixo de viadutos e divis\u00f3rias de ferro nos bancos de pra\u00e7a para impedir que moradores de rua durmam nestes locais. \u00c9 uma medida antip\u00e1tica e que requer uma an\u00e1lise aprofundada.<\/p>\n<p>Dentro da pol\u00edtica atual da Prefeitura do Rio de massacrar aqueles que trabalham e &#8220;maquiar&#8221; a figura da cidade para que os turistas n\u00e3o vejam \u00e9 algo perfeitamente coerente. A quest\u00e3o \u00e9 que este tipo de medida n\u00e3o passa de paliativo, n\u00e3o resolvendo a quest\u00e3o social do morador de rua.<\/p>\n<p><a href=\"http:\/\/pedromigao.blogspot.com\/2010\/01\/incendios-upps-e-favelofobia.html\">Tal e qual a pol\u00edtica das UPPs<\/a>, o objetivo \u00e9 afastar os moradores de rua do eixo Centro-Zona Sul, confinando-os \u00e0s regi\u00f5es das Zonas Norte ou Oeste. Estas n\u00e3o fazem parte do mapa da cidade para efeito de pol\u00edticas p\u00fablicas, servindo apenas como dejeto de tudo que n\u00e3o \u00e9 adequado \u00e0s \u00e1reas nobres da cidade. A finalidade \u00e9 deixar a popula\u00e7\u00e3o de rua junto com os traficantes em algum lugar isolado como Piedade ou Santa Cruz.<\/p>\n<p>Obviamente, impedir que pessoas durmam embaixo dos viadutos ou em bancos de pra\u00e7a n\u00e3o ir\u00e1 resolver o problemas destas. Apenas deslocar, o que parece atingir \u00e0 necessidade dos \u00f3rg\u00e3os da prefeitura. Entretanto, faz-se necess\u00e1ria uma pol\u00edtica de reinser\u00e7\u00e3o destes indiv\u00edduos na sociedade organizada, primeiro atrav\u00e9s de a\u00e7\u00f5es sociais e posteriormente por meio de medidas que permitam a absor\u00e7\u00e3o destes pelo mercado de trabalho.<\/p>\n<p>N\u00e3o custa lembrar que muitos destes &#8220;moradores de rua&#8221; s\u00e3o catadores de latinhas ou de papel\u00e3o &#8211; desempenhando um papel importante n\u00e3o somente na economia quanto no meio ambiente. Muitas vezes s\u00e3o pessoas que possuem suas casas, mas a dist\u00e2ncia e o trabalho de sol a sol impedem que retornem todos os dias para seus lares. Estes demandam um tipo de medida diferente do requerido pelas popula\u00e7\u00f5es t\u00edpicas de rua.<\/p>\n<p>Na pr\u00e1tica, a medida tomada equivale a uma vers\u00e3o amenizada do famoso epis\u00f3dio do Guandu, onde mendigos teriam sido afogados \u00e0s dezenas por ordem da ent\u00e3o secret\u00e1ria de estado Sandra Cavalcanti. Infelizmente, mais de quarenta anos depois repete-se esta desagrad\u00e1vel faceta de nossos governantes.<\/p>\n<p>Que fique claro que n\u00e3o sou a favor de mendigos e assemelhados, mas sou a favor de pol\u00edticas que os permitam sair desta situa\u00e7\u00e3o. Varrer o problema para debaixo do tapete n\u00e3o adianta rigorosamente nada, apesar do prefeito atual professar a velha cren\u00e7a do in\u00edcio do S\u00e9culo XX de que <i>&#8220;a quest\u00e3o social \u00e9 caso de pol\u00edcia.&#8221;<\/i><\/div>\n<div>Entretanto, como o alcaide da cidade acha que foi eleito para governar a Zona Sul somos obrigados a ver este tipo de atitude elitista, paliativa e que n\u00e3o resolve rigorosamente nada.<\/div>\n<div><\/div>\n<div>Ou seja, lament\u00e1vel.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Leio no jornal O Dia de ontem que a prefeitura est\u00e1 instalando pedras embaixo de viadutos e divis\u00f3rias de ferro nos bancos de pra\u00e7a paraTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[26,24,27,6],"class_list":["post-12118","post","type-post","status-publish","format-standard","hentry","category-pedro-migao","tag-policia","tag-politica","tag-sociedade","tag-vida-cotidiana"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/12118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=12118"}],"version-history":[{"count":0,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/12118\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=12118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=12118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=12118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}