{"id":11073,"date":"2012-04-27T06:29:00","date_gmt":"2012-04-27T08:29:00","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/04\/reading-de-volta-a-premier-league\/"},"modified":"2012-04-27T06:29:00","modified_gmt":"2012-04-27T08:29:00","slug":"reading-de-volta-a-premier-league","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/04\/reading-de-volta-a-premier-league\/","title":{"rendered":"Reading: de volta \u00e0 Premier League"},"content":{"rendered":"<div>\n<div><\/div>\n<p>O leitor deste blog sabe que o Flamengo este ano de 2012 somente tem me trazido desgosto. \u00c9 mico atr\u00e1s de mico, bagun\u00e7a atr\u00e1s de bagun\u00e7a, vexame atr\u00e1s de vexame e agora um m\u00eas de f\u00e9rias at\u00e9 o in\u00edcio do Brasileiro. Como dizia aquele ministro da ditadura, &#8220;nada a declarar&#8221;.<\/p>\n<p>Mas at\u00e9 que minhas &#8220;paix\u00f5es alternativas&#8221; vem me trazendo algum alento. O Giants foi campe\u00e3o da NFL e o Knicks no momento em que escrevo est\u00e1 classificado para os playoffs da NBA. Mas quero falar hoje de outra simpatia alternativa que vem me trazendo alegrias: o Reading Football Clube, da Inglaterra.<\/p>\n<p>Clube da cidade de mesmo nome, a pouco mais de 60 quil\u00f4metros de Londres e que hoje se notabiliza por ser um centro universit\u00e1rio, de seguros e da ind\u00fastria de inform\u00e1tica (uma esp\u00e9cie de &#8220;Vale do Sil\u00edcio&#8221; inglesa), o azul e branco brit\u00e2nico esta \u00faltima semana conquistou n\u00e3o somente o direito de retornar \u00e0 Premier League para a temporada 2012\/13 como ainda obteve o t\u00edtulo da Championship, a Segundona inglesa.<\/p>\n<div><\/div>\n<p>O clube foi fundado em 1871 e passou por duas fus\u00f5es antes de adotar seu nome atual, em 1877 e em 1889. Passou a jogar no profissionalismo em 1920 e at\u00e9 2006 jamais havia jogado na Primeira Divis\u00e3o, a Premier League.<\/p>\n<p>O\u00a0nome\u00a0da cidade e consequentemente do clube n\u00e3o tem nada a ver com leitura, apesar de Reading ser um dos centros universit\u00e1rios do Reino Unido. O nome vem de &#8220;Reada Ingas&#8221;, povo de Reada em portugu\u00eas &#8211; Reada foi um chefe sax\u00e3o do S\u00e9culo VIII.<\/p>\n<p>As listras azuis e brancas do uniforme formam uma combina\u00e7\u00e3o bastante incomum em uniformes esportivos de futebol: o formato horizontal j\u00e1 \u00e9 raro, ainda mais nesta cor. E foi justamente o uniforme que me aproximou da equipe, no ano em que disputava a Premier League da vez anterior.<\/p>\n<div><\/div>\n<div><\/div>\n<div>As cores do uniforme eram id\u00eanticas \u00e0s utilizadas pelo meu (hoje extinto) time no jogo online Hattrick, o Mig\u00e3o Clube. Como azul e branco nesta configura\u00e7\u00e3o \u00e9 algo muito raro, me chamou a aten\u00e7\u00e3o &#8211; e passei a ter simpatia pelo clube.<\/div>\n<div><\/div>\n<div>Naquela temporada (2007\/08) consegui que uma brasileira a quem havia prestado um favor aqui no Rio de Janeiro (arrumar uma vaga em uma escola de samba para ela e um grupo) me trouxesse uma camisa do clube daquela temporada (foto, da \u00e9poca, no final deste post). Talvez seja um dos \u00fanicos brasileiros a ter uma camisa do Reading \u00a0&#8211; pronuncia-se R\u00e9ding &#8211; aqui. Neste ano de 2012 encomendei outra camisa mas ela simplesmente se extraviou nos Correios, apesar de estar paga h\u00e1 muito tempo&#8230;<\/div>\n<div><\/div>\n<div>Aquela mesma temporada teve um final tr\u00e1gico, com o rebaixamento na \u00faltima rodada na diferen\u00e7a do saldo de gols. Com isso o clube esteve de l\u00e1 para c\u00e1 na Segundona inglesa, denominada &#8220;Championship&#8221;, que tem uma f\u00f3rmula de disputa bastante peculiar: as 24 equipes jogam em turno e returno. Ao final os dois primeiros s\u00e3o promovidos e os clubes classificados do terceiro ao sexto lugar disputam um playoff para determinar o terceiro clube a subir para a Premier League, a primeira divis\u00e3o.<\/div>\n<div><\/div>\n<div>Ano passado o clube &#8220;bateu na trave&#8221;: ap\u00f3s uma sensacional rea\u00e7\u00e3o na segunda metade da temporada terminou em quinto no campeonato e perdeu a chance de subir ap\u00f3s perder por 4 a 2 para o Swansea na final do playoff &#8211; com 86 mil pessoas em Wembley e uma arbitragem muito contestada.<\/div>\n<div><\/div>\n<div><\/div>\n<p>  Na temporada passada passei a acompanhar os jogos da equipe praticamente em tempo real pelo Twitter oficial. O clube tem uma estrutura de dar inveja a qualquer time brasileiro, o que pode ser visto pelo Madejski Stadium, que foi\u00a0constru\u00eddo\u00a0em 1998 e tem capacidade para 24 mil pagantes &#8211; antes, o time jogou durante um s\u00e9culo no Elm Park.<\/p>\n<p>Para o leitor acostumado com a bagun\u00e7a do futebol brasileiro ter uma ideia, o carn\u00ea de ingressos para a pr\u00f3xima temporada custar\u00e1 aproximadamente R$ 1,3 mil nos melhores lugares do est\u00e1dio, e R$ 1,1 mil nos demais &#8211; para todos os jogos. Isso quando sequer a temporada atual se encerrou.<\/p>\n<p>Na temporada atual o time teve uma arrancada espetacular, com 22 vit\u00f3rias nos 27 jogos finais (de um total de 46) e pulando da d\u00e9cima quarta coloca\u00e7\u00e3o para o t\u00edtulo. A promo\u00e7\u00e3o \u00e0 Premier League veio na ter\u00e7a feira retrasada, com a vit\u00f3ria de 1 a 0 sobre o Nottingham Forest (dois primeiros v\u00eddeos). Note o leitor a invas\u00e3o de campo pelo p\u00fablico a fim de comemorar a promo\u00e7\u00e3o. Nos dois v\u00eddeos seguintes, gravados na vit\u00f3ria fora de casa sobre o Brighton, temos a torcida e a sua m\u00fasica tema, &#8220;We\u00b4re going up&#8221;.<\/p>\n<p>No s\u00e1bado \u00faltimo, apesar do empate de 2 a 2 com o Bristol City o clube conquistou o t\u00edtulo devido \u00e0 derrota do Southampton por 2 a 1 para o Middlesbrough, alcan\u00e7ando 89 pontos e quatro de vantagem a uma rodada do fim.<\/p>\n<p>Vamos aguardar a prepara\u00e7\u00e3o para a vida na Premier League. O time precisa se refor\u00e7ar se quiser manter-se na elite do futebol ingl\u00eas. Mas pelo menos neste momento \u00e9 fonte de alegrias para este blogueiro t\u00e3o maltratado pelo Flamengo&#8230;.<\/p>\n<p>Para saber mais:<\/p>\n<p>&#8211; <a href=\"http:\/\/www.readingfc.co.uk\/page\/Home\/0,,10306,00.html\" target=\"_blank\">Site Oficial<\/a>;<br \/>&#8211; <a href=\"http:\/\/twitter.com\/ReadingFC\" target=\"_blank\">Twitter<\/a>;<\/p>\n<div><a href=\"http:\/\/3.bp.blogspot.com\/-oKjBFHb3E_U\/T5TMfZtm62I\/AAAAAAAAEpE\/xDZzAneT7Mo\/s1600\/Cabi%C3%BAna_06_03_08+017.jpg\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"480\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/04\/Cabi%C3%BAna_06_03_08+017.jpg\" width=\"640\"><\/a><\/div>\n<p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>O leitor deste blog sabe que o Flamengo este ano de 2012 somente tem me trazido desgosto. \u00c9 mico atr\u00e1s de mico, bagun\u00e7a atr\u00e1s deTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[41,37,36],"class_list":["post-11073","post","type-post","status-publish","format-standard","hentry","category-pedro-migao","tag-esporte","tag-futebol","tag-gestao-esportiva"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/11073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=11073"}],"version-history":[{"count":0,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/11073\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=11073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=11073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=11073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}