{"id":10968,"date":"2012-07-25T08:35:00","date_gmt":"2012-07-25T10:35:00","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/07\/tempo-midiatico-e-tempo-de-voto-momentos-diferentes\/"},"modified":"2012-07-25T08:35:00","modified_gmt":"2012-07-25T10:35:00","slug":"tempo-midiatico-e-tempo-de-voto-momentos-diferentes","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/07\/tempo-midiatico-e-tempo-de-voto-momentos-diferentes\/","title":{"rendered":"Tempo midi\u00e1tico e tempo de voto: momentos diferentes"},"content":{"rendered":"<div><a href=\"http:\/\/2.bp.blogspot.com\/-g2Rz0SlNJZc\/UA8F92ajJoI\/AAAAAAAAFeg\/oAtMz2TkfpU\/s1600\/elei%C3%A7oes+e+olimpiadas.jpg\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"360\" sda=\"true\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/07\/elei%C3%A7oes+e+olimpiadas.jpg\" width=\"640\"><\/a><\/div>\n<p><\/p>\n<div>Tenho visto bastante excita\u00e7\u00e3o na imprensa como um todo \u2013 incluindo n\u00e3o somente a grande m\u00eddia como blogs formadores de opini\u00e3o \u2013 com as elei\u00e7\u00f5es municipais que se avizinham.<\/div>\n<div><\/div>\n<div>Gr\u00e1ficos de inten\u00e7\u00e3o de votos, tend\u00eancias, alian\u00e7as, declara\u00e7\u00f5es. Tudo \u00e9 amplificado \u2013 ou n\u00e3o \u2013 com grande estardalha\u00e7o buscando ressoar os interesses defendidos por estes \u00f3rg\u00e3os.<\/div>\n<div><\/div>\n<div>Entretanto n\u00e3o se v\u00ea na popula\u00e7\u00e3o o mesmo entusiasmo midi\u00e1tico. Ainda que comparado ao mesmo per\u00edodo em outras ocasi\u00f5es me parece que o interesse da popula\u00e7\u00e3o \u00e9 ainda menor.<\/div>\n<div><\/div>\n<div>Aqui no Rio de Janeiro, especificamente, o quadro n\u00e3o ajuda muito. O atual prefeito Eduardo Paes, candidato \u00e0 reelei\u00e7\u00e3o, n\u00e3o empolga, mas as op\u00e7\u00f5es competitivas a ele tamb\u00e9m n\u00e3o representam progresso.<\/div>\n<div><\/div>\n<div>Pois vejamos: os dois principais candidatos de oposi\u00e7\u00e3o s\u00e3o a dupla para l\u00e1 de ins\u00f3lita formada pelos filhos do ex-prefeito Cesar Maia e do ex-governador Anthony Garotinho \u2013 <a href=\"http:\/\/pedromigao.blogspot.com.br\/2012\/03\/garotinho-e-cesar-maia-uma-analise-de.html\" target=\"_blank\"><strong>cujos problemas j\u00e1 escrevi em outro post<\/strong><\/a> \u2013 e o PSOL apresentou a candidatura do deputado estadual Marcelo Freixo. Embora este \u00faltimo entusiasme certo segmento formador de opini\u00e3o, a pol\u00edtica de alian\u00e7as do partido a meu ver impede que v\u00e1 muito longe \u2013 ele simplesmente n\u00e3o consegue dialogar com os segmentos mais populares do eleitorado.<\/div>\n<div><\/div>\n<div>Ou seja, at\u00e9 por in\u00e9rcia a tend\u00eancia \u00e9 que o prefeito Eduardo Paes se reeleja em primeiro turno. N\u00e3o votei nele em 2008 \u2013 sufraguei o hoje deputado federal Chico Alencar no primeiro turno e anulei o voto no segundo \u2013 mas diria que at\u00e9 pelas minhas baixas expectativas ele acabou superando o que eu imaginava.<\/div>\n<div><\/div>\n<div>\u00c9 ineg\u00e1vel que a cidade hoje \u00e9 um canteiro de obras e que o andamento das instala\u00e7\u00f5es de infraestrutura visando os Jogos Ol\u00edmpicos parece satisfat\u00f3rio. Outro ponto que \u00e9 menor, mas que me interessa: pela primeira vez vejo um representante do Poder P\u00fablico tentando limitar o poder dos comandantes do carnaval carioca.<\/div>\n<div><\/div>\n<div>Por outro lado \u00e9 evidente que muito mais poderia ter sido feito em diversas \u00e1reas, apesar do estado de \u201cterra arrasada\u201d herdado de seu antecessor Cesar Maia. O fato de pertencer ao grupo pol\u00edtico do atual governador, enredado e enrolado em rela\u00e7\u00f5es no m\u00ednimo esquisitas com construtoras e que tais, tamb\u00e9m dep\u00f5e contra.<\/div>\n<div><\/div>\n<div>Alias e a prop\u00f3sito, chega a ser engra\u00e7ado ver a chapa dos filhos pr\u00f3digos fazendo campanha baseada na moralidade. Fecha o par\u00eantese.<\/div>\n<div><\/div>\n<div>S\u00e3o Paulo, a outra capital relevante que n\u00e3o havia abordado, tem um quadro mais interessante. O ex-governador e ex-prefeito \u2013 sem encerrar o mandato em nenhum dos casos \u2013 Jos\u00e9 Serra tem uma lideran\u00e7a que me parece fr\u00e1gil. Por outro lado, o candidato petista Haddad \u00e9 pouco conhecido, embora tenha uma rejei\u00e7\u00e3o bem menor.<\/div>\n<div><\/div>\n<div>Serra possui elevada rejei\u00e7\u00e3o devido \u00e0 m\u00e1 avalia\u00e7\u00e3o do governo Kassab e \u00e0 desconfian\u00e7a de que n\u00e3o ir\u00e1 terminar seu mandato uma vez mais. Por outro lado as recentes den\u00fancias do livro \u201cA Privataria Tucana\u201d, <a href=\"http:\/\/pedromigao.blogspot.com.br\/2012\/02\/o-arriscado-calculo-de-jose-serra.html\" target=\"_blank\">como escrevi em artigo anterior<\/a>, certamente ser\u00e3o relembradas durante a campanha.<\/div>\n<div><\/div>\n<div>N\u00e3o surpreende, portanto, que o candidato tucano esteja em uma cruzada visando censurar blogs e perfis em redes sociais que a ele fazem cr\u00edticas. Vale lembrar que ele tem apoio total de chamada \u201cgrande m\u00eddia\u201d \u2013 muito \u00e0 base de compra maci\u00e7a de assinaturas de publica\u00e7\u00f5es destes ve\u00edculos por parte de \u00f3rg\u00e3os p\u00fablicos paulistas.<\/div>\n<div><\/div>\n<div>Por outro lado, tamb\u00e9m se deve lembrar que no governo ele tinha o h\u00e1bito de \u201cpedir a cabe\u00e7a\u201d de jornalistas que o ousassem critic\u00e1-lo. Enfim, lament\u00e1vel.<\/div>\n<div><\/div>\n<div>A tend\u00eancia \u00e9 de que Haddad cres\u00e7a \u00e0 medida em que ficar mais conhecido o fato de ser o candidato da Presidenta Dilma (bem avaliada <personname productid=\"em S\u00e3o Paulo\" w:st=\"on\">em S\u00e3o Paulo<\/personname>) e do ex-Presidente Lula. De acordo com pesquisas cerca de 40% dos paulistanos votariam em um candidato apoiado pela Presidenta. Por outro lado a alian\u00e7a com Paulo Maluf ao que parece tira mais votos que d\u00e1 ao candidato petista.<\/div>\n<div><\/div>\n<div>Mas ao contr\u00e1rio do Rio de Janeiro a elei\u00e7\u00e3o paulistana somente dever\u00e1 se definir quando a campanha realmente chamar a aten\u00e7\u00e3o da popula\u00e7\u00e3o. Em minha \u00faltima visita \u00e0 capital paulista, que foi rapid\u00edssima \u2013 durou cerca de seis horas, para a grava\u00e7\u00e3o do programa da ESPN \u2013 me chamou a aten\u00e7\u00e3o a m\u00e1 avalia\u00e7\u00e3o da gest\u00e3o de Gilberto Kassab e a desconfian\u00e7a generalizada de que Serra n\u00e3o ir\u00e1 cumprir o mandato at\u00e9 o final.<\/div>\n<div><\/div>\n<div>Sem d\u00favida alguma as Olimp\u00edadas a serem realizadas a partir da semana que vem tendem a retardar o in\u00edcio do interesse da popula\u00e7\u00e3o pelas pr\u00f3ximas elei\u00e7\u00f5es. Apesar de estar sendo absolutamente ignorada pela Rede Globo, a realiza\u00e7\u00e3o dos Jogos deve canalizar o interesse de boa parte da popula\u00e7\u00e3o nas pr\u00f3ximas duas semanas.<\/div>\n<div><\/div>\n<div>Outro fator \u00e9 que a propaganda eleitoral gratuita no r\u00e1dio e na televis\u00e3o somente se inicia em 21 de agosto, o que tamb\u00e9m retarda o interesse popular pelas elei\u00e7\u00f5es. O pr\u00f3ximo julgamento do Mensal\u00e3o tamb\u00e9m dever\u00e1 estar encerrado quando do in\u00edcio dos comerciais da televis\u00e3o e, apesar do massacre midi\u00e1tico que se espera sobre este caso, tamb\u00e9m tenho d\u00favidas sobre seu alcance nas inten\u00e7\u00f5es de voto.<\/div>\n<div><\/div>\n<div>Finalizando, apesar das expectativas midi\u00e1ticas de especialmente impor seus preferidos, a campanha eleitoral e especialmente a defini\u00e7\u00e3o de voto efetiva da popula\u00e7\u00e3o somente ocorrer\u00e3o bem mais tarde e bem mais pr\u00f3xima ao pleito.<\/div>\n<div><\/div>\n<div><em>P.S. \u2013 acho que pela primeira vez desde 1992, quando comecei a votar, chego a esta \u00e9poca do ano sem ter nenhum voto definido.<\/em><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tenho visto bastante excita\u00e7\u00e3o na imprensa como um todo \u2013 incluindo n\u00e3o somente a grande m\u00eddia como blogs formadores de opini\u00e3o \u2013 com as elei\u00e7\u00f5esTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[78,93,24],"class_list":["post-10968","post","type-post","status-publish","format-standard","hentry","category-pedro-migao","tag-eleicoes-2012","tag-jogos-olimpicos-2012","tag-politica"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/10968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=10968"}],"version-history":[{"count":0,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/10968\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=10968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=10968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=10968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}