{"id":10934,"date":"2012-08-24T18:39:00","date_gmt":"2012-08-24T20:39:00","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/08\/final-de-semana-preceito\/"},"modified":"2012-08-24T18:39:00","modified_gmt":"2012-08-24T20:39:00","slug":"final-de-semana-preceito","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/08\/final-de-semana-preceito\/","title":{"rendered":"Final de Semana &#8211; &quot;Preceito&quot;"},"content":{"rendered":"<p><\/p>\n<div><\/div>\n<p><\/p>\n<div><\/div>\n<div>Nesta semana muito corrida, nossa faixa musical traz a cantora Luiza Dion\u00edsio, revela\u00e7\u00e3o do samba carioca. A faixa \u00e9 &#8220;Preceito&#8221;, do \u00f3timo cd lan\u00e7ado em 2010 denominado de &#8220;Devo\u00e7\u00e3o&#8221; &#8211; o qual ganhei de presente semana passada do amigo Luiz Carlos M\u00e1ximo.<\/div>\n<div><\/div>\n<div>Sem mais delongas, vamos \u00e0 letra, de autoria de Roque Ferreira e Toninho Geraes.<\/div>\n<div><\/div>\n<div><em>Malungo, olha l\u00e1 o Barra-vento<br \/>Que o som do aguer\u00ea vai te levar<br \/>Malungo respeita fundamento<br \/>Que o santo mandou respeitar<\/em><\/div>\n<div><\/div>\n<div><em>Falei n\u00e3o deu valor<br \/>A for\u00e7a do preceito lhe pegou<br \/>Falei voc\u00ea se embara\u00e7ou<br \/>Se \u00e9 da mironga tem que ser conhecedor<\/em><\/div>\n<div><\/div>\n<div><em>A comida que \u00e9 de santo<br \/>\u00c9 pra quem sabe preparar<br \/>Sem saber mexer na coisa<br \/>Deu Dend\u00ea pra Oxal\u00e1<\/em><\/div>\n<div><\/div>\n<div><em>E botou comida branca no peji de Beira-Mar<br \/>Hoje em dia t\u00e1 pagando<br \/>Que \u00e9 pra nunca mais errar<\/em><\/div>\n<div><\/div>\n<div><em>Falei n\u00e3o deu valor<br \/>A for\u00e7a do preceito lhe pegou<br \/>Falei voc\u00ea se embara\u00e7ou<br \/>Se \u00e9 da mironga tem que ser conhecedor<\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nesta semana muito corrida, nossa faixa musical traz a cantora Luiza Dion\u00edsio, revela\u00e7\u00e3o do samba carioca. A faixa \u00e9 &#8220;Preceito&#8221;, do \u00f3timo cd lan\u00e7ado emTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[12,40,15,85],"class_list":["post-10934","post","type-post","status-publish","format-standard","hentry","category-pedro-migao","tag-cultura","tag-final-de-semana","tag-musica","tag-samba"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/10934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=10934"}],"version-history":[{"count":0,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/10934\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=10934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=10934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=10934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}