{"id":10907,"date":"2012-09-21T07:23:00","date_gmt":"2012-09-21T09:23:00","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/09\/cinecasulofilia-a-vida-vai-melhorar\/"},"modified":"2012-09-21T07:23:00","modified_gmt":"2012-09-21T09:23:00","slug":"cinecasulofilia-a-vida-vai-melhorar","status":"publish","type":"post","link":"https:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/09\/cinecasulofilia-a-vida-vai-melhorar\/","title":{"rendered":"Cinecasulofilia &#8211; &quot;A vida vai melhorar&quot;"},"content":{"rendered":"<div><a href=\"http:\/\/1.bp.blogspot.com\/-BWjqBXahycQ\/UFo3jt8qHtI\/AAAAAAAAGLY\/Zm2nEYIBZo8\/s1600\/a+vida+vai+melhorar.jpg\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" hea=\"true\" height=\"424\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/09\/a+vida+vai+melhorar.jpg\" width=\"640\"><\/a><\/div>\n<p><\/p>\n<div>Nesta sexta feira, mais uma edi\u00e7\u00e3o <strong>da coluna \u201cCinecasulofilia\u201d, assinada pelo professor, cr\u00edtico de cinema e cineasta Marcelo Ikeda<\/strong>. De forma habitual, publicada em parceria <a href=\"http:\/\/www.cinecasulofilia.blogspot.com.br\/\" target=\"_blank\">com o blog de mesmo nome<\/a>.<\/div>\n<div><\/div>\n<div><strong><em>A vida vai melhorar<\/em><\/strong><\/div>\n<div><\/div>\n<div>Quando falo das influ\u00eancias do neorrealismo e o comparo com as op\u00e7\u00f5es tomadas por cineastas como Bresson ou os Dardennes, penso tamb\u00e9m em um filme recente como esse A vida vai melhorar, de Cedric Kahn. <\/div>\n<div><\/div>\n<div>Fico pensando tamb\u00e9m numa frase recente dita por Luiz Camilo Os\u00f3rio: \u201cDar ao mercado o que \u00e9 do mercado: agilidade e efici\u00eancia. Dar a arte o que \u00e9 da arte: tempo e experimenta\u00e7\u00e3o.\u201d <\/div>\n<div><\/div>\n<div>O filme de Kahn \u00e9 uma experi\u00eancia bem inserida no \u201cmercado de filmes de arte\u201d. Ele \u00e9 muito eficiente em prover o espectador de uma suposta experi\u00eancia com as dificuldades da classe m\u00e9dia baixa (dos desfavorecidos) em ascender socialmente. Mostra um casal que sonha em ter um restaurante, busca um empr\u00e9stimo e enfrenta obst\u00e1culo para honr\u00e1-lo. <\/div>\n<div><\/div>\n<div>O que me incomoda no filme \u00e9 justamente a sua efici\u00eancia. \u00c9 sua op\u00e7\u00e3o em faz\u00ea-lo sempre de uma forma muito confort\u00e1vel para o espectador. Em apresentar um mundo violento de uma forma nada violenta. O filme \u00e9 angustiante mas n\u00e3o \u00e9 violento. <\/div>\n<div><\/div>\n<div>O roteiro procura todo o tempo fazer com que o espectador se identifique com o drama desses personagens, a torcer pelo sucesso deles. A princ\u00edpio, o humanismo desse filme do Kahn nos comove, a partir do seu desejo em descortinar um lado do capitalismo contempor\u00e2neo, em que os neg\u00f3cios e a obsess\u00e3o pelo dinheiro sufocam a conquista do bem-estar. <\/div>\n<div><\/div>\n<div>Isso poderia muito bem se encaixar nos prop\u00f3sitos do filme do Bresson (L\u00b4argent). Mas o que \u00e9 muito diferente entre filme como O Dinheiro e A vida vai melhorar \u2013 j\u00e1 come\u00e7ando pelo t\u00edtulo \u2013 s\u00e3o as suas op\u00e7\u00f5es em como encenar esses prop\u00f3sitos, em como situar o espectador diante do que lhe \u00e9 exposto. <\/div>\n<div><\/div>\n<div>O filme do Kahn opta pela psicologiza\u00e7\u00e3o, pelo didatismo das inten\u00e7\u00f5es, pelo conforto do espectador. Pelo passeio de f\u00e9rias, ao inv\u00e9s da reflex\u00e3o. <\/div>\n<div><\/div>\n<div>Enquanto Kahn filma situa\u00e7\u00f5es angustiantes, Bresson encena angustiantemente. Enquanto Kahn busca sempre levar a narrativa para frente, de modo que o espectador fique esperando de forma aflita qual ser\u00e1 o desenrolar da trama, Bresson trava a naturaliza\u00e7\u00e3o de uma situa\u00e7\u00e3o que n\u00e3o pode ser encarada por n\u00f3s (espectadores) como natural, atrav\u00e9s de enquadramentos singulares e de elipses que exigem um outro engajamento do espectador. <\/div>\n<div><\/div>\n<div>O filme do Kahn \u00e9 bem feito (de boas inten\u00e7\u00f5es, o inferno est\u00e1 cheio), mas \u00e9 mercado. O filme de Bresson \u00e9 arte. <\/div>\n<div><\/div>\n<div>Por isso, Rosetta (falando dos Dardennes) poderia parecer um filme pr\u00f3ximo a este do Kahn, mas na verdade s\u00e3o dois filmes bem diferentes. Ou ainda, o cinema de Kaurismaki, que tamb\u00e9m circula por a\u00ed. Mas Kahn est\u00e1 mais para Loach, ainda que um pouco melhor do que este. <\/div>\n<div><\/div>\n<div>Ele quer fazer \u201cmercado de filmes de arte\u201d, e consegue!<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nesta sexta feira, mais uma edi\u00e7\u00e3o da coluna \u201cCinecasulofilia\u201d, assinada pelo professor, cr\u00edtico de cinema e cineasta Marcelo Ikeda. De forma habitual, publicada em parceriaTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[13,12,11],"class_list":["post-10907","post","type-post","status-publish","format-standard","hentry","category-cinecasulofilia","tag-cinema","tag-cultura","tag-marcelo-ikeda"],"_links":{"self":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/10907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=10907"}],"version-history":[{"count":0,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/10907\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=10907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=10907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=10907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}