{"id":47932,"date":"2018-02-19T10:08:19","date_gmt":"2018-02-19T13:08:19","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=47932"},"modified":"2018-02-19T16:59:57","modified_gmt":"2018-02-19T19:59:57","slug":"beija-flor-tuiuti-2018","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2018\/02\/beija-flor-tuiuti-2018\/","title":{"rendered":"A Beija-Flor, o Tuiuti e mais Algumas Notas sobre o Carnaval"},"content":{"rendered":"<p style=\"text-align: justify;\">Eu deveria ter escrito este artigo ainda na semana passada, p\u00f3s resultados, mas a Light me deixou sem luz desde a chuva da Quarta Feira de Cinzas at\u00e9 a noite de s\u00e1bado, de forma que somente agora consigo parar para escrever fazendo um balan\u00e7o sobre o carnaval 2018.<\/p>\n<p style=\"text-align: justify;\"><strong>Sobre o t\u00edtulo da Beija-Flor<\/strong>, o <a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2018\/02\/um-premio-ao-desenredo-e-a-falta-de-esmero\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\">artigo do editor adjunto Fred Sabino publicado semana passada<\/span><\/a> resume bem a quest\u00e3o. Considero, tamb\u00e9m, que a vit\u00f3ria refletiu a hegemonia do discurso da Lava Jato na sociedade, al\u00e9m de enveredar por um vi\u00e9s conservador. Explico.<\/p>\n<p style=\"text-align: justify;\">Ao abrir o desfile colocando &#8211; estou simplificando para melhor compreens\u00e3o &#8211; a corrup\u00e7\u00e3o da Petrobras como sendo a causadora dos problemas sociais do Brasil, a Beija-Flor repetiu o discurso da Lava Jato e de setores conservadores de que a corrup\u00e7\u00e3o da esquerda \u00e9 o mal fundamental em nossa sociedade. Os ratos banhados em petr\u00f3leo em uma das primeiras alas, bem como a reprodu\u00e7\u00e3o (mambembe) do edif\u00edcio sede da Cia em uma das alegorias s\u00e3o os exemplos apontados para a narrativa pela qual a escola de Nil\u00f3polis optou.<\/p>\n<p style=\"text-align: justify;\">Um bom exemplo desse vi\u00e9s \u00e9 que, ao contr\u00e1rio do Para\u00edso do Tuiuti, a Beija-Flor n\u00e3o sofreu press\u00f5es para alterar elementos de seu desfile para a noite das Campe\u00e3s. E nem deveria, pois reproduziu o discurso de quem det\u00e9m o poder constitu\u00eddo atualmente.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-14.26.47.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-47923\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-14.26.47-453x340.jpeg\" alt=\"\" width=\"593\" height=\"445\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-14.26.47-453x340.jpeg 453w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-14.26.47-300x225.jpeg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/WhatsApp-Image-2018-02-15-at-14.26.47.jpeg 720w\" sizes=\"auto, (max-width: 593px) 100vw, 593px\" \/><\/a>At\u00e9 a\u00ed, ok.<\/p>\n<p style=\"text-align: justify;\">A escola adotou um vi\u00e9s com o qual n\u00e3o compactuo, mas foi a narrativa escolhida para seu enredo e este n\u00e3o deve ser julgado ideologicamente. A quest\u00e3o \u00e9 que faltou carnavaliza\u00e7\u00e3o nos aspectos pl\u00e1sticos e visuais, especialmente em fantasias.<\/p>\n<p style=\"text-align: justify;\">Estava claro que muitas das roupas utilizadas no desfile foram compradas em lojas populares, sem qualquer tipo de estiliza\u00e7\u00e3o ou carnavaliza\u00e7\u00e3o. \u00d3bvio que n\u00e3o poder\u00edamos exigir luxo, mas a Beija-Flor repetiu uma solu\u00e7\u00e3o utilizada pela Tradi\u00e7\u00e3o em 2003, no ano do desfile sobre Ronaldo Fen\u00f4meno. Naquela ocasi\u00e3o, a agremia\u00e7\u00e3o de Campinho trouxe diversas alas com os componentes vestindo shorts, chuteiras e camisetas com os nomes das equipes que o jogador havia defendido at\u00e9 ent\u00e3o.<\/p>\n<p><iframe loading=\"lazy\" title=\"Tradi\u00e7\u00e3o 2003\" width=\"525\" height=\"394\" src=\"https:\/\/www.youtube.com\/embed\/cMdPVHd7PE0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">Guardadas as devidas propor\u00e7\u00f5es, a Beija-Flor utilizou o mesmo estratagema. Os uniformes do Col\u00e9gio Pedro II utilizados em uma das alegorias e nos caix\u00f5es foram claramente comprados em uma loja especializada e jogados direto no desfile &#8211; este \u00e9 um bom exemplo, mas poderia citar outros.<\/p>\n<p style=\"text-align: justify;\">Chega at\u00e9 a ser injusto com outras escolas que se esfor\u00e7aram para vestir e fantasiar adequadamente de 2.500 a 3 mil componentes em um ano extremamente duro para as finan\u00e7as das agremia\u00e7\u00f5es. Alas de short e camiseta, roupas baratas compradas em lojas populares e assemelhados fizeram 29,9 em 30 poss\u00edveis no quesito Fantasia. N\u00e3o d\u00e1.<\/p>\n<p style=\"text-align: justify;\">O mesmo vale para Alegorias, mas o julgamento deste quesito como um todo me pareceu, em um primeiro momento, bastante equivocado.<\/p>\n<p style=\"text-align: justify;\">Ainda sob este aspecto, <strong>me parece claro que o Tuiuti<\/strong> se beneficiou da repercuss\u00e3o de seu desfile entre as noites de domingo e segunda feira. Como as notas s\u00e3o fechadas apenas ap\u00f3s a passagem da \u00faltima escola, os jurados tiveram acesso ao notici\u00e1rio durante a segunda-feira e isso me parece ter exercido um efeito positivo sobre as notas da escola.<\/p>\n<p style=\"text-align: justify;\">Ao contr\u00e1rio da Beija-Flor, a meu ju\u00edzo era desfile para voltar \u00e0s Campe\u00e3s, mas n\u00e3o com o vice-campeonato. Entretanto, \u00e9 um pr\u00eamio para uma escola que n\u00e3o tinha nada a perder e que resolveu arriscar. Fica a li\u00e7\u00e3o para escolas como a Uni\u00e3o da Ilha, a S\u00e3o Clemente e a pr\u00f3pria Imperatriz.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/tuiuti-dsc-8361-alexandre-durao-g1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-47933\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/tuiuti-dsc-8361-alexandre-durao-g1-510x340.jpg\" alt=\"\" width=\"593\" height=\"395\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/tuiuti-dsc-8361-alexandre-durao-g1-510x340.jpg 510w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/tuiuti-dsc-8361-alexandre-durao-g1-300x200.jpg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/tuiuti-dsc-8361-alexandre-durao-g1-768x512.jpg 768w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/tuiuti-dsc-8361-alexandre-durao-g1.jpg 1600w\" sizes=\"auto, (max-width: 593px) 100vw, 593px\" \/><\/a>Ainda sobre o Tuiuti, a abordagem ideol\u00f3gica do enredo foi claramente oposta \u00e0 da Beija-Flor, mas cabe aqui fazer uma diferencia\u00e7\u00e3o: o desfile teve um vi\u00e9s de esquerda. A escola, longe disso &#8211; como deixou claro no pr\u00e9-desfile das Campe\u00e3s. Cheguei a achar engra\u00e7ado ver pessoas ligadas \u00e0 esquerda e que n\u00e3o acompanham carnaval o ano todo saudando a escola como tal.<\/p>\n<p style=\"text-align: justify;\">As escolas de samba, historicamente, sempre tiveram um vi\u00e9s de dialogar e\/ou aderir ao poder constitu\u00eddo &#8211; que, com breves exce\u00e7\u00f5es, sempre foi ideologicamente conservador.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2017\/01\/as-escolas-de-samba-e-a-critica-um-breve-historico\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\">Escrevi artigo em 2017 sobre a cr\u00edtica e o carnaval<\/span><\/a> onde digo que, \u00e0 exce\u00e7\u00e3o da d\u00e9cada de 80 do s\u00e9culo passado, o desafio ao poder constitu\u00eddo sempre foi a exce\u00e7\u00e3o absoluta, n\u00e3o a regra. A pr\u00f3pria rela\u00e7\u00e3o de depend\u00eancia das escolas de samba com o Poder P\u00fablico &#8211; que deveria ser menor, mas isso \u00e9 papo para depois &#8211; torna bastante escasso e estreito o espa\u00e7o para a contesta\u00e7\u00e3o e a cr\u00edtica.<\/p>\n<p style=\"text-align: justify;\">Ou, como nas<a href=\"https:\/\/www.facebook.com\/luizantonio.simas\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"> palavras do historiador e ex-colunista deste blog Luiz Antonio Simas em sua p\u00e1gina no Facebook<\/span><\/a>:<\/p>\n<p style=\"text-align: justify;\"><em>&#8220;Escolas de samba sempre dialogaram e negociaram, desde a d\u00e9cada de 1930, com inst\u00e2ncias externas: o poder p\u00fablico, via subven\u00e7\u00e3o, o setor do turismo, empresas privadas, o crime organizado&#8230; N\u00e3o interessa a nenhuma escola de samba fechar canais de di\u00e1logo com o poder institu\u00eddo. Podem apostar (&#8230;)&#8221;<\/em><\/p>\n<p style=\"text-align: justify;\">Tem muita gente me cobrando a <a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2018\/02\/algumas-reflexoes-sobre-o-grupo-especial\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\"><strong>promessa que fiz se a Grande Rio fosse rebaixada<\/strong><\/span><\/a>, mas prefiro esperar os desdobramentos do caso. O movimento por uma nova virada de mesa, trazendo de volta Grande Rio e Imp\u00e9rio Serrano, pode se concretizar dadas as \u00faltimas declara\u00e7\u00f5es \u00e0 imprensa, todas na linha de <em>&#8220;temos que respeitar o regulamento mas \u00e9 uma pena que a Grande Rio esteja sendo rebaixada&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">Em uma opini\u00e3o absolutamente pessoal e que n\u00e3o reflete a posi\u00e7\u00e3o institucional da escola da qual fa\u00e7o parte, penso que 14 escolas com ascenso e descenso de duas me parece o modelo ideal. Mas para o modelo de neg\u00f3cios do carnaval essa instabilidade de resultados e de regulamento prejudica bastante, especialmente no que tange \u00e0 capta\u00e7\u00e3o de recursos.<\/p>\n<p><iframe loading=\"lazy\" title=\"Final Portela - Desfile das Campe\u00e3s 2018\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/zE-maMKrJF4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\"><strong>J\u00e1 que tocamos em estabilidade, o quarto lugar da Portela<\/strong> poderia ter sido um pouco melhor, mas \u00e9 mostra da estabilidade que a gest\u00e3o do grupo pol\u00edtico Portela Verdade, do qual fa\u00e7o parte, trouxe \u00e0 escola. Cinco carnavais, um t\u00edtulo e cinco presen\u00e7as no Desfile das Campe\u00e3s, sendo com o Salgueiro a \u00fanica agremia\u00e7\u00e3o que esteve em todos os anos no s\u00e1bado das Campe\u00e3s. <a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2018\/02\/estatisticas-recentes-do-carnaval-carioca\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff6600;\">N\u00e3o \u00e0 toa, as duas lideram o atual ranking da Liesa<\/span><\/a>.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o \u00e9 pouca coisa. Como escrevi na semana passada, chegou a hora de um enredo que toque profundamente a emo\u00e7\u00e3o do portelense. Pelo que conversei durante o Desfile das Campe\u00e3s com diversas pessoas, n\u00e3o \u00e9 um sentimento somente meu.<\/p>\n<p style=\"text-align: justify;\"><strong>Finalizando, a dan\u00e7a das cadeiras no mundo do samba<\/strong> come\u00e7ou cedo este ano. A rec\u00e9m promovida Unidos do Viradouro contratou o carnavalesco Paulo Barros, em negocia\u00e7\u00e3o cuja qual j\u00e1 havia rumores n\u00e3o confirmados antes mesmo do carnaval e que se confirmou posteriormente. O carnavalesco campe\u00e3o Edson Pereira troca de lugar com Barros e far\u00e1 a Vila Isabel para 2019.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/20180217_230308.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-47934\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/20180217_230308-453x340.jpg\" alt=\"\" width=\"593\" height=\"445\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/20180217_230308-453x340.jpg 453w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/20180217_230308-300x225.jpg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2018\/02\/20180217_230308-768x576.jpg 768w\" sizes=\"auto, (max-width: 593px) 100vw, 593px\" \/><\/a>A Vila Isabel dispensou o mestre de bateria Chuvisco e seu int\u00e9rprete Igor Sorriso anunciou que n\u00e3o fica na escola &#8211; a tend\u00eancia \u00e9 de que seja reposto com a volta de Tinga, extremamente identificado com as cores de Noel. Mocidade, Mangueira e Portela renovaram com seus carnavalescos, respectivamente Alexandre Louzada, Leandro Vieira e Rosa Magalh\u00e3es. O Salgueiro tamb\u00e9m j\u00e1 havia renovado com Alex de Souza antes do Carnaval.<\/p>\n<p style=\"text-align: justify;\">A Tijuca contratou Patrick Carvalho, core\u00f3grafo da aclamada comiss\u00e3o de frente do Para\u00edso do Tuiuti.<\/p>\n<p style=\"text-align: justify;\">Acredito que outras mudan\u00e7as ir\u00e3o depender muito de que grupo a Grande Rio ir\u00e1 desfilar em 2019, bem como da perman\u00eancia ou n\u00e3o de La\u00edla na Beija-Flor.<\/p>\n<p style=\"text-align: justify;\">Ou seja, o carnaval 2019 j\u00e1 come\u00e7ou.<\/p>\n<p style=\"text-align: justify;\"><strong>Imagens: Fabiano Artiles, Arquivo Ouro de Tolo e G1 (Tuiuti)<\/strong><\/p>\n<p style=\"text-align: justify;\">[related_posts limit=&#8221;3&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eu deveria ter escrito este artigo ainda na semana passada, p\u00f3s resultados, mas a Light me deixou sem luz desde a chuva da Quarta FeiraTour Details<\/p>\n","protected":false},"author":2,"featured_media":47935,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[18,1224,1320,19],"class_list":["post-47932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pedro-migao","tag-carnaval","tag-carnaval-2018","tag-carnaval-2019","tag-escolas-de-samba"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/47932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=47932"}],"version-history":[{"count":7,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/47932\/revisions"}],"predecessor-version":[{"id":47944,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/47932\/revisions\/47944"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media\/47935"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=47932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=47932"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=47932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}