{"id":47580,"date":"2017-12-31T09:06:19","date_gmt":"2017-12-31T11:06:19","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=47580"},"modified":"2017-12-29T09:12:33","modified_gmt":"2017-12-29T11:12:33","slug":"2017-o-ano-em-que-odiamos","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2017\/12\/2017-o-ano-em-que-odiamos\/","title":{"rendered":"2017, o ano em que odiamos"},"content":{"rendered":"<p style=\"text-align: justify;\">E acabou 2017.<\/p>\n<p style=\"text-align: justify;\">Coube a mim o \u00faltimo post do blog no \u00faltimo dia do ano, e lembro que nessa \u00e9poca em 2016 implor\u00e1vamos por seu fim. N\u00e3o que ach\u00e1ssemos que 2017 seria melhor, mas que pelo menos acabasse logo aquele ano tr\u00e1gico.<\/p>\n<p style=\"text-align: justify;\">O ano de 2017 n\u00e3o foi tr\u00e1gico como 2016, n\u00e3o no geral, apesar de sempre termos nossas trag\u00e9dias pessoais como a perda que nosso editor teve, mas foi um ano esquisito. Um ano esquisito e ruim que acredito tenha sido consequ\u00eancia de 2016.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-47522 alignleft\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/12\/622_295c72e3-681f-4015-af84-7b631443df73-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/12\/622_295c72e3-681f-4015-af84-7b631443df73-300x169.jpg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/12\/622_295c72e3-681f-4015-af84-7b631443df73-550x309.jpg 550w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/12\/622_295c72e3-681f-4015-af84-7b631443df73.jpg 622w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Nunca fomos t\u00e3o intolerantes como em 2017, nunca odiamos tanto quanto em 2017. Opini\u00f5es divergentes viraram ofensas pessoais, ter ideologia diferente ou torcer para clube de futebol diferente viraram declara\u00e7\u00e3o de guerra. Come\u00e7amos o ano achando que as coisas no futebol poderiam mudar com a trag\u00e9dia da Chapecoense. Terminamos com a torcida do Flamengo fazendo vergonha mundial na mesma competi\u00e7\u00e3o em que ocorreu a trag\u00e9dia.<\/p>\n<p style=\"text-align: justify;\">Mas n\u00e3o foram s\u00f3 torcidas de futebol que fizeram vergonha, ela \u00e9 democr\u00e1tica e atinge a todos. Vai da direita, passa pelo centro e vai at\u00e9 a esquerda. \u00c9 bom &#8216;j\u00e1 ir&#8221; se acostumando que a tend\u00eancia em 2018 \u00e9 que piore por ter elei\u00e7\u00f5es. A esquerda tem seus bandidos de estima\u00e7\u00e3o e a direita elegeu falsos her\u00f3is com frases recheadas de clich\u00eas.\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-47135 alignright\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/10\/Frota.jpg\" alt=\"\" width=\"196\" height=\"258\" \/><\/p>\n<p style=\"text-align: justify;\">Vivemos um ano em que Alexandre Frota virou refer\u00eancia de pensamentos e que, apenas para mantermos fama de liberais, achamos normal crian\u00e7as tocarem em homens adultos pelados. N\u00e3o, n\u00e3o posso achar isso estranho ou n\u00e3o salutar porque sou de esquerda e minha ideologia \u00e9 mais importante que meu pensamento. N\u00e3o, n\u00e3o posso achar que um cara que foi preso com pinho sol possa ser solto porque sou de direita e minha ideologia \u00e9 mais importante que meu pensamento.<\/p>\n<p style=\"text-align: justify;\">Rafael Braga est\u00e1 preso, mas quem matou os pais e enteada recebeu indulto de Natal. O Bruno tamb\u00e9m chegou a ser solto e at\u00e9 fotos com f\u00e3s tirou. Pol\u00edticos foram presos, empres\u00e1rios tamb\u00e9m, mas quem tem padrinho n\u00e3o morre pag\u00e3o, ainda mais se foi padrinho em casamento. Gilmar Mendes foi o melhor laxante de 2017, soltou tudo que p\u00f4de.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-46934 alignleft\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/09\/Temerelectroot-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/09\/Temerelectroot-300x200.jpg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/09\/Temerelectroot.jpg 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Cabral continua preso, Garotinho visitou a cadeia algumas vezes, Maluf est\u00e1 l\u00e1, Lula ainda n\u00e3o sabemos e Temer por enquanto n\u00e3o tem nada a temer mesmo sendo pego em grava\u00e7\u00f5es constrangedoras. Querem nos convencer que o pa\u00eds est\u00e1 melhor com ele, mas n\u00e3o \u00e9 isso que o dia a dia mostra. O fracasso do \u00faltimo governo do PT aliado \u00e0 ascens\u00e3o do Temer provocaram esse \u00f3dio que vemos por a\u00ed.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o \u00e9 mimimi se defender do \u00f3dio, assim como n\u00e3o \u00e9 vitimiza\u00e7\u00e3o reclamar dele. Vivemos um tempo esquisito em que a culpa \u00e9 da v\u00edtima, n\u00e3o do agressor. Parece simples perceber que se cada um cuidar exclusivamente de sua vida isso cessa, mas o ser humano \u00e9 buro demais pra perceber.<\/p>\n<p style=\"text-align: justify;\">Matamos e morremos na viol\u00eancia do dia a dia que cada vez cresce mais, nos matamos por religi\u00e3o, ideologia e n\u00e3o respeitamos o pr\u00f3ximo. A internet deu vaz\u00e3o aos idiotas t\u00e3o propagados por Nelson Rodrigues que um dia dominariam o mundo. Dominam atrav\u00e9s das redes sociais e seu anonimato que serve para proteger covardes;<\/p>\n<p style=\"text-align: justify;\">Assim se ataca a cor alheia, a op\u00e7\u00e3o sexual alheia ou o sexo a que pertence. O ano de 2017 nos trouxe doen\u00e7as que pens\u00e1vamos estar perto da erradica\u00e7\u00e3o como homofobia, machismo, racismo e principalmente, nazismo. O pensamento da tal ra\u00e7a se achar superior a outras n\u00e3o \u00e9 mais visto com tanto nojo e para alguns \u00e9 at\u00e9 aceit\u00e1vel.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-45414 alignleft\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/03\/acidentetijuca2017-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/03\/acidentetijuca2017-300x200.jpg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/03\/acidentetijuca2017-510x340.jpg 510w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2017\/03\/acidentetijuca2017.jpg 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Assim como virou aceit\u00e1vel um prefeito colocar sua religi\u00e3o acima dos interesses de uma cidade, assim como virou aceit\u00e1vel ter morte em desfile na Marqu\u00eas de Sapuca\u00ed. O sambista n\u00e3o merecia Marcelo Crivella, quem comanda o samba sim. No Rio de Janeiro o samba atravessou de v\u00e1rias formas. O carioca entristeceu em 2017 ao ver que seus sonhos de uma cidade melhor se apagaram junto com a pira ol\u00edmpica.<\/p>\n<p style=\"text-align: justify;\">H\u00e1 esperan\u00e7as para n\u00f3s em 2018? Sim at\u00e9 porque se n\u00e3o tivermos esperan\u00e7as \u00e9 melhor nem viver e apesar de tudo viver \u00e9 muito bom.<\/p>\n<p style=\"text-align: justify;\">Pode piorar, mas pode melhorar e, acreditem, esse futuro passa pela gente. Que em 2018 a gente possa voltar a sorrir e odiar menos.<\/p>\n<p style=\"text-align: justify;\">Feliz ano novo amigos<\/p>\n<p style=\"text-align: justify;\">Twitter &#8211; @aloisiovillar<\/p>\n<p style=\"text-align: justify;\">Facebook &#8211; Aloisio Villar<\/p>\n<p>[related_posts limit=&#8221;3&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E acabou 2017. Coube a mim o \u00faltimo post do blog no \u00faltimo dia do ano, e lembro que nessa \u00e9poca em 2016 implor\u00e1vamos porTour Details<\/p>\n","protected":false},"author":8,"featured_media":47581,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[18,682,37,27,549],"class_list":["post-47580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orun-aye","tag-carnaval","tag-cotidiano","tag-futebol","tag-sociedade","tag-violencia"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/47580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=47580"}],"version-history":[{"count":1,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/47580\/revisions"}],"predecessor-version":[{"id":47582,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/47580\/revisions\/47582"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media\/47581"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=47580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=47580"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=47580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}