{"id":40123,"date":"2016-02-09T16:09:53","date_gmt":"2016-02-09T18:09:53","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=40123"},"modified":"2016-02-09T19:50:53","modified_gmt":"2016-02-09T21:50:53","slug":"o-grupo-especial-em-um-paragrafo","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2016\/02\/o-grupo-especial-em-um-paragrafo\/","title":{"rendered":"O Grupo Especial em Um Par\u00e1grafo"},"content":{"rendered":"<p style=\"text-align: justify;\">Antes de mais nada, pe\u00e7o desculpas aos leitores pela aus\u00eancia de v\u00eddeo comentando a segunda feira do Especial. Eu n\u00e3o tinha a menor condi\u00e7\u00e3o emocional de fazer qualquer coisa ap\u00f3s o desfile da Portela. Mas vamos em frente.<\/p>\n<p style=\"text-align: justify;\">A ideia aqui \u00e9 resumir em um par\u00e1grafo o 2016 das escolas do Grupo Especial. N\u00e3o necessariamente projetar resultado ou algo parecido, mas sim estabelecer r\u00e1pidos &#8220;flashes&#8221; do que foi este 2016 para cada escola. Uma a uma, vamos l\u00e1:<\/p>\n<p style=\"text-align: justify;\"><strong>1 &#8211; Est\u00e1cio de S\u00e1<\/strong>: a escola fez o suficiente a meu ver para se manter no Grupo Especial. Mas ficou claro para mim que faltou um samba um pouco melhor para tornar esta senten\u00e7a incontest\u00e1vel. E havia op\u00e7\u00f5es melhores durante o processo.<\/p>\n<p style=\"text-align: justify;\"><strong>2 &#8211; Uni\u00e3o da Ilha<\/strong>: o desfile s\u00f3 coroou um ano repleto de equ\u00edvocos, principalmente de sua dire\u00e7\u00e3o executiva. Ao menos, como diria aquele jornalista esportivo, &#8220;ferimentos leves&#8221;: a escola ter\u00e1 a chance de recome\u00e7ar para 2017. E com seus componentes felizes como mostraram no desfile.<\/p>\n<p style=\"text-align: justify;\"><strong>3 &#8211; Beija Flor<\/strong>: mostrou a corre\u00e7\u00e3o habitual, mas aquele &#8220;4-5-1&#8221; retrancado em busca do resultado como sempre. Pensar um pouco menos em resultado e um pouco mais no carnaval enquanto institui\u00e7\u00e3o faria bem \u00e0 escola e ao espet\u00e1culo.<\/p>\n<p style=\"text-align: justify;\"><strong>4 &#8211; Grande Rio:<\/strong> a escola precisa ficar fora do s\u00e1bado das Campe\u00e3s. \u00c9 outra agremia\u00e7\u00e3o que vem apostando em um modelo de resultados &#8211; s\u00f3 que estes n\u00e3o v\u00eam. Para pensar.<\/p>\n<p style=\"text-align: justify;\"><strong>5 &#8211; Mocidade:<\/strong> Equ\u00edvoco total. A escola parece totalmente perdida. Merece e precisa ser contemplada com o rebaixamento &#8211; mas duvido que isso ocorra.<\/p>\n<p style=\"text-align: justify;\"><strong>6 &#8211; Tijuca:<\/strong> mais uma que desfilou com o regulamento debaixo do bra\u00e7o, mas retomou a tradi\u00e7\u00e3o de bons sambas. Precisa manter.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/2016\/02\/o-grupo-especial-em-um-paragrafo\/20160208_221927\/\" rel=\"attachment wp-att-40125\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40125\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/02\/20160208_221927-550x309.jpg\" alt=\"20160208_221927\" width=\"550\" height=\"309\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/02\/20160208_221927-550x309.jpg 550w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/02\/20160208_221927-300x169.jpg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2016\/02\/20160208_221927-768x432.jpg 768w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>7 &#8211; Vila Isabel<\/strong>: a escola sabe e gosta de fazer enredos com tem\u00e1ticas pol\u00edtica e de resist\u00eancia popular. E quando a escola est\u00e1 feliz consigo mesma tudo flui melhor. E Andr\u00e9 Diniz \u00e9 g\u00eanio!<\/p>\n<p style=\"text-align: justify;\"><strong>8 &#8211; Salgueiro:<\/strong> n\u00e3o irei cair no lugar comum de que a agremia\u00e7\u00e3o teria sentido o favoritismo. Um \u00f3timo desfile com alguns probleminhas que podem ocorrer a qualquer um. O caminho \u00e9 esse &#8211; especialmente em samba de enredo.<\/p>\n<p style=\"text-align: justify;\"><strong>9 &#8211; S\u00e3o Clemente<\/strong>: eu avisei l\u00e1 atr\u00e1s no Bar Apoteose que a escola sentiria o peso de vir ensanduichada entre Salgueiro e Portela. A agremia\u00e7\u00e3o sentiu.<\/p>\n<p style=\"text-align: justify;\"><strong>10 &#8211; Portela:<\/strong> os humilhados ser\u00e3o exaltados. Sem mais.<\/p>\n<p style=\"text-align: justify;\"><strong>11 &#8211; Imperatriz:<\/strong> nunca \u00e9 f\u00e1cil vir ap\u00f3s um desfile apote\u00f3tico como foi o da Portela, mas claramente a escola precisa evoluir em termos pl\u00e1sticos. E isso passa por um novo carnavalesco. Por outro lado, acertos em puxador e bateria.<\/p>\n<p style=\"text-align: justify;\"><strong>12 &#8211; Mangueira<\/strong>: quesito a quesito n\u00e3o foi desfile para t\u00edtulo, talvez nem fique entre as tr\u00eas, mas este 2016 marca a retomada e a volta da Velha Companheira ao caminho e ao lugar que sempre foi seu. Me lembra o momento que a Portela come\u00e7ou a viver em 2012.<\/p>\n<p><iframe loading=\"lazy\" title=\"Bateria da Portela entrando no Setor 1 - Desfile 2016\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/7xYpzpo_VTE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de mais nada, pe\u00e7o desculpas aos leitores pela aus\u00eancia de v\u00eddeo comentando a segunda feira do Especial. Eu n\u00e3o tinha a menor condi\u00e7\u00e3o emocionalTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[18,837,19],"class_list":["post-40123","post","type-post","status-publish","format-standard","hentry","category-pedro-migao","tag-carnaval","tag-carnaval-2016","tag-escolas-de-samba"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/40123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=40123"}],"version-history":[{"count":0,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/40123\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=40123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=40123"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=40123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}