{"id":39651,"date":"2016-01-26T08:58:56","date_gmt":"2016-01-26T10:58:56","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=39651"},"modified":"2016-01-26T08:58:56","modified_gmt":"2016-01-26T10:58:56","slug":"videoblog-os-ensaios-tecnicos-do-final-de-semana","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2016\/01\/videoblog-os-ensaios-tecnicos-do-final-de-semana\/","title":{"rendered":"VideoBlog: os Ensaios T\u00e9cnicos do Final de Semana"},"content":{"rendered":"<p style=\"text-align: justify;\">Tivemos um grande fim de semana de ensaios t\u00e9cnicos. No s\u00e1bado Acad\u00eamicos do Cubango, Imp\u00e9rio Serrano e Unidos de Padre Miguel. No domingo Unidos do Viradouro, encerrando a temporada de ensaios da s\u00e9rie A, Unidos da Tijuca e Acad\u00eamicos do Salgueiro. Ensaios de seis agremia\u00e7\u00f5es que brigam por t\u00edtulos no carnaval.<\/p>\n<p style=\"text-align: justify;\">Analisei os seis ensaios, seus defeitos e qualidades, tamb\u00e9m gravei apresenta\u00e7\u00f5es das baterias de Imp\u00e9rio e Salgueiro. S\u00f3 uma corre\u00e7\u00e3o. No v\u00eddeo de s\u00e1bado falo que o enredo da Cubango \u00e9 sobre o mar e \u00e9 sobre as \u00e1guas.<\/p>\n<p style=\"text-align: justify;\"><strong>Bateria do Imp\u00e9rio Serrano<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"Bateria Imp\u00e9rio Serrano 2016\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/lKHwnfb0hRs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\"><strong>An\u00e1lise dos Ensaios de S\u00e1bado<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"An\u00e1lise Cubango, Imp\u00e9rio e Padre Miguel\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/_6J4RF3S7sI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\"><strong>An\u00e1lise dos Ensaios de Domingo<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"An\u00e1lise Viradouro, Tijuca e Salgueiro\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/onqXf3ZQgbc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">Twitter &#8211; @aloisiovillar<\/p>\n<p style=\"text-align: justify;\">Facebook &#8211; Aloisio Villar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tivemos um grande fim de semana de ensaios t\u00e9cnicos. No s\u00e1bado Acad\u00eamicos do Cubango, Imp\u00e9rio Serrano e Unidos de Padre Miguel. No domingo Unidos doTour Details<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[815],"tags":[18,837,19],"class_list":["post-39651","post","type-post","status-publish","format-standard","hentry","category-podcast","tag-carnaval","tag-carnaval-2016","tag-escolas-de-samba"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/39651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=39651"}],"version-history":[{"count":0,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/39651\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=39651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=39651"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=39651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}