{"id":37023,"date":"2015-09-06T10:21:20","date_gmt":"2015-09-06T13:21:20","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=37023"},"modified":"2015-09-03T09:48:13","modified_gmt":"2015-09-03T12:48:13","slug":"a-midia-do-seculo-xxi","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2015\/09\/a-midia-do-seculo-xxi\/","title":{"rendered":"A m\u00eddia do s\u00e9culo XXI"},"content":{"rendered":"<p style=\"text-align: justify;\">No come\u00e7o da semana passada estreamos o programa \u201cBar Apoteose\u201d. Vem a ser um programa do canal \u201cBar Apoteose\u201d, parceiro do Ouro de Tolo, que transmitir\u00e1 ao vivo nas segundas-feiras debate sobre carnaval com alguns dos integrantes do blog e convidados. Ser\u00e1 retransmitido por algumas webradios e amanh\u00e3 mesmo tem outra edi\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">\u00c9 mais um ve\u00edculo para se discutir como tantos que surgiram ao longo desse s\u00e9culo. O nosso blog n\u00e3o \u00e9 especialista, mas vive intensamente a folia principalmente em sua proximidade ou na pr\u00f3pria. Temos sites especializados como \u201cSRZD\u201d no qual trabalho e o \u201cCarnavalesco\u201d, grandes empresas hoje em dia. Temos a \u201cR\u00e1dio Arquibancada\u201d e a \u201cR\u00e1dio A\u00e7\u00e3o\u201d dominando a faixa das r\u00e1dios voltadas para a internet, outras surgem como a \u201cSambista.com\u201d (Tamb\u00e9m trabalho nela). Temos ainda em plena atividade sites pioneiros como \u201cGaleria do Samba\u201d, \u201cApoteose on Line\u201d e \u201cObatuque.com\u201d (Tamb\u00e9m trabalho nesse. Acho que ando trabalhando muito).<\/p>\n<p style=\"text-align: justify;\">Nosso \u201cBar Apoteose\u201d acredito que seja o primeiro voltado ao youtube e com transmiss\u00e3o ao vivo. Mais um campo que o carnaval chega.<\/p>\n<p style=\"text-align: justify;\">Nunca existiu uma m\u00eddia t\u00e3o forte em rela\u00e7\u00e3o a carnaval tanto que um desses expoentes, Anderson Baltar, agora ministra aulas sobre o tema. Penso como era antigamente e vejo como as coisas mudaram.<\/p>\n<p style=\"text-align: justify;\">Sou da gera\u00e7\u00e3o anos 80. Era uma dificuldade enorme saber not\u00edcias de carnaval naquela \u00e9poca. Lembro da ansiedade que me tomava quando se aproximava dezembro e finalmente teria acesso aos sambas, especialmente da minha escola Uni\u00e3o da Ilha. S\u00f3 viv\u00edamos carnaval de dezembro a fevereiro gra\u00e7as ao Chacrinha que levava todas as escolas e a Rede Manchete que fazia programas especiais.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o tinha ensaios t\u00e9cnicos, n\u00e3o tinha sites, webradio, nada disso. Carnaval acabava e para nosso desespero o tema tamb\u00e9m. Viv\u00edamos um tempo de luto e depois segu\u00edamos a vida deixando o assunto carnaval de lado.<\/p>\n<p style=\"text-align: justify;\">Foi assim at\u00e9 a chegada da internet e a percep\u00e7\u00e3o que o samba teve que poderia utiliz\u00e1-lo. No fim dos anos 90 chegaram os primeiros sites e as listas de discuss\u00e3o que existem at\u00e9 hoje. As lend\u00e1rias \u201cRio carnaval\u201d e \u201cAcademia do Samba\u201d que fizeram muitas amizades e revelaram diversas pessoas que hoje militam ativamente no samba. Depois surgiram listas como a \u201cPlaneta samba\u201d e a \u201cMonarcas do samba\u201d na qual perten\u00e7o com orgulho at\u00e9 hoje.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/08\/20150221_233315.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-36386 alignleft\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/08\/20150221_233315-300x169.jpg\" alt=\"20150221_233315\" width=\"300\" height=\"169\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/08\/20150221_233315-300x169.jpg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/08\/20150221_233315-550x309.jpg 550w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Finalmente com a internet tivemos a oportunidade de falar o ano inteiro de samba sem parecermos malucos. Os sambistas da nova era souberam aproveitar bem as redes sociais. Sempre digo que os compositores de hoje, mesmo os que perdem, s\u00e3o mais conhecidos que os antigos gra\u00e7as a possibilidade de demonstra\u00e7\u00e3o e repercuss\u00e3o de suas obras. Seus sambas s\u00e3o executados nos sites e os clips (Nova tend\u00eancia) facilmente encontrados no youtube. Compositores como Paulinho Direito, que nunca passaram da primeira fase de um concurso, s\u00e3o mais famosos que a maioria dos compositores dos anos 60, 70 e 80.<\/p>\n<p style=\"text-align: justify;\">Sambista hoje \u00e9 celebridade. Da entrevistas, faz ensaio sensual, abre sua casa e conta o segredo da boa forma. Temos in\u00fameras m\u00eddias de carnaval e como a m\u00eddia \u201cnormal\u201d ela tem todas as tend\u00eancias. Tem a m\u00eddia festiva, a chapa branca, a de futilidades, a informativa, a \u201cdo contra\u201d, enfim, para todos os gostos. A porta bandeira descobriu que pode ser gata e posar de biquini na praia, o passista que pode virar modelo e fazer propaganda de marcas voltadas ao carnaval. A folia descobriu a m\u00eddia e por consequ\u00eancia o business.<\/p>\n<p style=\"text-align: justify;\">Caso curioso esse porque nunca existiu uma m\u00eddia t\u00e3o forte de carnaval e nunca o carnaval esteve t\u00e3o fora da m\u00eddia. Carnaval virou gueto, parte de um nicho e essa m\u00eddia especializada acabou, sem querer, servindo para isso. Ao mesmo tempo em que ela descobre o fil\u00e3o a grande m\u00eddia lhe esquece. Nunca o sambista foi t\u00e3o famoso entre os seus e nunca t\u00e3o desconhecido fora.<\/p>\n<p style=\"text-align: justify;\">A porta bandeira posa de biquini, o passista de modelo, o cantor abre sua casa, mas nenhum deles \u00e9 conhecido fora do samba. Como eu disse uma vez, Paulo Barros \u00e9 hoje o \u00fanico profissional voltado exclusivamente para o carnaval que \u00e9 reconhecido no \u201cBarra Shopping\u201d.<\/p>\n<p style=\"text-align: justify;\">Muito curioso isso e a causa passa por uma s\u00e9rie de situa\u00e7\u00f5es que exigem outras colunas.<\/p>\n<p style=\"text-align: justify;\">O caso \u00e9 que o carnaval que \u00e9 t\u00e3o retr\u00f3grado e atrasado em v\u00e1rios pontos nesse caso foi \u00e1gil e percebeu rapidamente que a m\u00eddia mudou. Agora \u00e9 poss\u00edvel alcan\u00e7ar seu p\u00fablico, passar informa\u00e7\u00f5es sem precisar da grande m\u00eddia.<\/p>\n<p style=\"text-align: justify;\">A internet \u00e9 veloz, as redes sociais ferozes. Internet n\u00e3o precisa publicar algo para sair no dia seguinte. N\u00e3o precisa ir a um est\u00fadio gravar. Muitas vezes basta uma webcam, um blog e o enter. \u00c9 mais r\u00e1pida e mais barata. Como \u00e9 mais barata n\u00e3o precisa seguir tantos interesses para lucrar, como n\u00e3o precisa seguir tantos interesses para lucrar tem menos \u201crabo preso\u201d.<\/p>\n<p style=\"text-align: justify;\">E a\u00ed entro em outro assunto, mas que tem a ver.<\/p>\n<p style=\"text-align: justify;\">O carnaval foi mais r\u00e1pido, por exemplo, que a grande m\u00eddia. A mesma ainda n\u00e3o reparou que as coisas mudaram, o mundo mudou e as pessoas n\u00e3o precisam mais tanto dela. Existe a facilidade da comunica\u00e7\u00e3o. Facilidade de buscar informa\u00e7\u00f5es e informa\u00e7\u00f5es independentes. Coisa que ela n\u00e3o sabe fazer.<\/p>\n<p style=\"text-align: justify;\">Presa em velhos v\u00edcios, interesses e ideologias a grande m\u00eddia agoniza e faz demiss\u00e3o em massa. Na \u00faltima semana muitos jornalistas perderam seus empregos. Grandes nomes, com anos de casa receberam o \u201cbilhete azul\u201d. A grande m\u00eddia percebe de um jeito duro que o p\u00fablico n\u00e3o se deixa enganar mais t\u00e3o f\u00e1cil e aumentou seu grau de exig\u00eancia com velocidade e informa\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">A m\u00eddia tem que se reinventar. A m\u00eddia do s\u00e9culo XXI talvez seja essa que o carnaval descobriu e trabalha t\u00e3o bem. \u00c9 nicho? \u00c9, mas \u00e9 um nicho satisfeito com as informa\u00e7\u00f5es que recebe e n\u00e3o importa o s\u00e9culo. Cliente satisfeito \u00e9 cliente fiel.<\/p>\n<p style=\"text-align: justify;\">Essa \u00e9 a manchete de hoje.<\/p>\n<p style=\"text-align: justify;\">A de amanh\u00e3 \u00e9 que tem \u201cBar Apoteose\u201d \u00e0s 20h30.<\/p>\n<p style=\"text-align: justify;\">Twitter &#8211; @aloisiovillar<\/p>\n<p style=\"text-align: justify;\">Facebook \u2013 Aloisio Villar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No come\u00e7o da semana passada estreamos o programa \u201cBar Apoteose\u201d. Vem a ser um programa do canal \u201cBar Apoteose\u201d, parceiro do Ouro de Tolo, queTour Details<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[1038,565,430,1036,1037],"class_list":["post-37023","post","type-post","status-publish","format-standard","hentry","category-orun-aye","tag-bar-apoteose","tag-internet","tag-midia","tag-sites","tag-webradio"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/37023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=37023"}],"version-history":[{"count":0,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/37023\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=37023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=37023"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=37023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}