{"id":35273,"date":"2015-06-07T09:24:41","date_gmt":"2015-06-07T12:24:41","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=35273"},"modified":"2015-06-05T16:02:35","modified_gmt":"2015-06-05T19:02:35","slug":"um-gesto-de-amor","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2015\/06\/um-gesto-de-amor\/","title":{"rendered":"Um gesto de amor"},"content":{"rendered":"<p style=\"text-align: justify;\">A pol\u00eamica da semana no pa\u00eds das pol\u00eamicas veio do comercial do Botic\u00e1rio para o dia dos namorados.\u00a0Nada demais, v\u00e1rios casais de namorados trocando presentes, se abra\u00e7ando e entre eles casais gays.<\/p>\n<p style=\"text-align: justify;\">No pa\u00eds chato, de direita e conservador em que vivemos hoje isso \u00e9 pior que esfaquear algu\u00e9m.<\/p>\n<p style=\"text-align: justify;\">Que vivemos uma era chata e politicamente correta n\u00f3s sabemos bem, que existe uma onda de conservadorismo guiada por pentecostais tamb\u00e9m; mas a coisa vai al\u00e9m, \u00e9 pior.<\/p>\n<p style=\"text-align: justify;\">Enquanto v\u00edamos esses pastores conservadores falando para seu rebanho apenas ach\u00e1vamos engra\u00e7ado, quando come\u00e7aram a chutar santas, atacar religi\u00f5es africanas e ganhar espa\u00e7o em m\u00eddia come\u00e7amos a nos incomodar. Chegou a hora de nos preocuparmos.<\/p>\n<p style=\"text-align: justify;\">Nos preocupamos a partir do momento que formam um ex\u00e9rcito de hipocrisia e deturpa\u00e7\u00e3o das palavras de Cristo. Se voltam contra os homossexuais de forma odiosa e preconceituosa e esse \u00f3dio vai surtindo efeito.<\/p>\n<p style=\"text-align: justify;\">Surte efeito, apoiado nessa onda de conservadorismo que surgiu ap\u00f3s as trapalhadas do governo PT, quando come\u00e7a a mudar os rumos do pa\u00eds. Atacaram a novela &#8220;Babil\u00f4nia&#8221; da Globo n\u00e3o pelas chantagens, crimes ou coisas do tipo, mas porque duas atrizes trocaram beijo na boca no primeiro cap\u00edtulo.<\/p>\n<p style=\"text-align: justify;\">Esse beijo e a tara da personagem de Gl\u00f3ria Pires que pegava uns tr\u00eas personagens por cap\u00edtulo fizeram com que os evang\u00e9licos come\u00e7assem um boicote em rela\u00e7\u00e3o a novela.<\/p>\n<p style=\"text-align: justify;\">No capital n\u00e3o h\u00e1 espa\u00e7o para a solidariedade. A emissora oficial dos evang\u00e9licos, a Record, evidente, se aproveitou da situa\u00e7\u00e3o e meteu novela b\u00edblica. O SBT continuou com sua faixa infantil &#8211; natural, mas cutucou a novela da Globo dizendo que era a novela da fam\u00edlia.<\/p>\n<p style=\"text-align: justify;\">Como assim? Novela com gays n\u00e3o \u00e9 de fam\u00edlia?<\/p>\n<p style=\"text-align: justify;\">Da Record n\u00e3o se espera nada mesmo, mas de forma ing\u00eanua esperei solidariedade do SBT at\u00e9 porque quem se aproveita de censura e boicote hoje pode ser a v\u00edtima amanh\u00e3. Mas n\u00e3o: a emissoras aderiram a forte campanha contr\u00e1ria e a estrat\u00e9gia deu certo.<\/p>\n<p style=\"text-align: justify;\">A Globo se assustou, os autores fraquejaram e mudaram tudo na novela. A mesma que parecia promissora se transformou em um arremedo, algo sem rumo e foi encurtada.<\/p>\n<p style=\"text-align: justify;\">Como diriam os hip\u00f3critas. Vit\u00f3ria do povo de Deus.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=1_04RSlhQAA<\/p>\n<p style=\"text-align: justify;\">A v\u00edtima agora \u00e9 o Botic\u00e1rio apenas porque insinuou rela\u00e7\u00f5es gays. Come\u00e7aram a tentativa de boicote e do jeito que o Brasil est\u00e1 hoje n\u00e3o duvido que seja bem sucedida.<\/p>\n<p style=\"text-align: justify;\">Vivemos era perigosa. Do fundamentalismo religioso e da hipocrisia. Aqui n\u00e3o temos, ainda, grupos extremistas cortando cabe\u00e7as de pessoas que tem outro tipo de adora\u00e7\u00e3o a Deus, mas j\u00e1 temos espancamento e mortes de gente com outro pensamento sexual. N\u00e3o vejo diferen\u00e7a entre Silas Malafaia e esse pessoal do Estado Isl\u00e2mico.<\/p>\n<p style=\"text-align: justify;\">Um fundamentalismo religioso misturado com ignor\u00e2ncia e hipocrisia, o esporte preferido do Brasil. Gente que t\u00eam amantes, faz monte de coisas por baixo dos panos reclama em redes sociais desse tipo de an\u00fancio, mas l\u00f3gico, dizendo antes de qualquer coisa que n\u00e3o \u00e9 homof\u00f3bico. Assim como o racista diz que n\u00e3o \u00e9 e &#8220;at\u00e9&#8221; tem amigos negros.<\/p>\n<p style=\"text-align: justify;\">O hip\u00f3crita n\u00e3o vai comprar no Botic\u00e1rio, vai boicotar porque n\u00e3o aceita seus filhos vendo esse tipo de comercial na TV. Vai \u00e0 concorrente comprar perfume para mulher e \u00e0 amante.<\/p>\n<p><iframe loading=\"lazy\" title=\"ITAIPAVA - O Ver\u00e3o chegou\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/Xos2z449R4k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">O mesmo pa\u00eds que condena comercial de abra\u00e7os e acha nada demais no machismo extremo e da falta de criatividade dos comerciais de cerveja com o auge sendo daquela que chama a mulher de &#8220;Ver\u00e3o&#8221; lhe tratando como objeto.<\/p>\n<p style=\"text-align: justify;\">\u00c9 incr\u00edvel que tudo isso venha da falta de uma coisa t\u00e3o importante. A falta de amor.<\/p>\n<p style=\"text-align: justify;\">Se Deus existe e acredito que Ele exista, n\u00e3o tenho d\u00favida que a maior de suas inven\u00e7\u00f5es foi o amor. O sentimento puro que une pessoas que muitas vezes nem sabem o porque.<\/p>\n<p style=\"text-align: justify;\">Em vez de brigarmos e cultivarmos o \u00f3dio e a intoler\u00e2ncia dev\u00edamos agradecer todos os dias a Deus pela exist\u00eancia desse sentimento. Falta amor ao mundo e principalmente o amor ao pr\u00f3ximo que resolveria todos os problemas da humanidade.<\/p>\n<p style=\"text-align: justify;\">O amor pede nada em troca, ele j\u00e1 \u00e9 feliz por existir. Onde h\u00e1 amor n\u00e3o h\u00e1 espa\u00e7o para intoler\u00e2ncia, preconceito, viol\u00eancia, humilha\u00e7\u00f5es ou desrespeito. at\u00e9 porque se existe um desses sentimentos em uma pessoa n\u00e3o existe amor.<\/p>\n<p style=\"text-align: justify;\">No amor n\u00e3o h\u00e1 lugar para a maldade at\u00e9 porque o amor traz paz de esp\u00edrito. Quem cultiva amor n\u00e3o se preocupa com a religi\u00e3o do outro ou com quem o outro desenvolve seu amor. Ali\u00e1s o amor de verdade n\u00e3o tem sexo, cor ou credo. Ele \u00e9 universal, onipresente e transparente.<\/p>\n<p style=\"text-align: justify;\">Parece t\u00e3o simples e \u00e9. O ser humano que complica. O amor est\u00e1 presente nas pequenas coisas e por isso \u00e9 t\u00e3o grande.<\/p>\n<p style=\"text-align: justify;\">No dia que usarem de verdade as palavras de Jesus, sem deturpar para aquilo que lhe \u00e9 conveniente a coisa anda.<\/p>\n<p style=\"text-align: justify;\">Quem sabe um dia o abra\u00e7o deixe de ser pol\u00eamico e passe a ser apenas o que ele \u00e9.<\/p>\n<p style=\"text-align: justify;\">Um gesto de amor.<\/p>\n<p style=\"text-align: justify;\">Twitter &#8211; @aloisiovillar<\/p>\n<p style=\"text-align: justify;\">Facebook \u2013 Aloisio Villar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pol\u00eamica da semana no pa\u00eds das pol\u00eamicas veio do comercial do Botic\u00e1rio para o dia dos namorados.\u00a0Nada demais, v\u00e1rios casais de namorados trocando presentes,Tour Details<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[381,948,947,797,790,9,339],"class_list":["post-35273","post","type-post","status-publish","format-standard","hentry","category-orun-aye","tag-amor","tag-boticario","tag-fundamentalismo","tag-intolerancia","tag-novela","tag-religiao","tag-sexo"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/35273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=35273"}],"version-history":[{"count":0,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/35273\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=35273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=35273"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=35273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}