{"id":33856,"date":"2015-03-27T14:39:14","date_gmt":"2015-03-27T17:39:14","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=33856"},"modified":"2015-03-27T13:04:40","modified_gmt":"2015-03-27T16:04:40","slug":"profissao-perigo","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2015\/03\/profissao-perigo\/","title":{"rendered":"Profiss\u00e3o = perigo"},"content":{"rendered":"<p style=\"text-align: justify;\">Sabemos bem que a profiss\u00e3o de t\u00e9cnico de futebol \u00e9 complicada. Bem complicada, ali\u00e1s. Simplesmente n\u00e3o h\u00e1 estabilidade alguma para se desenvolver um trabalho. Tr\u00eas derrotas seguidas quase sempre s\u00e3o garantia apenas de demiss\u00e3o.<\/p>\n<p style=\"text-align: justify;\">N\u00e3o s\u00e3o levados\u00a0em conta uma s\u00e9rie de fatores: politicagem interna nos clubes, elencos limitados, falta de recursos mesmo em clubes grandes, atrasos de sal\u00e1rios ou at\u00e9 mesmo conluios internos em grupos que n\u00e3o aceitam determinadas medidas disciplinares.<\/p>\n<p style=\"text-align: justify;\">E, nesse ambiente de salve-se quem puder, estoura quase sempre no treinador. N\u00e3o que os t\u00e9cnicos muitas vezes n\u00e3o cometam erros estrat\u00e9gicos ou de substitui\u00e7\u00f5es ou escala\u00e7\u00f5es. Mas em vez de se tomarem medidas mais significativas numa engrenagem complexa que \u00e9 um time de futebol, tira-se apenas uma pe\u00e7a: o t\u00e9cnico.<\/p>\n<p style=\"text-align: justify;\">Nesse vaiv\u00e9m de t\u00e9cnicos, temos visto cada vez mais que a sa\u00fade desses profissionais tem ficado prejudicada. Que eu me lembre, Joel Santana, Oswaldo de Oliveira, Ricardo Gomes, Guto Ferreira, Ant\u00f4nio Lopes\u00a0e\u00a0Van Basten tiveram problemas diretamente ligados a estresse. Que, n\u00e3o tenho d\u00favidas, vem do futebol.<\/p>\n<p style=\"text-align: justify;\">Mas nenhum caso me chama mais a aten\u00e7\u00e3o do que o de Muricy Ramalho. Outro dia estava editando um VT para o T\u00e1 na \u00c1rea sobre o treinador e, na pesquisa de imagens, fiquei assustado como o t\u00e9cnico &#8220;envelheceu&#8221; em sete, oito anos&#8230; (vejam na foto que abre o post).<\/p>\n<p style=\"text-align: justify;\">Desnecess\u00e1rio discorrer sobre o curr\u00edculo extraordin\u00e1rio de Muricy Ramalho, campe\u00e3o de tudo (ou praticamente) que disputou. Nesse ano, o S\u00e3o Paulo, \u00e9 fato, n\u00e3o teve um desempenho aceit\u00e1vel nos cl\u00e1ssicos. Mas o time estaria classificado para a sequ\u00eancia do Paulista e da Libertadores no momento em que escrevo.<\/p>\n<p style=\"text-align: justify;\">A\u00ed eu me pergunto: Muricy tem culpa que o Rog\u00e9rio Ceni faz besteira e ainda toma um gol quase do meio-campo? (sem tirar, claro, os m\u00e9ritos do palmeirense Robinho) Muricy tem culpa de Ganso outra vez ter tido um desempenho ap\u00e1tico em campo? Muricy tem culpa de Luis Fabiano outra vez passar em branco num jogo importante?<\/p>\n<p style=\"text-align: justify;\">Recentemente, o Fluminense dispensou Crist\u00f3v\u00e3o Borges depois de um empate com o Tigres no qual o Tricolor foi prejudicado pela arbitragem e deveria ter vencido. Crist\u00f3v\u00e3o tem culpa disso? Crist\u00f3v\u00e3o tem culpa de o clube ter perdido um punhado significativo de jogadores ap\u00f3s o fim da parceria com a Unimed?<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/03\/oswaldogabriel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-33858 size-medium alignleft\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/03\/oswaldogabriel-300x221.jpg\" alt=\"oswaldogabriel\" width=\"300\" height=\"221\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/03\/oswaldogabriel-300x221.jpg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/03\/oswaldogabriel-462x340.jpg 462w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2015\/03\/oswaldogabriel.jpg 1092w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>O desabafo\u00a0&#8211;\u00a0at\u00e9 engra\u00e7ado\u00a0&#8211;\u00a0de Oswaldo de Oliveira, sobre a insist\u00eancia de um torcedor ao pedir, ou melhor EXIGIR, Gabri\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9\u00e9lllllll em campo, mostra um simples exemplo do que o treinador tem de aturar no exerc\u00edcio de sua profiss\u00e3o. Oswaldo, como j\u00e1 citei, outro que teve um problema de sa\u00fade recente.<\/p>\n<p style=\"text-align: justify;\">A\u00ed eu te pergunto (como diria Marcelo Rezende): voc\u00ea em seu ambiente de trabalho consegue desenvolver a sua atividade com tanta coisa perturbando, com tantos problemas estruturais em volta, ou com tanta gente jogando contra? N\u00e3o, definitivamente.<\/p>\n<p style=\"text-align: justify;\"><em>&#8220;Ah, mas o t\u00e9cnico de futebol ganha uma grana preta&#8221;<\/em>, voc\u00ea pode dizer. Sim, fato, existem distor\u00e7\u00f5es no mercado. Mas um equ\u00edvoco n\u00e3o justifica o outro, e est\u00e1 claro que os t\u00e9cnicos de futebol precisam de um ambiente mais adequado para trabalhar. Mais um problema no futebol do 7 a 1.<\/p>\n<p style=\"text-align: justify;\">Para encerrar, Muricy chegou a entregar o cargo depois da derrota para o Palmeiras, mas a diretoria o demoveu da ideia. Sinceramente lamentei profundamente quando li isso. N\u00e3o porque ache que ele esteja fazendo um bom ou mau trabalho. Mas porque Muricy claramente n\u00e3o est\u00e1 bem, e ele tem uma fam\u00edlia. Como todos n\u00f3s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabemos bem que a profiss\u00e3o de t\u00e9cnico de futebol \u00e9 complicada. Bem complicada, ali\u00e1s. Simplesmente n\u00e3o h\u00e1 estabilidade alguma para se desenvolver um trabalho. Tr\u00easTour Details<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[37,4,27,880],"class_list":["post-33856","post","type-post","status-publish","format-standard","hentry","category-sabinadas","tag-futebol","tag-saude","tag-sociedade","tag-tecnicos-de-futebol"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/33856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=33856"}],"version-history":[{"count":0,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/33856\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=33856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=33856"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=33856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}