{"id":26428,"date":"2014-06-05T05:11:50","date_gmt":"2014-06-05T08:11:50","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=26428"},"modified":"2014-08-05T13:21:37","modified_gmt":"2014-08-05T16:21:37","slug":"pitaco-notas-sobre-a-democracia-parte-i","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2014\/06\/pitaco-notas-sobre-a-democracia-parte-i\/","title":{"rendered":"Pitaco: \u201cNotas sobre a Democracia &#8211; Parte I\u201d"},"content":{"rendered":"<p style=\"text-align: justify\">Neste quarto e \u00faltimo artigo da s\u00e9rie sobre a ditadura, proponho uma reflex\u00e3o sobre seu oposto, a democracia. O que, exatamente, caracteriza um regime democr\u00e1tico? Por que ela estava t\u00e3o fr\u00e1gil na \u00e9poca do golpe? Quais s\u00e3o suas perspectivas hoje, no Brasil e no mundo? O artigo \u00e9 dividido em duas partes: a primeira trata do tema numa perspectiva mais te\u00f3rica; a segunda, amanh\u00e3, tenta examinar alguns dilemas concretos.<\/p>\n<p style=\"text-align: justify\">Comecemos pelos elementos da democracia. Eric Hobsbawm (<em>Globaliza\u00e7\u00e3o, Democracia e Terrorismo<\/em>), como quase sempre, acerta ao dizer que <em>\u201cno discurso p\u00fablico ocidental de hoje falam-se mais bobagens e absurdos sobre a democracia do que sobre qualquer outra palavra ou conceito pol\u00edtico\u201d. <\/em>Os disparates decorrem, em parte, de o termo ser usado no discurso vulgar por pessoas que n\u00e3o dominam seu conceito, ou que o confundem com conceitos diferentes.<\/p>\n<p style=\"text-align: justify\">O n\u00facleo duro da democracia \u00e9 o exerc\u00edcio do poder pol\u00edtico pelo povo, eventualmente de forma direta, mas geralmente por meio de representantes eleitos por sufr\u00e1gio universal. \u00c9 da ess\u00eancia da democracia que os cidad\u00e3os estejam em condi\u00e7\u00e3o de igualdade. \u00c9 comum confundir-se democracia com o <em>liberalismo pol\u00edtico<\/em>, que engloba, entre outras garantias, a liberdade de express\u00e3o, a liberdade religiosa, os direitos civis e a independ\u00eancia entre os poderes.<\/p>\n<p style=\"text-align: justify\">A democracia moderna, simbolizada pelo sufr\u00e1gio universal, surgiu com a Revolu\u00e7\u00e3o Francesa, que n\u00e3o era \u201cliberal\u201d. O liberalismo surgiu na Inglaterra, tendo como marco a Revolu\u00e7\u00e3o Gloriosa, que n\u00e3o era \u201cdemocr\u00e1tica\u201d. Foram duas formas distintas de supera\u00e7\u00e3o do absolutismo mon\u00e1rquico e dos privil\u00e9gios da aristocracia. \u00c9 emblem\u00e1tica a diferen\u00e7a entre Voltaire (liberal, mas n\u00e3o democrata) e Rousseau (democrata, mas n\u00e3o liberal).<\/p>\n<p style=\"text-align: justify\">O regime liberal ingl\u00eas evoluiu, lentamente, para uma democracia, e o regime democr\u00e1tico franc\u00eas evoluiu, com idas e vindas, para o liberalismo. Pode-se dizer que ambos os pa\u00edses, assim como v\u00e1rios outros, t\u00eam hoje uma \u201cdemocracia liberal\u201d, mas \u00e9 preciso sempre levar em conta que democracia e liberalismo pol\u00edtico s\u00e3o culturas com origens e hist\u00f3rias diferentes, e podem perfeitamente existir em separado.<\/p>\n<p style=\"text-align: justify\">Tamb\u00e9m \u00e9 poss\u00edvel haver, como na Alemanha de Bismarck, um <em>estado de direito<\/em>, ou seja a submiss\u00e3o do poder soberano ao imp\u00e9rio da lei, sem que haja necessariamente democracia nem liberalismo.<\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2014\/06\/acorrentado.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-26430\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2014\/06\/acorrentado-300x207.jpeg\" alt=\"acorrentado\" width=\"300\" height=\"207\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2014\/06\/acorrentado-300x207.jpeg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2014\/06\/acorrentado-490x340.jpeg 490w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2014\/06\/acorrentado.jpeg 635w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Podemos temer que, se o Brasil fosse radicalmente democr\u00e1tico, vale dizer, se a vontade popular sempre prevalecesse, alguns marcos do nosso liberalismo, como a aboli\u00e7\u00e3o da pena de morte, seriam revertidos. Na Am\u00e9rica do Sul, a Col\u00f4mbia \u00e9 o pa\u00eds com a mais longa tradi\u00e7\u00e3o de democracia formal e tamb\u00e9m o campe\u00e3o de atrocidades.<\/p>\n<p style=\"text-align: justify\">\u00c9 controverso se a democracia \u00e9 o melhor regime para garantir o desenvolvimento econ\u00f4mico e os direitos humanos, parecendo mais acertado dizer que sua sobreviv\u00eancia depende da prosperidade e da paz social. Assim como na Rep\u00fablica de Weimar, a vontade da maioria em pa\u00edses importantes na Europa de hoje parece se inclinar para a xenofobia e a intoler\u00e2ncia.<\/p>\n<p style=\"text-align: justify\">De modo geral, h\u00e1 uma inflex\u00e3o antidemocr\u00e1tica no mundo.<\/p>\n<p style=\"text-align: justify\">Para enxergarmos isto, precisamos lembrar que a democracia \u00e9 uma constru\u00e7\u00e3o hist\u00f3rica. Ela se estabeleceu como sistema dominante no ocidente como um instrumento das classes mercantis em ascens\u00e3o, em seu combate contra a nobreza pelo controle das institui\u00e7\u00f5es de Estado. O quadro atual \u00e9 um tanto diferente do se apresentava no s\u00e9culo XIX: a aristocracia rural n\u00e3o possui mais poder heredit\u00e1rio em pa\u00edses avan\u00e7ados, e s\u00e3o as classes mais baixas que agora t\u00eam interesse em aprofundar a democracia, em contraposi\u00e7\u00e3o ao poder natural do empresariado.<\/p>\n<p style=\"text-align: justify\">De modo que conv\u00e9m \u00e0 plutocracia do nosso tempo (se n\u00e3o conscientemente, por intui\u00e7\u00e3o) solapar os instrumentos de representa\u00e7\u00e3o democr\u00e1tica. Isso est\u00e1 longe de ser uma peculiaridade brasileira, podendo ser observado em todo o mundo. A t\u00e1tica mais comum \u00e9 desacreditar a pol\u00edtica eleitoral, difundindo ideias como a de que <em>\u201ctodos os pol\u00edticos s\u00e3o iguais\u201d, \u201ctodos s\u00e3o corruptos\u201d, \u201co Estado \u00e9 ineficiente\u201d<\/em>, etc. N\u00e3o h\u00e1 v\u00e1cuo em pol\u00edtica. Se o Estado \u00e9 desmoralizado e diminu\u00eddo em sua influ\u00eancia social, h\u00e1 de prevalecer outro tipo de poder, notadamente o econ\u00f4mico, heredit\u00e1rio e n\u00e3o submetido ao escrut\u00ednio popular.<\/p>\n<p style=\"text-align: justify\">\u00c9 comum vermos, por exemplo, porta-vozes dos bancos defendendo \u201cautonomia para o presidente do Banco Central\u201d, sob o argumento de que um dirigente de BC submetido \u00e0 autoridade do Presidente da Rep\u00fablica fica exposto a \u201cpress\u00f5es pol\u00edticas\u201d. N\u00e3o \u00e9 dif\u00edcil perceber que a tese encontra maior eco justamente entre os que desacreditam da atividade pol\u00edtico-partid\u00e1ria. E n\u00e3o \u00e9 dif\u00edcil entender que o objetivo dos autonomistas n\u00e3o \u00e9 livrar o Banco Central de press\u00f5es, mas facilitar a press\u00e3o exercida pelos banqueiros, que j\u00e1 \u00e9 fort\u00edssima, e que n\u00e3o poderia mais ser freada pelo poder pol\u00edtico.<\/p>\n<p style=\"text-align: justify\">N\u00e3o h\u00e1 nenhuma raz\u00e3o te\u00f3rica ou emp\u00edrica para acreditarmos que autoridades n\u00e3o eleitas e \u201cindependentes\u201d dos representantes escolhidos pelo povo exer\u00e7am seu mister melhor que as eleitas ou que devam satisfa\u00e7\u00e3o \u00e0 popula\u00e7\u00e3o e seus mandat\u00e1rios. Como a Hist\u00f3ria demonstra, a tecnocracia nunca \u00e9 \u201cneutra\u201d; seus atos s\u00e3o uma fun\u00e7\u00e3o das influ\u00eancias a que est\u00e1 sujeita, e estas podem ser tanto do poder pol\u00edtico quanto do econ\u00f4mico (h\u00e1 ainda outras modalidades de poder, como o religioso, que est\u00e1 em decl\u00ednio). A finalidade da democracia \u00e9 exatamente conter o poder das classes que, por sua posi\u00e7\u00e3o social, exer\u00e7am influ\u00eancia desproporcional.<\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2014\/06\/OBRAS-AYRTON-SENNA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-26431\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2014\/06\/OBRAS-AYRTON-SENNA-300x200.jpg\" alt=\"OBRAS-AYRTON-SENNA\" width=\"300\" height=\"200\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2014\/06\/OBRAS-AYRTON-SENNA-300x200.jpg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2014\/06\/OBRAS-AYRTON-SENNA.jpg 506w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>A segunda t\u00e1tica \u00e9 controlar o pr\u00f3prio Estado e seus agentes de forma a burlar os princ\u00edpios da representa\u00e7\u00e3o. Uma forma eficiente de alcan\u00e7ar este resultado \u00e9 a corrup\u00e7\u00e3o: vista como uma pervers\u00e3o dos pol\u00edticos, esta na verdade se presta de forma pr\u00e1tica ao controle do Estado por aqueles que podem \u201ccomprar\u201d os agentes p\u00fablicos, no caso a plutocracia. Outro m\u00e9todo bem sucedido \u00e9 elevar os custos de financiamento das campanhas a patamares que deixar\u00e3o os pol\u00edticos inevitavelmente dependentes dos potenciais doadores. \u00c9 uma vit\u00f3ria para a democracia que o STF esteja em vias de proibir o financiamento privado de campanhas.<\/p>\n<p style=\"text-align: justify\">Como se v\u00ea, as estrat\u00e9gias mais comuns de sabotagem da democracia passam sempre por alguma forma de minar o princ\u00edpio da igualdade pol\u00edtica, fazendo prevalecer o poder de alguns em detrimento do de outros, ainda que os primeiros sejam minorit\u00e1rios. E fica claro que a capacidade de subverter a l\u00f3gica democr\u00e1tica pertence \u00e0 classe social que det\u00e9m o ativo mais valorizado em nossa era: o capital.<\/p>\n<p style=\"text-align: justify\">A democracia n\u00e3o \u201cfunciona sozinha\u201d. Mais que qualquer outro sistema de governo, depende da dedica\u00e7\u00e3o e da participa\u00e7\u00e3o interessada e vigilante dos cidad\u00e3os. Modelos pol\u00edticos n\u00e3o cumprem uma \u201cevolu\u00e7\u00e3o\u201d em que o ponto de chegada \u00e9 uma democracia cada vez mais sofisticada.<\/p>\n<p style=\"text-align: justify\">Como vimos em 64, nada garante que um regime mais ou menos democr\u00e1tico n\u00e3o possa ser \u201crevertido\u201d a um molde autorit\u00e1rio. E a forma como isto se d\u00e1 n\u00e3o precisa a ser a de um golpe militar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste quarto e \u00faltimo artigo da s\u00e9rie sobre a ditadura, proponho uma reflex\u00e3o sobre seu oposto, a democracia. O que, exatamente, caracteriza um regime democr\u00e1tico?Tour Details<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[349],"tags":[58,35,24],"class_list":["post-26428","post","type-post","status-publish","format-standard","hentry","category-pitaco","tag-economia","tag-historia","tag-politica"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/26428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=26428"}],"version-history":[{"count":0,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/26428\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=26428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=26428"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=26428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}