{"id":16514,"date":"2013-02-15T07:20:56","date_gmt":"2013-02-15T09:20:56","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/?p=16514"},"modified":"2013-02-15T07:21:37","modified_gmt":"2013-02-15T09:21:37","slug":"lacombianas-um-lindo-dia-para-morrer","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2013\/02\/lacombianas-um-lindo-dia-para-morrer\/","title":{"rendered":"Lacombianas &#8211; &#8220;Um lindo dia para morrer&#8221;"},"content":{"rendered":"<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><a href=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/02\/IMG00271-20101009-1320.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-16515\" alt=\"IMG00271-20101009-1320\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/02\/IMG00271-20101009-1320-453x340.jpg\" width=\"453\" height=\"340\" srcset=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/02\/IMG00271-20101009-1320-453x340.jpg 453w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/02\/IMG00271-20101009-1320-300x225.jpg 300w, http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2013\/02\/IMG00271-20101009-1320.jpg 2048w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><\/a><span style=\"color: #000080\">Retomando o curso normal do blog, <strong>a coluna &#8220;Lacombianas&#8221;, da jornalista Milly Lacombe<\/strong>, faz um convite \u00e0 reflex\u00e3o.<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"text-decoration: underline\"><em><strong><span style=\"color: #000080;text-decoration: underline\">Um lindo dia para morrer<\/span><\/strong><\/em><\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Acordei assustado, cora\u00e7\u00e3o batendo apressado e fora de compasso. Em seguida, movido por um estranho impulso, sentei na cama. Estava suando, camiseta colada ao peito, respirando pela boca como se o ar no quarto fosse o do acampamento-base do Everest. Passei a m\u00e3o direita no cabelo e os fios estavam molhados, como ficam sempre que corro mais do que os usuais sete quil\u00f4metros di\u00e1rios. Peguei o celular que deixo na mesinha ao lado da cama e vi que eram cinco e quinze. E ent\u00e3o lembrei de uma mat\u00e9ria que tinha lido h\u00e1 alguns anos e que dizia que a maioria dos infartos acontece nas primeiras horas da manh\u00e3. Era isso ent\u00e3o. Eu estava tendo uma parada card\u00edaca. A idade parecia correta: 39. S\u00e3o os fatais, dizia a mesma mat\u00e9ria. Sem um plano emergencial, e sozinho em casa, tentei chegar ao banheiro, mas minhas pernas n\u00e3o responderam ao impulso. Com o celular nas m\u00e3os n\u00e3o sabia para quem ligar. Os americanos s\u00e3o muito claros numa hora dessas. \u00c9 911 e nada mais. Mas e aqui? Por que n\u00e3o divulgam esse n\u00famero como um mantra? Ligo para a policia? Qual policia se temos duas? Bombeiros? Mas n\u00e3o estou pegando fogo, apesar do suor excessivo. Enquanto pensava freneticamente sem saber que n\u00famero discar, vi a silhueta no canto do quarto.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cQuem est\u00e1 a\u00ed?, perguntei enquanto tentava, ainda ofegante e agora tremendo, alcan\u00e7ar sem sucesso o interruptor do abajur.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cAntes de mais nada, voc\u00ea precisa respirar com calma, como fez naquela aula de ioga h\u00e1 mais de cinco anos\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cQuem \u00e9 voc\u00ea? O que est\u00e1 fazendo no meu quarto? Como entrou aqui?\u201d Minha voz n\u00e3o parecia minha voz. Tomada pelo pavor, ela sa\u00eda fraca e rouca.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cSe voc\u00ea n\u00e3o respirar lentamente n\u00e3o vai ter tempo para as respostas. \u00c9 preciso se acalmar, eu vou falar devagar, e prometo explicar o que der antes de ter que me mandar\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Meus olhos, mais adaptados \u00e0 escurid\u00e3o, podiam v\u00ea-lo melhor. Estava sentado na poltrona que uso para ler \u00e0 noite e colocar os sapatos pela manh\u00e3. Mas, ao contr\u00e1rio do que imaginei, j\u00e1 n\u00e3o parecia mais ser um homem, e sim uma mulher de cabelos curtos ou presos, n\u00e3o dava para saber, e voz firme. As pernas estavam cruzadas, o trinco jogado para tr\u00e1s. A \u00fanica pessoa tensa dentro daquele quarto era eu. Tentei respirar mais pausadamente, mas ainda estava ofegante quando disse:\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cQuem \u00e9 voc\u00ea?\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cVoc\u00ea n\u00e3o me conhece e \u00e9 melhor que continue assim. Pr\u00f3xima pergunta\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cComo entrou aqui?\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cVoc\u00ea deixou a porta dos fundos aberta ontem quando chegou carregado com as compras do supermercado\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cVoc\u00ea \u00e9 homem ou mulher?\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cComo preferir. Isso pouco importa\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cVoc\u00ea vai me roubar? Me matar? Est\u00e1 armada?\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cAh, escolheu que eu fosse uma mulher? Entendo. N\u00e3o, n\u00e3o e n\u00e3o s\u00e3o as respostas\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cO que voc\u00ea est\u00e1 fazendo aqui?\u201d. Minha voz estava mais calma agora. A respira\u00e7\u00e3o tinha voltado a um ritmo aceit\u00e1vel e eu conseguia v\u00ea-la um pouco melhor. Estava vestida com uma cal\u00e7a branca, uma camiseta bege, chinelos de dedo e o cabelo n\u00e3o era nem curto, nem estava preso: agora me parecia bastante preto, longo e cacheado.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cEstava zanzando pela cidade, meio entediada, e lembrei da porta aberta. Decidi dar um tempo por aqui, mas voc\u00ea acordou logo, n\u00e3o tive tempo de sair e c\u00e1 estamos\u201d.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cComo sabe que fiz uma aula de ioga h\u00e1 alguns anos?\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201c\u00c9 meu trabalho estar informada\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cQuem \u00e9 voc\u00ea?\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cVamos deixar isso pra l\u00e1. Meu tempo est\u00e1 acabando. Fa\u00e7a as perguntas certas e ter\u00e1 as respostas certas\u201d.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cEstou morrendo?\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cEst\u00e1. Todos na Terra est\u00e3o\u201d.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cEstou morrendo agora? Nesta manh\u00e3?\u201d, perguntei j\u00e1 sem paci\u00eancia;\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cMais ou menos\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cChega desse tipo de resposta idiota\u201d, gritei tentando outra vez alcan\u00e7ar o interruptor para acender o abajur e v\u00ea-la melhor. Outra vez, n\u00e3o consegui antes que ela e sua voz grossa voltassem a mim.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cGritar n\u00e3o vai levar a gente a lugar nenhum e ainda vai acelerar seu cora\u00e7\u00e3o outra vez\u201d, ela disse, ainda muito calma. \u201cVou tentar explicar. N\u00e3o existe apenas uma morte. Existem muitas mortes. Hoje voc\u00ea vai morrer uma delas. Entendeu?\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cClaro que n\u00e3o entendi\u201d, disse tentando levantar da cama e percebendo que minhas pernas ainda n\u00e3o reagiam. \u201cQue muitas mortes s\u00e3o essas? Vidas depois da morte? Do que voc\u00ea t\u00e1 falando?\u201d, perguntei tirando com for\u00e7a o len\u00e7o de cima de mim porque o quarto estava ficando estupidamente quente.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cEstou falando de conseguir mudar sua vida. Morrer para ela at\u00e9 aqui, e come\u00e7ar outra. Emprego, cren\u00e7as, conceitos, rela\u00e7\u00f5es. \u00c9 disso que estou falando. \u00c9 o que voc\u00ea vai fazer quando sair do hospital.\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cQue hospital?\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cAquele para onde est\u00e1 indo\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cN\u00e3o estou indo a lugar nenhum\u201d, gritei furioso jogando o len\u00e7ol ainda mais para o canto. E foi quando senti a dor aguda no peito. Sufocante, angustiante.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cViu? Est\u00e1 sim. Em menos de um minuto voc\u00ea pegar\u00e1 o telefone e discar\u00e1 para sua m\u00e3e. Sua voz n\u00e3o vai sair, e ela entender\u00e1 tudo, porque m\u00e3es entendem tudo, e ligar\u00e1 para a pol\u00edcia. Ali\u00e1s, o n\u00famero \u00e9 190, que fique como refer\u00eancia futura. Sua m\u00e3e sabe disso e discar\u00e1 190. Uma ambul\u00e2ncia vir\u00e1 buscar voc\u00ea, que, dentro dela, ser\u00e1 reanimado duas vezes antes de voltar a respirar\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Deitado, eu j\u00e1 n\u00e3o conseguia falar. Peguei o telefone e disquei para minha m\u00e3e. Depois disso, pude v\u00ea-la sair da cadeira e vir em minha dire\u00e7\u00e3o. Como era alta\u2026 Ela se sentou na cama, perto de meus joelhos, e colocou a m\u00e3o em minha testa.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cEssa \u00e9 a primeira morte\u201d, disse baixinho, com a boca bem perto de meu ouvido esquerdo. \u201cHaver\u00e1 mais uma antes da derradeira. Acontece com todo mundo nesse planeta. Voc\u00ea tem a sorte de ter a sua bem demarcada: uma parada card\u00edaca. Muita gente n\u00e3o tem essa sorte e n\u00e3o entende quando a primeira morte chega. Mas o fato \u00e9 que todos t\u00eam direito a duas mortes antes da partida. Eu acho isso bacana, sabe?\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Ela ia falando como se eu n\u00e3o estivesse morrendo bem na sua frente. Minha voz n\u00e3o sa\u00eda mais, e eu sentia meu corpo r\u00edgido, travado, preso ao colch\u00e3o. Por que ela n\u00e3o me ajudava e continuava ali falando coisas sem sentido? Meu cora\u00e7\u00e3o batia de um jeito assustador.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cMas n\u00e3o fui eu que inventei isso. J\u00e1 nem sei mais quem foi. Quando assumi esse posto era assim e eu n\u00e3o mudei, nem sei se teria autonomia para mudar, te digo a verdade. A ambul\u00e2ncia chegar\u00e1 em sete minutos, e em oito seu cora\u00e7\u00e3o vai parar de bater pela primeira vez. Ent\u00e3o ainda temos um tempinho. O que mais quer saber?\u201d\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Eu n\u00e3o conseguia falar, ser\u00e1 que ela n\u00e3o via isso? Tinha mais um milh\u00e3o de perguntas, mas n\u00e3o conseguia falar, eu estava morrendo diante de uma mulher de voz grossa e cabelos encaracolados, estranha e enorme, que permanecia imp\u00e1vida sentada a meus p\u00e9s.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cEu sei, a voz n\u00e3o sai. Ent\u00e3o vou falar o que acho que voc\u00ea quer saber. Vou dizer quem eu n\u00e3o sou. N\u00e3o sou Deus. Mas trabalho para ela. N\u00e3o diretamente, digamos que sou terceirizada. Tem muito trabalho e ela n\u00e3o estava dando conta de tudo s\u00f3 com um time. Ent\u00e3o a gente veio ajudar. Mas isso aqui que eu estou fazendo n\u00e3o \u00e9 permitido, eu provavelmente serei multada. Voc\u00ea n\u00e3o poderia ter me visto, entende? Mas eu estava cansada e me sentei naquela cadeira e marquei touca quando voc\u00ea acordou. Paci\u00eancia. J\u00e1 que estou aqui, agora vou te fazer companhia at\u00e9 os param\u00e9dicos chegarem. Ent\u00e3o, como estava dizendo, ou acho que estava dizendo, j\u00e1 nem sei mais, mas o fato \u00e9 que voc\u00ea precisa mudar. Ioga, pilates, alimenta\u00e7\u00e3o regrada, mais \u00e1gua, menos alcool, blablabl\u00e1, claro que todo isso importa, mas n\u00e3o \u00e9 disso que estou falando. Estou falando das coisas grandes. T\u00f4 falando de atitudes, entende? Eu sei, n\u00e3o precisa tentar responder. Vou dar exemplos pr\u00e1ticos. O primeiro: por que voc\u00ea n\u00e3o foi visitar sua m\u00e3e no domingo passado se voc\u00ea disse que ia? Ela ficou esperando, sabia? Fez almo\u00e7o e tudo. E voc\u00ea ligou apenas no fim do dia para dizer que n\u00e3o tinha dado para ir. Isso \u00e9 chato, isso que n\u00e3o pode, sabe? E por que n\u00e3o foi a casa de sua irm\u00e3 quando ela se separou? Por que nunca tocou nesse assunto com ela? Por que continua a julgar o fato de ela ter se apaixonado por outro e terminado o casamento? Preferia que ela continuasse casada e infeliz? E j\u00e1 que estamos nesses assuntos pentelhos, por que voc\u00ea continua a trafegar pelo acostamento quando o tr\u00e2nsito na estrada est\u00e1 carregado? E por que para em fila dulpa na rua? Por que n\u00e3o l\u00ea um livro, ali\u00e1s? Fica s\u00f3 nesse neg\u00f3cio de Facebook e Twitter. Voc\u00ea lia tanto quando era um moleque\u2026 \u00c9 preciso continuar aprendendo, sabe? Sempre aprendendo. Esses detalhes \u00e9 que formam o que eu chamo de coisas grandes, entende? Vou ser mais clara: voc\u00ea \u00e9 um d\u00e2ndi ego\u00edsta-machista-orgulhoso. \u00c9 isso, basicamente. Uma tr\u00edade bem ruim essa sua. Coloca ruim nisso, afe. Opa, olha a\u00ed a sirene da ambul\u00e2ncia, t\u00e1 ouvindo? \u00c9 a minha deixa. Vou nessa. Espero que tudo acabe bem\u201d.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">Disse isso e soltou uma gargalhada. \u201cAcabe bem \u00e9 boa, n\u00e9?\u201d, emendou. \u201cTudo acaba igual pra todo mundo, nem sei por que disse isso\u201d, e continuou a rir antes de continuar a falar, j\u00e1 de p\u00e9 na porta do quarto.\u00a0<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><span style=\"color: #000080\">\u201cMas foi bom tocar no assunto porque n\u00e3o sei se j\u00e1 disse que o importante na vida \u00e9 ter eleg\u00e2ncia. E eu sei que voc\u00ea t\u00e1 a\u00ed pensando que eleg\u00e2ncia s\u00e3o aquelas camisas Armani que voc\u00ea tem no arm\u00e1rio, e os Prada que voc\u00ea usa nos finais de semana, e os len\u00e7ois de mil fios sobre os quais voc\u00ea se deita cada noite com uma mulher. N\u00e3o, meu querido, eleg\u00e2ncia n\u00e3o tem nada a ver com grana. Ali\u00e1s, nesses meus ziguezagues mundanos as pessoas mais elegantes que conheci moravam em comunidades, ganhavam mal, comiam mal, se vestiam mal, e eram sofisticad\u00edssimas. Coisa de alma, sabe? E a dana\u00e7\u00e3o \u00e9 que at\u00e9 para morrer \u00e9 preciso ter eleg\u00e2ncia. Mas sabe qual \u00e9 o truque? S\u00f3 sabem morrer aqueles que sabem viver. E olha seu estado agora? Uma l\u00e1stima. Todo apavorado. Se voc\u00ea pudesse se ver ia sentir vergonha. Metade do que voc\u00ea est\u00e1 sentindo \u00e9 medo de morrer, n\u00e3o tem nada a ver com o cora\u00e7\u00e3o. O fort\u00e3o e mach\u00e3o tremendo como um menininho, hein. Bobagem ter medo do que \u00e9 inevit\u00e1vel. Ali\u00e1s, \u00e9 aquele velho ditado: diante do inevit\u00e1vel a \u00fanica rea\u00e7\u00e3o poss\u00edvel \u00e9 o humor. Adoro esse ditado, voc\u00ea n\u00e3o? Bom, era isso, falei demais, n\u00e3o devia ter tomado aquele \u00faltimo energ\u00e9tico. Agora voc\u00ea est\u00e1 por conta. Quem sabe eu volte qualquer dia desses. Vamos ver quantos pontos essa multa que vou tomar vai me render. Se n\u00e3o forem muitos, e se eu n\u00e3o puder indicar outro infrator, volto. Foi um prazer, mas mais ou menos, n\u00e9? Os param\u00e9dicos est\u00e3o entrando pelos fundos, ainda bem que eu deixei a porta aberta. Shhhhhhh, n\u00e3o precisa agradecer\u201d.<\/span><\/p>\n<p style=\"font-family: Verdana, Arial, Helvetica, sans-serif;text-align: justify\"><em><span style=\"color: #000080\">(e-mail para a colunista: lacombianas@pedromigao.com.br)<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retomando o curso normal do blog, a coluna &#8220;Lacombianas&#8221;, da jornalista Milly Lacombe, faz um convite \u00e0 reflex\u00e3o. Um lindo dia para morrer Acordei assustado,Tour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[7,6],"class_list":["post-16514","post","type-post","status-publish","format-standard","hentry","category-lacombianas","tag-reflexoes","tag-vida-cotidiana"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/16514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=16514"}],"version-history":[{"count":0,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/16514\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=16514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=16514"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=16514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}