{"id":11621,"date":"2011-02-01T08:09:00","date_gmt":"2011-02-01T10:09:00","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2011\/02\/samba-de-terca-a-grande-constelacao-das-estrelas-negras\/"},"modified":"2017-03-07T15:36:08","modified_gmt":"2017-03-07T18:36:08","slug":"samba-de-terca-a-grande-constelacao-das-estrelas-negras","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2011\/02\/samba-de-terca-a-grande-constelacao-das-estrelas-negras\/","title":{"rendered":"Samba de Ter\u00e7a &#8211; &#8220;A Grande Constela\u00e7\u00e3o das Estrelas Negras&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">Mais uma ter\u00e7a feira, ares soteropolitanos, e a nossa coluna &#8220;Samba de Ter\u00e7a&#8221; traz um samba &#8211; sugest\u00e3o do leitor Emerson Braz &#8211; que nem \u00e9 brilhante, mas \u00e9 personagem de um dos resultados mais pol\u00eamicos da hist\u00f3ria do carnaval carioca: Beija-Flor 1983.<\/p>\n<p style=\"text-align: justify;\">A Beija-Flor era uma escola pequena, que transitava entre o primeiro e o segundo grupos do carnaval carioca. Em 1974 e 1975 desfilou com enredos de exalta\u00e7\u00e3o \u00e0 ditadura militar, o que granjeou antipatias extremas em setores da intelectualidade carioca.<\/p>\n<p style=\"text-align: justify;\">Em 1976 o banqueiro do jogo do bicho Anisio Abra\u00e3o David assumiu a escola &#8211; onde se encontra at\u00e9 hoje &#8211; e investiu fortemente para coloc\u00e1-la no grupo das grandes. Trouxe do Salgueiro o carnavalesco bicampe\u00e3o Jo\u00e3ozinho Trinta e gastou muito dinheiro a fim de revolucionar o visual dos desfiles.<\/p>\n<p style=\"text-align: justify;\">Com isso, a escola foi tricampe\u00e3 em 1976, 77 e 78, vice em 1979, campe\u00e3 de novo em 1980 &#8211; junto com a Portela e a Imperatriz Leopoldinense &#8211; e vice em 1981.<\/p>\n<p style=\"text-align: justify;\">Entretanto, em 1982 a escola foi apenas a sexta colocada, ainda tendo de enfrentar um desconto de pontos como puni\u00e7\u00e3o por ter desfilado com pessoas vivas em suas alegorias &#8211; isso era proibido no regulamento daquele ano.<\/p>\n<p style=\"text-align: justify;\">Para o ano seguinte, a escola de Nil\u00f3polis optaria por um enredo de f\u00e1cil comunica\u00e7\u00e3o com o p\u00fablico: &#8220;A Grande Constela\u00e7\u00e3o das Estrelas Negras&#8221;. O objetivo era listar personalidades negras de destaque como Pel\u00e9, Clementina de Jesus, Ganga Zumba e a passista da escola Pinah &#8211; que havia deixado embasbacado o Pr\u00edncipe Charles da Inglaterra em evento aqui no Brasil.<\/p>\n<p style=\"text-align: justify;\">A escola n\u00e3o tinha tradi\u00e7\u00e3o de grandes sambas, \u00e0 exce\u00e7\u00e3o de 1976 e 1978 &#8211; e o samba escolhido para o carnaval de 83 tamb\u00e9m n\u00e3o era dos melhores daquele ano. Ainda mais comparando-se com sambas como o do Imp\u00e9rio Serrano, o da Portela e o da Mocidade Independente, entre outros.<\/p>\n<p style=\"text-align: justify;\">Ali\u00e1s, Jo\u00e3ozinho Trinta e Paulo Barros, dois dos grandes revolucionadores art\u00edsticos do carnaval t\u00eam a caracter\u00edstica de que as escolas onde passam n\u00e3o possuem grandes sambas enquanto est\u00e3o l\u00e1. Curioso.<\/p>\n<p style=\"text-align: justify;\">Os autores da composi\u00e7\u00e3o eram o puxador Neguinho da Beija Flor e seu irm\u00e3o, N\u00eago &#8211; este mesmo que hoje \u00e9 int\u00e9rprete da Mocidade. Era um samba curto e que estava a servi\u00e7o do visual proposto pelo carnavalesco.<\/p>\n<p><iframe loading=\"lazy\" title=\"Beija Flor - Carnaval 1983 - Desfile Completo\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/gZVzXDQv7lc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\">A Beija-Flor foi a d\u00e9cima-segunda e \u00faltima escola a desfilar, j\u00e1 na no final da manh\u00e3 da segunda feira de carnaval, 14 de fevereiro &#8211; sob um sol escaldante. Toda em branco e prata, a agremia\u00e7\u00e3o encerrou os desfiles daquele ano.\u00a0Se o leitor observar o v\u00eddeo com aten\u00e7\u00e3o ver\u00e1 que os carros da escola nada mais eram que plataformas para mulatas e destaques &#8211; como Jesus Henrique e a cantora Clementina de Jesus &#8211; sem esculturas que contassem o enredo &#8211; mais tema que enredo.<\/p>\n<p style=\"text-align: justify;\">A expectativa para a apura\u00e7\u00e3o era de que a Mocidade Independente, o Imp\u00e9rio Serrano e a Portela duelariam ponto a ponto pelo t\u00edtulo. Mas&#8230;<\/p>\n<p style=\"text-align: justify;\">Em um resultado surpreendente a escola de Nil\u00f3polis conquistou o t\u00edtulo, com 204 pontos, tr\u00eas \u00e0 frente da Portela e quatro do Imp\u00e9rio Serrano. A Mocidade parou apenas em sexto, mais de dez pontos atr\u00e1s da campe\u00e3.<\/p>\n<p style=\"text-align: justify;\">Logo depois come\u00e7aram a aparecer as hist\u00f3rias da apura\u00e7\u00e3o. A primeira delas foi a de um jurado, que deu nota baixa para o Imp\u00e9rio Serrano (um esc\u00e2ndalo) e \u00a0dez\u00a0somente\u00a0para a Beija-Flor. O sujeito, que n\u00e3o tinha muitas condi\u00e7\u00f5es financeiras, apareceu na semana seguinte ao carnaval com um Monza 0 km &#8211; o carro considerado &#8220;chique&#8221; \u00e0 \u00e9poca &#8211; dado por n\u00e3o se sabe quem.<\/p>\n<p style=\"text-align: justify;\">E tivemos o &#8220;Fator Messias Neiva&#8221;. Jurado de alegorias, decidiu o carnaval ao dar Nota Dez apenas para a Beija Flor &#8211; que s\u00f3 tinha pessoas em cima dos carros, mais nada &#8211; e seis para Portela e Mocidade. Como a diferen\u00e7a final foi de tr\u00eas pontos, ele deu o t\u00edtulo \u00e0 Beija Flor.<\/p>\n<p style=\"text-align: justify;\">Ele foi acusado de ter recebido 1 milh\u00e3o de cruzeiros &#8211; a moeda da \u00e9poca &#8211; para dar estas notas. Mas vamos \u00e0 mat\u00e9ria publicada no jornal O Globo em 19 de fevereiro de 1983, s\u00e1bado seguinte ao desfile, que uma boa alma digitalizou, colocou em uma das listas de discuss\u00e3o e eu tive o cuidado de guardar. Ela fala por si s\u00f3:<\/p>\n<p style=\"text-align: justify;\"><em><strong>Messias nem se lembra dos enredos das escolas<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">O jurado Messias Neiva afirmou ontem ter &#8220;esquecido&#8221; at\u00e9 o enredo da Portela e s\u00f3 poder\u00e1 explicar por que lhe deu nota seis em Alegorias e Adere\u00e7os se ver o teipe do desfile. Ele disse ter esquecido tamb\u00e9m o enredo e a raz\u00e3o da nota oito \u00e0 Imperatriz Leopoldinense e n\u00e3o se lembra sequer do enredo do Imp\u00e9rio Serrano. Reconheceu que n\u00e3o\u00a0entende de samba e disse que, se a Mocidade Independente tivesse colocado o tatu no ch\u00e3o, e n\u00e3o em cima da \u00e1rvore &#8220;levaria mais dois pontos&#8221;.<\/p>\n<p style=\"text-align: justify;\">Artista pl\u00e1stico, morador de Caxias, Messias Neiva disse n\u00e3o ter recebido qualquer orienta\u00e7\u00e3o da Riotur sobre como votar: &#8220;Fui l\u00e1 e dei nota de acordo como que senti na hora&#8221;. Ele informou que foi convidado para o j\u00fari por um fregu\u00eas de seus quadros, o juiz Jos\u00e9 Cauipe, que o apresentou ao Coronel Annibal Uz\u00eada. Nas reuni\u00f5es a que\u00a0compareceu, soube apenas que n\u00e3o poderia dar nota zero.<\/p>\n<p style=\"text-align: justify;\"><strong>Justificativas<\/strong><\/p>\n<p style=\"text-align: justify;\">Ele mostrou ao GLOBO o papel no qual justificou as notas dadas \u00e0 Unidos da Tijuca, Uni\u00e3o da Ilha, Mocidade Independente e Mangueira &#8211; \u00fanicas escolas que mereceram anota\u00e7\u00f5es ao lado da nota. A Unidos da Tijuca, por exemplo, tirou sete porque &#8220;um cidad\u00e3o empurrava um carro \u00e0 paisana&#8221;:<\/p>\n<p style=\"text-align: justify;\">&#8211; Esse cara matou o desfile da escola, porque ela merecia mais, mas ele empurrava um carro aleg\u00f3rico sem estar fantasiado. (A Riotur, por\u00e9m, permite que os componentes empurrem os carros sem fantasia, o que em todas as escolas).<\/p>\n<p style=\"text-align: justify;\">Messias Neiva, que disse viver de sua pintura &#8220;desde a d\u00e9cada de 50&#8221;, come\u00e7ou a carreira como pintor de letreiros eleitorais. Sobre a acusa\u00e7\u00e3o de ter recebido Cr$ 1 milh\u00e3o da Beija-Flor para lhe dar dez, disse:<\/p>\n<p style=\"text-align: justify;\">&#8211; \u00c9 muito pouco para eu sujar meu nome.<\/p>\n<p style=\"text-align: justify;\">Ele confirmou que vem recebendo amea\u00e7as de morte e recusou-se a dar seu endere\u00e7o, em Caxias, onde mora com a fam\u00edlia. A entrevista foi na casa de um amigo, em Copacabana.<\/p>\n<p style=\"text-align: justify;\"><strong>Esquecimento<\/strong><\/p>\n<p style=\"text-align: justify;\">Messias afirmou que julgou o desfile &#8220;como artista e n\u00e3o como sambista&#8221;, porque n\u00e3o entende de samba. A Mocidade Independente foi a \u00fanica escola que ontem soube analisar rapidamente, mas se referiu a seu enredo como &#8220;aquela coisa da selva&#8221;:<\/p>\n<p style=\"text-align: justify;\">&#8211; Da Mocidade eu sei: nos carros, vinha a vegeta\u00e7\u00e3o l\u00e1 em cima uma mulher, com on\u00e7as em volta dela trepadas na \u00e1rvore. No segundo carro, vinham tatus nas copas das \u00e1rvores: foi nesse carro que ela levou pau. Se ela colocasse os p\u00e1ssaros em cima e o tatu em baixo eu aumentaria a nota em dois pontos: de seis para oito. No terceiro\u00a0carro, vinha a selva, mas faltou a mulher: ou seja, ela adoeceu ou se atrasou. A Riotur disse que, se faltasse um componente, a gente tinha direito at\u00e9 de deixar de votar. E eu vi o espa\u00e7o da figura viva vazia.<\/p>\n<p style=\"text-align: justify;\">&#8211; E a Mangueira, por que mereceu seis?<\/p>\n<p style=\"text-align: justify;\">&#8211; Ah, a Mangueira estava fraca de alegoria e aquele trem realmente era maravilhoso, enchia os olhos da gente, mas era s\u00f3 um belo trabalho de carpintaria.<\/p>\n<p style=\"text-align: justify;\">&#8211; E o seis da Portela?<\/p>\n<p style=\"text-align: justify;\">&#8211; Dei o que ela merecia.<\/p>\n<p style=\"text-align: justify;\">&#8211; Mas por que merecia seis?<\/p>\n<p style=\"text-align: justify;\">&#8211; Porque na hora eu vi e achei que era seis. Agora n\u00e3o me lembro mais. Como \u00e9 que posso me lembrar do que vi h\u00e1 quatro dias?<\/p>\n<p style=\"text-align: justify;\">&#8211; Voc\u00ea n\u00e3o se lembra nem do enredo? Qual era o enredo da Portela?<\/p>\n<p style=\"text-align: justify;\">&#8211; Sinceramente n\u00e3o sei, n\u00e3o posso me lembrar de todos. Sei que a escola estava maravilhosa, n\u00e3o houve falhas.<\/p>\n<p style=\"text-align: justify;\">&#8211; E por que o seis, se n\u00e3o houve falhas?<\/p>\n<p style=\"text-align: justify;\">&#8211; Ih, j\u00e1 vi que voc\u00ea \u00e9 portelense. Ora, n\u00e3o sei me lembro. Na hora, eu achei que era seis. Se voc\u00ea me trouxer o teipe do desfile, eu digo.<\/p>\n<p style=\"text-align: justify;\">&#8211; U\u00e9, a Uni\u00e3o da Ilha?<\/p>\n<p style=\"text-align: justify;\">&#8211; A Uni\u00e3o da Ilha tenho aqui anotado ( e come\u00e7a a ler sua justificativa): &#8220;Uma senhora sonolenta em cima de um carro, oferecendo perigo&#8221;. Dei nota sete por isso.<\/p>\n<p style=\"text-align: justify;\"><strong>Vis\u00e3o Prec\u00e1ria<\/strong><\/p>\n<p style=\"text-align: justify;\">Messias Neiva n\u00e3o se lembra nem do enredo da Beija-Flor, \u00fanica escola que mereceu sua nota dez, &#8220;porque desfilou de dia, para o sol, e pude ver tudo melhor&#8221;. Ele explicou que os desfiles durante a noite s\u00e3o sempre prejudicados pela m\u00e1 visibilidade (ele abaixou-se junto ao abajur para ler, sem \u00f3culos, suas anota\u00e7\u00f5es com dificuldade de vis\u00e3o e, na Avenida Marqu\u00eas de Sapuca\u00ed, tamb\u00e9m n\u00e3o usava \u00f3culos).<\/p>\n<p style=\"text-align: justify;\">&#8211; O artista da Beija-Flor fez a obra para desfilar de dia, com sol, e o trabalho ficou bem vis\u00edvel. Vi, achei que estava bom e dei dez.<\/p>\n<p style=\"text-align: justify;\">&#8211; Mas a Imperatriz tamb\u00e9m desfilou durante o dia e mereceu oito. Por que?<\/p>\n<p style=\"text-align: justify;\">&#8211; Porque n\u00e3o sou obrigado a dar dez para todo mundo. Ningu\u00e9m me disse que eu tinha que dar dez a todas. Vi a Imperatriz, o artista dela era excelente, mas achei que merecia oito.<\/p>\n<p style=\"text-align: justify;\">&#8211; Voc\u00ea se lembra do enredo dela?<\/p>\n<p style=\"text-align: justify;\">&#8211; N\u00e3o, n\u00e3o me lembro mais.<\/p>\n<p style=\"text-align: justify;\">&#8211; E a Portela, desfilou de dia ou \u00e0 noite?<\/p>\n<p style=\"text-align: justify;\">&#8211; A que horas a Portela desfilou? N\u00e3o sei. Vai ver ele saiu \u00e0 noite, quando fica dif\u00edcil de a a gente ver os trabalhos.<\/p>\n<p style=\"text-align: justify;\"><strong>Dinheiro, N\u00e3o<\/strong><\/p>\n<p style=\"text-align: justify;\">Messias Neiva, de 58 anos, disse que n\u00e3o conhece o Presidente de Honra da Beija-Flor, o banqueiro-do-bicho. Aniz Abra\u00e3o David, o An\u00edsio, e nem tem interesse em conhec\u00ea-lo.<\/p>\n<p style=\"text-align: justify;\">Muito contrariado com a repercuss\u00e3o de suas notas, comentou que, se soubesse que perderia a tranq\u00fcilidade, teria dispensado o convite para ser jurado:<\/p>\n<p style=\"text-align: justify;\">&#8211; Olhe, eu tenho casa pr\u00f3pria, um sitio na serra de Petr\u00f3polis e vivo de minha arte. Gra\u00e7as a Deus, n\u00e3o preciso do dinheiro de ningu\u00e9m e Cr$ 1 milh\u00e3o seria at\u00e9 muito pouco para sujar meu nome. Tenho quadros vendidos na Europa e nos Estados Unidos. At\u00e9 Frank Sinatra comprou um quadro meu quando veio aqui.<\/p>\n<p style=\"text-align: justify;\">Messias Neiva vende quadros pequenos a pre\u00e7o entre Cr$ 60 a Cr$ 100 mil e disse que ter\u00e1 &#8220;um preju\u00edzo incalcul\u00e1vel&#8221; ao manter fechado seu ateli\u00ea na Avenida Nossa Senhora de Copacabana, localiza\u00e7\u00e3o que n\u00e3o considera longe de Caxias, onde mora. Ele disse que est\u00e1 evitando ir ao ateli\u00ea devido \u00e0s amea\u00e7as:<\/p>\n<p style=\"text-align: justify;\">&#8211; Gra\u00e7as a Deus, n\u00e3o tenho quadros mais para vender. Est\u00e3o todos vendidos, por enquanto. S\u00f3 tenho um conselho a dar aos pr\u00f3ximos jurados da Riotur, n\u00e3o aceitem.&#8221;<\/p>\n<p style=\"text-align: justify;\"><strong><em>(O Globo, 19\/02\/1983)<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Bom, como v\u00eaem, no m\u00ednimo bastante suspeito o que ocorreu com este julgamento de 1983. Mas o que passou \u00e0 hist\u00f3ria \u00e9 que, por meios suspeitos ou l\u00edcitos, mas de forma injusta, a Beija Flor foi a campe\u00e3 do carnaval.<\/p>\n<p style=\"text-align: justify;\">E naquele ano a escola iniciaria um longo jejum de quinze anos sem t\u00edtulos, somente quebrado em 1998 &#8211; em um empate com a Mangueira para l\u00e1 de contestado&#8230;<\/p>\n<p style=\"text-align: justify;\">Vamos \u00e0 letra do samba:<\/p>\n<p style=\"text-align: justify;\"><strong>&#8220;A Grande Constela\u00e7\u00e3o das Estrelas Negras&#8221;<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>\u00d4 \u00f4 \u00f4 Ya\u00f4s quanto amor<\/em><br \/>\n<em>Quanto amor<\/em><br \/>\n<em>As pretas velhas Ya\u00f4s<\/em><br \/>\n<em>V\u00eam cantando em seu louvor<\/em><\/p>\n<p style=\"text-align: justify;\"><em>A constela\u00e7\u00e3o<\/em><br \/>\n<em>De estrelas negras que reluz<\/em><br \/>\n<em>Clementina de Jesus<\/em><br \/>\n<em>Eleva o seu cantar feliz<\/em><\/p>\n<p style=\"text-align: justify;\"><em>A Ganga-Zumba<\/em><br \/>\n<em>Que lutou e foi raiz<\/em><br \/>\n<em>Do negro que \u00e9 arte, \u00e9 cultura<\/em><br \/>\n<em>\u00c9 desenvoltura deste meu pa\u00eds<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00cah ! Luana<\/em><br \/>\n<em>O trono de Fran\u00e7a ser\u00e1 seu baiana<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Pinah \u00ea\u00ea\u00ea Pinah<\/em><br \/>\n<em>A Cinderela negra<\/em><br \/>\n<em>Que ao pr\u00edncipe encantou<\/em><br \/>\n<em>No carnaval com o seu esplendor<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Grande Otelo homem show<\/em><br \/>\n<em>Em talento d\u00e1 ol\u00e9<\/em><br \/>\n<em>E o mundo inteiro gritou, Gol ! \u00a0(\u00c9 gol)<\/em><br \/>\n<em>Gol do grande Rei Pel\u00e9 \u00a0(\u00d4 Ya\u00f4s)\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais uma ter\u00e7a feira, ares soteropolitanos, e a nossa coluna &#8220;Samba de Ter\u00e7a&#8221; traz um samba &#8211; sugest\u00e3o do leitor Emerson Braz &#8211; que nemTour Details<\/p>\n","protected":false},"author":2,"featured_media":45429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[63,18,19,146],"class_list":["post-11621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pedro-migao","tag-beija-flor","tag-carnaval","tag-escolas-de-samba","tag-samba-de-terca"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/11621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=11621"}],"version-history":[{"count":0,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/11621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media\/45429"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=11621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=11621"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=11621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}