{"id":11238,"date":"2011-11-27T08:31:00","date_gmt":"2011-11-27T10:31:00","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2011\/11\/orun-aye-carta-aberta-a-minha-mae\/"},"modified":"2011-11-27T08:31:00","modified_gmt":"2011-11-27T10:31:00","slug":"orun-aye-carta-aberta-a-minha-mae","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2011\/11\/orun-aye-carta-aberta-a-minha-mae\/","title":{"rendered":"Orun Ay\u00e9 &#8211; &quot;Carta Aberta \u00e0 Minha M\u00e3e&quot;"},"content":{"rendered":"<div>Neste domingo, mais uma edi\u00e7\u00e3o da <b>coluna &#8220;Orun Ay\u00e9&#8221;, do compositor e publicit\u00e1rio Aloisio Villar<\/b>. Hoje, prefiro n\u00e3o falar muito, apenas agradecer a (imerecida) e gentil refer\u00eancia \u00e0 minha pessoa no texto. Leiam, \u00e9 de arrepiar.<\/p>\n<p><i><b>Carta Aberta \u00e0 Minha M\u00e3e<\/b><\/i><\/p>\n<p>Antes de qualquer coisa queria pedir desculpas aos amigos pela indelicadeza, mas usarei a coluna desse domingo pra conversar com uma pessoa. Ser\u00e1 algo mais pessoal. Podem ler \u00e0 vontade se der curiosidade &#8211; eu, como sou muito curioso, leria&#8230;<\/p>\n<p><i>Domingo, 27 de novembro de 2011<\/i><\/p>\n<p>Parab\u00e9ns pra voc\u00ea, nessa data querida&#8230;<\/p>\n<p>&#8230; ok m\u00e3e: eu sei que voc\u00ea n\u00e3o gosta de comemorar anivers\u00e1rios. Mas voc\u00ea sabe como eu sempre fui tamb\u00e9m n\u00e9? Teimoso, pirracento, mesmo voc\u00ea n\u00e3o querendo comemora\u00e7\u00f5es eu e a v\u00f3 Lieida arm\u00e1vamos algo para voc\u00ea. E acho que no fundo voc\u00ea gostava: era mais charme que fazia. Temos que comemorar: afinal de contas n\u00e3o \u00e9 todo dia que se faz cinquenta e quatro anos.<\/p>\n<p>Ent\u00e3o m\u00e3e, como voc\u00ea est\u00e1? Tempo que n\u00e3o nos falamos hein? Sei que as vezes voc\u00ea me manda alguns recados em sonhos, como quando vacilei com uma namorada ou na v\u00e9spera da vit\u00f3ria da Uni\u00e3o da Ilha, mas conversar temos pouco, justo n\u00f3s que sempre gostamos de um papo.<\/p>\n<p>J\u00e1 faz seis anos, sete meses e vinte e tr\u00eas dias que voc\u00ea foi embora e confesso que n\u00e3o teve um dia que n\u00e3o pensei ou lembrei algum momento de voc\u00ea &#8211; e foi duro hein m\u00e3e? O primeiro dia, primeira semana, o primeiro m\u00eas, o primeiro ano. N\u00e3o imaginei que conseguisse chegar at\u00e9 aqui e me assusto quando paro pra pensar que j\u00e1 faz tanto tempo.<\/p>\n<p>Tanta coisa aconteceu m\u00e3e&#8230; tantas coisas pra contar&#8230;<\/p>\n<p>N\u00e3o sei onde voc\u00ea est\u00e1 agora. Cada religi\u00e3o diz uma coisa, mas pela pessoa maravilhosa que \u00e9 tenho certeza que est\u00e1 em um \u00f3timo lugar e vem acompanhando todas as coisas boas que fa\u00e7o com imenso orgulho e as in\u00fameras bobagens com aquela cara braba que s\u00f3 voc\u00ea conseguia fazer. Imagino quantas vezes durante esses anos voc\u00ea irritada comigo n\u00e3o teria trancado o quarto, colocado Roberto Carlos alto no cd e n\u00e3o abriria a porta pra nada, nem em caso de inc\u00eandio.<\/p>\n<p>Ih m\u00e3e, acho que voc\u00ea usaria cd mais n\u00e3o, hoje em dia d\u00e1 pra baixar m\u00fasica pelo computador tem aparelhos que guardam mais de cem m\u00fasicas, \u00e9 s\u00e9rio. Mas como n\u00e3o tenho certeza se voc\u00ea acompanhou tudo deixa te contar de mim nesses seis anos.<\/p>\n<p>Bem&#8230;<\/p>\n<p>Voc\u00ea partiu depois daquele nosso encontro no hospital Getulio Vargas, em que por uma grande obra do destino deixaram a hora de visita extrapolar e muito enquanto eu segurava sua m\u00e3o inchada e voc\u00ea sem conseguir falar nada me olhava assustada. Foi um baque muito grande sua partida viu? Devia ter me avisado, apesar de achar que avisou e n\u00e3o entendi.<\/p>\n<p>O come\u00e7o foi barra m\u00e3e. Nossa fam\u00edlia n\u00e3o deixou que eu \u201ccurtisse meu luto\u201d direito e tive problemas s\u00e9rios com o tio Junior. Em vez de chorar sua perda tive que enfrentar grandes problemas e ali perceber que eu estava sozinho no mundo. Tinha a minha dor, as horas que deitava na cama vendo tudo desmoronar e a vontade de ir junto com voc\u00ea, hora que sentia uma dor no bra\u00e7o e torcia por um enfarte; ou de cabe\u00e7a torcendo por um aneurisma. Mas na maior parte do tempo tinha que ser forte, por pessoas ao meu lado precisarem de mim.<\/p>\n<p>Lembra da Michele n\u00e9? Minha namorada que mesmo depois do t\u00e9rmino continuou aqui em casa e voc\u00ea tinha como filha. Pois \u00e9, ela n\u00e3o ag\u00fcentou sua perda e de seu padrinho e come\u00e7ou se drogar.<\/p>\n<p>O dinheiro foi embora, a nossa renda que era de quatro mil e quinhentos reais caiu pra cento e sessenta em um m\u00eas porque enquanto voc\u00ea agonizava num hospital meu tio pegou a v\u00f3 na casa de repouso que ela foi colocada no meio de toda essa confus\u00e3o, levou a um banco e mudou senha de tudo virando o respons\u00e1vel por ela na calada da noite.<\/p>\n<p>Mas voc\u00ea tinha que ver m\u00e3e. N\u00e3o pedi piedade, n\u00e3o abaixei a cabe\u00e7a, mesmo quando a luz foi cortada e ele disse que s\u00f3 ajudaria se as coisas fossem do jeito dele. N\u00e3o foram, nunca foram, apanhei muito, ca\u00ed muito, chorei, mas foi tudo do meu jeito, do jeito que voc\u00ea queria.<\/p>\n<p>O pimp\u00e3o e a bolinha, cachorros que voc\u00ea amava e ele jurou em seu leito de morte que n\u00e3o sairiam daqui e logo depois tentou lev\u00e1-los com a carrocinha n\u00e3o sa\u00edram. Ficaram aqui at\u00e9 morrer como eu te prometi. Como voc\u00ea teria feito. Sabe m\u00e3e, muita gente n\u00e3o acredita quando digo que quase passei fome em 2005 porque n\u00e3o deixei que fizessem coisas como levar os cachorros que dormiam contigo para um canil p\u00fablico &#8211; e te digo que n\u00e3o me arrependo.<\/p>\n<p>Tomei golpes do seu \u00faltimo namorado que ficou um tempo ainda morando aqui. Alugu\u00e9is de quartos que eram pagos a ele e ele falava que a pessoa n\u00e3o pagou, mas me livrei dele tamb\u00e9m. Essa voc\u00ea me deve m\u00e3e.<\/p>\n<p>Mas nem tudo foi ruim m\u00e3e, muito pelo contr\u00e1rio. Conheci muita gente bacana nesse per\u00edodo. Voc\u00ea acredita que nenhum amigo meu me abandonou mesmo com todos esses problemas? Muito pelo contr\u00e1rio: foram solid\u00e1rios. Voc\u00ea nem sabe, mas o Paulo Travassos mal tendo comida em casa tirou em seu nome um empr\u00e9stimo para mim, a fim de que eu pudesse pagar aquela conta que quiseram me chantagear para ajudar a pagar.<\/p>\n<p>Demorei a pagar, o nome de coitado chegou a ir pro SPC, mas paguei tudo. O Walkir veio aqui oferecer dinheiro num dos piores momentos e depois comprou material para que eu pudesse fazer uma reforma aqui em casa e aumentar a renda dos alugu\u00e9is &#8211; e nunca me cobrou nada. O Cadinho me ajudou in\u00fameras vezes, todos os meus amigos que n\u00e3o vou citar mais nomes para n\u00e3o ser injusto me apoiaram, m\u00e3e e fiz outros especiais &#8211; como a aproxima\u00e7\u00e3o com o dono desse blog.<\/p>\n<p>E conheci mulheres maravilhosas m\u00e3e. Como voc\u00ea teria gostado de conhec\u00ea-las&#8230; Rafaela, Vivian, Thais, Bia&#8230; Mulheres inesquec\u00edveis que me ajudaram a amadurecer, a conhecer o amor. Errei com algumas delas e voc\u00ea teria puxado minha orelha, chorei por outras e senti falta de sua m\u00e3o no meu cabelo nesse momento me confortando. Mas superei, a vida ensina muito m\u00e3e. Ensina que tudo que fazemos tem um pre\u00e7o e mais cedo ou mais tarde pagaremos. Em rela\u00e7\u00e3o a elas eu paguei quando errei e posso dizer que s\u00f3 tenho boas lembran\u00e7as.<\/p>\n<p>Assim como no samba. Lembro at\u00e9 hoje m\u00e3e que voc\u00ea n\u00e3o gostava muito de meu envolvimento nele. Quantas vezes n\u00e3o pediu pra eu sair do Boi da Ilha, odiava o presidente Eloy. Voc\u00ea sabia que o Eloy foi ao seu enterro? Pois \u00e9, ele foi muito bacana comigo, nos aproximamos depois disso e ganhei mais um samba em sua gest\u00e3o. No momento que venci apontei pro c\u00e9u, apontei voc\u00ea e dediquei.<\/p>\n<p>Era minha primeira vit\u00f3ria depois de sua partida.<\/p>\n<p>Ih m\u00e3e, muitas vit\u00f3rias vieram. Infelizmente essa foi a \u00faltima com o Eloy porque ele tamb\u00e9m faleceu, mas ganhei mais um samba no Boi e esse samba foi premiado assim como aquele que recebeu Estandarte de Ouro e dediquei a voc\u00ea do palco contigo chorando na plat\u00e9ia.<\/p>\n<p>Ganhei muitos outros. Quatro no Dend\u00ea, mais um monte em in\u00fameras escolas e esse ano at\u00e9 na Uni\u00e3o da Ilha ganhei m\u00e3e!! Isso mesmo na Uni\u00e3o da Ilha d\u00e1 pra acreditar?? Eu consegui. Consegui me tornar um compositor respeitado, reconhecido pelas pessoas e claro que em todas essas conquistas voc\u00ea est\u00e1. Em todas as vit\u00f3rias da minha vida.<\/p>\n<p>E sei l\u00e1..acho que a maior das minhas vit\u00f3rias tem dedo seu&#8230;<\/p>\n<p>Pode falar m\u00e3e, eu ter a id\u00e9ia de registrar a Bia foi coisa sua n\u00e3o foi? Desconfio que sim porque essa id\u00e9ia surgiu do nada como se eu tivesse sido tocado por um anjo. E eu olho pra Bia e vejo voc\u00ea, olho minha rela\u00e7\u00e3o com ela e lembro a nossa. Ela olha sua foto e diz &#8216;vov\u00f3&#8217;, m\u00e3e&#8230; \u00c9 s\u00e9rio ela j\u00e1 disse algumas vezes e quando ela fala fico sem rea\u00e7\u00e3o.<\/p>\n<p>Sabe m\u00e3e eu nunca fui pai, n\u00e3o fui preparado pra isso, mas tento ser um bom pai e acho que to conseguindo. Eu, Michele e Renata deixamos faltar nada pra ela. Tive muito medo de dar errado, mas o problema \u00e9 o contr\u00e1rio: temos que nos segurar apra n\u00e3o ter excesso de amor e ela n\u00e3o virar uma crian\u00e7a mimada. Porque ela \u00e9 muito amada m\u00e3e, muito mimada, muito querida. \u00c9 carism\u00e1tica, inteligente, voc\u00ea tinha que v\u00ea-la cantar m\u00fasica de Natal m\u00e3e, tinha que me ver cantando pra ela as m\u00fasicas que voc\u00ea cantava pra mim&#8230; tinha que ver.<\/p>\n<p>Poxa m\u00e3e&#8230; Por que voc\u00ea foi t\u00e3o r\u00e1pido? Com quarenta e sete anos ainda. Tinha que estar aqui pra ver minhas vit\u00f3rias, conhecer a Bia. Seria t\u00e3o bom ver voc\u00eas duas juntas brincando, voc\u00ea babando por ela. Tive dois grandes amores na minha vida que nunca ir\u00e3o conviver, voc\u00ea e ela. Se voc\u00ea tivesse aqui teria evitado tantas besteiras que eu fiz, as vezes \u00e9 muito dif\u00edcil m\u00e3e eu acho que n\u00e3o nasci para ser adulto, sei l\u00e1, as vezes preciso de colo, do seu colo e voc\u00ea n\u00e3o t\u00e1 aqui. Suas broncas quando escondia provas com notas baixas, seu abra\u00e7o chorando quando tirei o oito inimagin\u00e1vel em geografia na sexta s\u00e9rie.<\/p>\n<p>Nossos passeios com a v\u00f3 Lieida, viagens, nossas conversas de madrugada. Voc\u00ea chorando no desfile do Boi da Ilha de 2001, nas minhas formaturas no 2\u00b0 grau e na faculdade, tanto n\u00f3s rimos e choramos juntos. Isso faz tanta falta e as vezes me sinto s\u00f3 metade. Sinto falta at\u00e9 mesmo de estar no computador, olhar pra tr\u00e1s e ver voc\u00ea na cama assistindo ER.<\/p>\n<p>\u00c9 complicado m\u00e3e, muito complicado. Mas hoje n\u00e3o \u00e9 dia de lamenta\u00e7\u00f5es, \u00e9 seu anivers\u00e1rio ent\u00e3o \u00e9 dia de celebrar, celebrar a vida.<\/p>\n<p>A minha, da Bia, a sua que \u00e9 eterna. No meu cora\u00e7\u00e3o voc\u00ea vive, no meu olhar voc\u00ea vive, no meu sorriso dentu\u00e7o porque n\u00e3o quis usar aparelho quando voc\u00ea mandou ou na minha l\u00e1grima de alegria e tristeza voc\u00ea vive, voc\u00ea est\u00e1. Porque todos os dias eu levanto da cama pra honrar seu nome. Para que voc\u00ea tenha orgulho de mim e quando eu morrer te encontrar em algum lugar, voc\u00ea abrir os bra\u00e7os numa mistura de sorriso e choro e me falar \u201cvaleu a pena\u201d.<\/p>\n<p>E pra celebrar essa data coloco aqui a m\u00fasica que fiz pra voc\u00ea no dia de sua missa de s\u00e9timo dia e que a partir do quinto verso forma seu nome nas iniciais.<\/p>\n<p>Te amo m\u00e3e. Para sempre, feliz anivers\u00e1rio. Orun Ay\u00e9!<\/p>\n<p><i><b>No Espelho<\/b><\/i><\/p>\n<p><i>Como vou viver sem o teu amor<\/i><br \/><i>Como viver sem o ombro amigo<\/i><br \/><i>Naqueles momentos onde s\u00f3 existe dor<\/i><br \/><i>Como vai ser ficar sem voc\u00ea<\/i><\/p>\n<p><i>Reluz uma l\u00e1grima em meus olhos<\/i><br \/><i>Eu sei, n\u00e3o vou lutar sozinho<\/i><br \/><i>Geralmente quando eu mais choro<\/i><br \/><i>Imagino seu afago, seu carinho<\/i><br \/><i>No espelho encontro teu olhar<\/i><br \/><i>A imagem que me fortalece<\/i><br \/><i>Vejo que est\u00e1s a me acompanhar<\/i><br \/><i>Intensa tua chama me aquece<\/i><\/p>\n<p><i>Legado que sigo em meu caminho<\/i><br \/><i>Lembran\u00e7as nunca ir\u00e3o se apagar<\/i><br \/><i>Amor \u00e9 como passarinho<\/i><br \/><i>Radiante tendo o c\u00e9u a desbravar \u00a0<\/i><\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste domingo, mais uma edi\u00e7\u00e3o da coluna &#8220;Orun Ay\u00e9&#8221;, do compositor e publicit\u00e1rio Aloisio Villar. Hoje, prefiro n\u00e3o falar muito, apenas agradecer a (imerecida) eTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[7,6],"class_list":["post-11238","post","type-post","status-publish","format-standard","hentry","category-orun-aye","tag-reflexoes","tag-vida-cotidiana"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/11238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=11238"}],"version-history":[{"count":0,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/11238\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=11238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=11238"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=11238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}