{"id":11046,"date":"2012-05-18T07:18:00","date_gmt":"2012-05-18T09:18:00","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/05\/a-gravacao-do-loucos-por-futebol-na-espn\/"},"modified":"2012-05-18T07:18:00","modified_gmt":"2012-05-18T09:18:00","slug":"a-gravacao-do-loucos-por-futebol-na-espn","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/05\/a-gravacao-do-loucos-por-futebol-na-espn\/","title":{"rendered":"A Grava\u00e7\u00e3o do &quot;Loucos por Futebol&quot; na Espn"},"content":{"rendered":"<div><a href=\"http:\/\/2.bp.blogspot.com\/-6l7hhxls7fc\/T7K5RTpx9QI\/AAAAAAAAEv4\/9zaCJ64z030\/s1600\/DSC_0232.JPG\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"424\" kba=\"true\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/05\/DSC_0232.jpg\" width=\"640\"><\/a><\/div>\n<p><\/p>\n<div align=\"justify\">Como os leitores est\u00e3o cansados de saber, na semana passada gravei o programa &#8220;Loucos por Futebol&#8221;, da Espn Brasil. Como prometido &#8211; <a href=\"http:\/\/pedromigao.blogspot.com.br\/2012\/02\/televisao-vista-de-dentro-visita-ao.html\" target=\"_blank\">e como fiz no post sobre a visita que fiz ao SporTv<\/a> &#8211; irei contar um pouco do que ocorre por tr\u00e1s das c\u00e2meras.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Na segunda feira retrasada, dia 07, ao abrir meu e-mail pessoal fui surpreendido com um e-mail da produtora Camila Peixoto\ufeff me convidando para participar do programa, que teria como tema principal o centen\u00e1rio do futebol do Flamengo, que se completa em 2012. Meio ressabiado (confesso)\u00a0respondi e a\u00ed soube como funcionaria: ficaria na mesa junto com os participantes fixos, para isso tendo de ir a S\u00e3o Paulo, onde ficam os est\u00fadios.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Consegui a necess\u00e1ria libera\u00e7\u00e3o no trabalho &#8211; e como j\u00e1 fiz no programa, agrade\u00e7o ao pessoal da Petrobras &#8211; e a produ\u00e7\u00e3o do programa me mandou as passagens para ir e voltar, bem como me disponibilizou um motorista para me buscar no aeroporto e me levar para o retorno posteriormente. A grava\u00e7\u00e3o do programa foi na quinta feira, dia 10.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Antes da grava\u00e7\u00e3o trocamos alguns e-mails para que eu pudesse entender n\u00e3o somente a din\u00e2mica do programa como o que falaria. Destas trocas de e-mails surgiram ideias como falar da hist\u00f3ria do urubu e a coincid\u00eancia do programa ir ao ar na v\u00e9spera do Dia das M\u00e3es e na data exata do anivers\u00e1rio da minha.<\/div>\n<div align=\"justify\"><\/div>\n<div><a href=\"http:\/\/3.bp.blogspot.com\/-xUwtT2fdIXs\/T7LDBcFRYjI\/AAAAAAAAEw8\/yDGoldacUAQ\/s1600\/S%C3%A3o+Paulo-20120510-00582.jpg\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"480\" kba=\"true\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/05\/S%C3%A3o+Paulo-20120510-00582.jpg\" width=\"640\"><\/a><\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">O leitor deve ter se perguntado como chegaram ao meu nome, certo?<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Foi atrav\u00e9s de um post deste Ouro de Tolo republicado no prestigiado blog do jornalista Luis Nassif (<a href=\"http:\/\/pedromigao.blogspot.com.br\/2012\/04\/algumas-notas-sobre-nacionalizacao-da.html\" target=\"_blank\">acredito que tenha sido o referente \u00e0 nacionalia\u00e7\u00e3o da petroleira argentina YPF<\/a>) que levou o editor Augusto Alves a este blog e a partir da\u00ed houve o convite.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">A pedido da produ\u00e7\u00e3o selecionei algumas camisas e materiais do meu acervo e coloquei em uma mochila. Havia a preocupa\u00e7\u00e3o de minha parte em n\u00e3o despachar bagagem porque estava com os hor\u00e1rios bastante apertados &#8211; precisava retornar ao Rio ainda na quinta &#8211; e n\u00e3o poderia me dar ao luxo de chegar uma hora antes nos aeroportos.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Sobre aeroportos, uma nota: eu jamais havia descido em Congonhas, porque normalmente quando vou a S\u00e3o Paulo embarco e desembarco por Guarulhos. Leitor: pousar de dia em Congonhas \u00e9 um verdadeiro filme de terror. Voc\u00ea v\u00ea os pr\u00e9dios passando pertinho da janela e n\u00e3o h\u00e1 a menor margem de manobra &#8211; e a pista \u00e9 muito curta.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">O curioso \u00e9 que acabei passando por quatro aeroportos neste dia, pois fui do Santos Dumont para Congonhas e retornei de Guarulhos (que est\u00e1 parecendo uma rodovi\u00e1ria, a prop\u00f3sito) para o Gale\u00e3o.<\/div>\n<div align=\"justify\"><\/div>\n<div><a href=\"http:\/\/2.bp.blogspot.com\/-n19YkpFfG3Q\/T7K6Gt1MBZI\/AAAAAAAAEwg\/CzOOlSwELUA\/s1600\/S%25C3%25A3o+Paulo-20120510-00585.jpg\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"480\" kba=\"true\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/05\/S%25C3%25A3o+Paulo-20120510-00585.jpg\" width=\"640\"><\/a><\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Ao desembarcar o motorista Miguel j\u00e1 me aguardava para o trajeto at\u00e9 a sede da Espn, que fica no bairro do Sumar\u00e9. \u00d3timo papo, o motorista me contou algumas hist\u00f3rias de visitas ilustres (o que n\u00e3o era meu caso, claro) que ele havia transportado.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Cheguei por volta de 13:45 na reda\u00e7\u00e3o, que ocupa o pr\u00e9dio utilizado anteriormente pela antiga Tv Tupi. A grava\u00e7\u00e3o estava programada para as 15 horas, e contaria com o apresentador Marcelo Duarte e os jornalistas Celso Unzelte (os dois comigo na foto acima) e o m\u00edtico Paulo Vin\u00edcius Coelho (abaixo), mais conhecido pelas iniciais de seu nome: PVC.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">A reda\u00e7\u00e3o &#8211; que pode ser vista nas duas primeiras fotos &#8211; tem tamanho equivalente a do SporTv que havia visitado anteriormente, com um n\u00famero de jornalistas parecido. Fiquei com a impress\u00e3o de que o clima era mais informal e menos, digamos, &#8220;controlado&#8221;. Se fosse comparar diria que o SporTv \u00e9 mais &#8220;futebol alem\u00e3o&#8221; e\u00a0a Espn &#8220;futebol brasileiro&#8221;. Estilos diferentes &#8211; n\u00e3o significa que um seja melhor que o outro.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Desde o in\u00edcio havia a preocupa\u00e7\u00e3o de me deixar\u00a0\u00e0 vontade. Toda a equipe me tratou com bastante defer\u00eancia (mais at\u00e9 que eu merecesse) e mostrando que eu n\u00e3o estava ali em sensa\u00e7\u00e3o de inferioridade: era um deles. Logicamente eu era um convidado do canal, e isso pesa. Duarte brincou muito comigo por conta do <a href=\"http:\/\/pedromigao.blogspot.com.br\/2012\/04\/reading-de-volta-premier-league.html\" target=\"_blank\">post que escrevi aqui sobre o Reading<\/a>, da Inglaterra.<\/div>\n<div align=\"justify\"><\/div>\n<div><a href=\"http:\/\/3.bp.blogspot.com\/-rqNyYXG1k6A\/T7LIN3voRxI\/AAAAAAAAExQ\/Rrlv2z5B8bs\/s1600\/DSC_0277.JPG\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"424\" kba=\"true\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/05\/DSC_0277.jpg\" width=\"640\"><\/a><\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Conversamos um pouco, acertamos alguns detalhes e fomos a uma sala onde \u00e9 feita uma pequena maquiagem e havia um lanche \u00e0 minha espera antes da grava\u00e7\u00e3o &#8211; que optei por deixar para depois. A profissional passa um produto no rosto para diminuir o brilho e, depois, uma esp\u00e9cie de creme para fazer desaparecer olheiras e rugas de express\u00e3o. Leitores, eu duvidava da efic\u00e1cia deste tipo de produto, mas realmente funciona: como podem ver nas fotos, me remo\u00e7ou uns dez anos.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Eu havia levado duas camisas do Flamengo para utilizar na grava\u00e7\u00e3o: uma rubro negra e outra azul (esta de goleiro), ambas do modelo atual. Os editores me deixaram \u00e0 vontade para utilizar a que eu quisesse, mas houve uma pondera\u00e7\u00e3o de que, com o cen\u00e1rio com v\u00e1rios elementos rubro-negros, utilizar a de goleiro destacaria mais &#8211; o que determinou a minha op\u00e7\u00e3o. Olhando as imagens depois acho que acertei.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Fomos para o cen\u00e1rio, que \u00e9 um est\u00fadio razoavelmente grande e com menos utiliza\u00e7\u00e3o de recursos tecnol\u00f3gicos, em especial de efeitos de luz e c\u00e2meras.\u00a0O processo \u00e9 mais artesanal, no sentido que que a parte t\u00e9cnica depende mais do manejo humano. O cen\u00e1rio tamb\u00e9m \u00e9 composto por livros, bonequinhos, murais de fotos, algumas quinquilharias e a geladeira onde se guardou a &#8220;Farofa Boiadeiro&#8221; (que, a prop\u00f3sito, est\u00e1 na minha despensa) e onde PVC mostrou o time de bot\u00e3o com o S\u00e3o Paulo de 1957. A prop\u00f3sito, ela n\u00e3o gela, embora existissem dentro dela latinhas (creio que de cerveja, mas n\u00e3o garanto) tem\u00e1ticas do Gr\u00eamio e do Inter de Porto Alegre como decora\u00e7\u00e3o.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Aproveitei todo o tempo que pude para conversar, ouvir\u00a0e aprender &#8211; inclusive com algumas dicas bastante valiosas do PVC sobre o balan\u00e7o do Palmeiras e que servem como alertas para a an\u00e1lise do balan\u00e7o rubro negro.<\/div>\n<div align=\"justify\"><\/div>\n<div><a href=\"http:\/\/3.bp.blogspot.com\/-T-G-hiCjAbM\/T7LLG_zspiI\/AAAAAAAAExk\/PQxsTXukPPA\/s1600\/DSC_0248.JPG\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"424\" kba=\"true\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/05\/DSC_0248.jpg\" width=\"640\"><\/a><\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Antes do in\u00edcio da grava\u00e7\u00e3o h\u00e1 uma s\u00e9rie de ajustes e h\u00e1 meio que um &#8220;esquenta&#8221;, com alguns testes e conversas em parte gravadas &#8211; e que por si s\u00f3 dariam um outro programa. O\u00a0&#8220;Loucos por Futebol&#8221;\u00a0\u00e9 mais descontra\u00eddo que outros de esportes, mas \u00e9 (quase) tudo combinado: minhas interven\u00e7\u00f5es j\u00e1 estavam acertadas antes mesmo da grava\u00e7\u00e3o, obviamente n\u00e3o as palavras mas os assuntos que eu iria abordar e os momentos.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Isso se faz necess\u00e1rio porque \u00e9 um programa de tempo cronometrado (54 minutos, inclu\u00eddas as mat\u00e9rias) e pela caracter\u00edstica dos assuntos se estenderem demais, as interven\u00e7\u00f5es isto acaba gerando um trabalho muito grande na edi\u00e7\u00e3o. Na pr\u00e1tica, a \u00fanicas improvisa\u00e7\u00f5es que fiz foram a refer\u00eancia ao Estadual do Rio de 2002, o coment\u00e1rio sobre a Alemanha\u00a0e a resposta sobre como conseguia as camisas que mostrei no programa. At\u00e9 o agradecimento \u00e0 Petrobras e as brincadeiras com o meu sobrenome estavam previamente acertadas.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">A grava\u00e7\u00e3o come\u00e7ou por volta de 15:20 e eu estava bastante tenso, especialmente no primeiro bloco. Nunca havia aparecido na televis\u00e3o antes e tamb\u00e9m estava procupado em olhar para a c\u00e2mera certa, embora vendo depois percebi que bastava olhar para quem estava com a palavra quando n\u00e3o estava falando.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">No intervalo para o segundo bloco o Unzelte disse que eu estava indo bem e a partir da\u00ed dei uma relaxada para os blocos restantes.<\/div>\n<div align=\"justify\"><\/div>\n<div><a href=\"http:\/\/1.bp.blogspot.com\/-Xy9rH9YYAZQ\/T7LNFbDvq3I\/AAAAAAAAExs\/vF0QKuFleM4\/s1600\/DSC_0267.JPG\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"424\" kba=\"true\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/12\/DSC_0267.jpg\" width=\"640\"><\/a><\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Os intervalos s\u00e3o um show \u00e0 parte. Os VTs das mat\u00e9rias s\u00e3o mostrados para a gente, e vamos conversando enquanto isso, com brincadeiras e trocas de informa\u00e7\u00f5es. Tanto que a informa\u00e7\u00e3o sobre o local onde o Jo\u00e3o M\u00e1ximo havia gravado a cr\u00f4nica sobre Dino Sani foi dada por mim ao apresentador Marcelo Duarte enquanto o mesmo era transmitido na grava\u00e7\u00e3o.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Vale mencionar que PVC e Unzelte passaram bom tempo debatendo se o jogador Sarar\u00e1 era o segundo ou o terceiro reserva do S\u00e3o Paulo de 1957 abordado no programa. Isso foi resolvido com uma consulta ao Google feita em seu celular por Unzelte no intervalo.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Ali\u00e1s, os caras s\u00e3o verdadeiras enciclop\u00e9dias. PVC \u00e9 uma esp\u00e9cie de &#8220;Google&#8221; futebol\u00edstico: se perguntar a escala\u00e7\u00e3o do Flamengo de 1928\u00a0ele sabe de cabe\u00e7a. Fera.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Engra\u00e7ad\u00edssimo foi o momento em que Unzelte canta os hinos dos times aniversariantes. A gente ria horrores enquanto os hinos eram literalmente &#8220;executados&#8221; pelo jornalista. Obviamente, a letra dos hinos estava na bancada, ou seja, ele lia. A infame sigla do Esporte Clube Uruguaiana (ECU) tamb\u00e9m foi alvo de muitas gargalhadas nos bastidores. O clima \u00e9 informal e descontra\u00eddo o tempo todo.<\/div>\n<div align=\"justify\"><\/div>\n<div><a href=\"http:\/\/4.bp.blogspot.com\/-LcjOAuJXGP8\/T7K5rOxbRwI\/AAAAAAAAEwI\/jbIWdQqiUKU\/s1600\/DSC_0234.JPG\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"640\" kba=\"true\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/05\/DSC_0234.jpg\" width=\"424\"><\/a><\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Em um dos intervalos eu troquei camisas que estavam no varal com outras que estavam na bancada a meu lado a fim de poder mostr\u00e1-las. Tamb\u00e9m bebi \u00e1gua e trocamos id\u00e9ias sobre o que seria feito no bloco seguinte, al\u00e9m de falar de assuntos como a Sele\u00e7\u00e3o brasileira, por exemplo.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Ao final ainda gravamos a vinheta que apareceria como &#8220;chamada&#8221; do programa, mas esta tive de repetir a pedido da editora. Pelo que percebi na edi\u00e7\u00e3o do programa foi tudo praticamente na \u00edntegra &#8211; no meu caso, apenas uma titubeada que dei quando falo do livro da Charanga Rubro Negra foi cortada. Duarte teve de repetir a escalada inicial devido a um equ\u00edvoco bobo: ele falou &#8220;Clube de Regatas Flamengo&#8221; quando o correto \u00e9 &#8220;Clube de Regatas do Flamengo&#8221; &#8211; mas a\u00ed se v\u00ea o cuidado da produ\u00e7\u00e3o.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Achei que tinha sido apenas razo\u00e1vel a minha participa\u00e7\u00e3o, apesar dos coment\u00e1rios em contr\u00e1rio dos jornalistas e da equipe. Na verdade a gente n\u00e3o tem muita no\u00e7\u00e3o na hora, ainda mais quando se \u00e9 a primeira vez em que se aparece na frente das c\u00e2meras. Olhando depois e com o feedback de quem assistiu achei muito bom.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Lanchamos ap\u00f3s a grava\u00e7\u00e3o e ainda conversei mais um pouco com a equipe, deixando acertadas entrevistas para este Ouro de Tolo com PVC e com Marcelo Duarte. Na verdade poderia at\u00e9 ter ficado um pouco mais, mas estava com o hor\u00e1rio bastante apertado &#8211; meu v\u00f4o era era \u00e0s 19:45 em Guarulhos. Mas at\u00e9 que o tr\u00e2nsito, embora pesado, estava razo\u00e1vel, e cheguei a Cumbica ainda a tempo de beber um chope antes do embarque &#8211; que foi complicado: tivemos de entrar no \u00f4nibus e depois esperar dentro do avi\u00e3o quase 25 minutos para a autoriza\u00e7\u00e3o da decolagem.<\/div>\n<div align=\"justify\"><\/div>\n<div><a href=\"http:\/\/2.bp.blogspot.com\/-ewFyFWwTe0Y\/T7LTrawL_tI\/AAAAAAAAEyA\/5T9nuFriy7Q\/s1600\/DSC_0279.JPG\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"424\" kba=\"true\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/05\/DSC_0279.jpg\" width=\"640\"><\/a><\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Posso dizer que fiquei muito feliz com o convite e gostei do resultado. Cada vez mais vejo que minha voca\u00e7\u00e3o era o jornalismo, mas agora &#8220;In\u00eas \u00e9 morta&#8221;&#8230; No momento em que escrevo o v\u00eddeo do programa ainda n\u00e3o estava dispon\u00edvel no Youtube.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Termino agradecendo ao editores Augusto Alves e Karen Barbosa e especialmente\u00a0\u00e0 produtora Camila Peixoto, pela oportunidade e pelo apoio.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Espero ter outras oportunidades de poder estar na tv, pois confesso que gostei bastante da experi\u00eancia. J\u00e1 havia em duas ocasi\u00f5es dado entrevistas a r\u00e1dios e jornais, mas \u00e0 frente das c\u00e2meras jamais.<\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\">Mas valeu demais.<\/div>\n<div align=\"justify\"><\/div>\n<div><a href=\"http:\/\/2.bp.blogspot.com\/-ofkXV3-lhUI\/T7K5_67t9mI\/AAAAAAAAEwY\/WcLMqYHDjzc\/s1600\/S%25C3%25A3o+Paulo-20120510-00593.jpg\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"480\" kba=\"true\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/05\/S%25C3%25A3o+Paulo-20120510-00593.jpg\" width=\"640\"><\/a><\/div>\n<div align=\"justify\"><\/div>\n<div align=\"justify\"><em>(Da esquerda para a direita: Augusto (que \u00e9 Flamengo), eu, Camila e Karen)<\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Como os leitores est\u00e3o cansados de saber, na semana passada gravei o programa &#8220;Loucos por Futebol&#8221;, da Espn Brasil. Como prometido &#8211; e como fizTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[289],"tags":[41,42,33,87],"class_list":["post-11046","post","type-post","status-publish","format-standard","hentry","category-pedro-migao","tag-esporte","tag-flamengo","tag-jornalismo","tag-televisao"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/11046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=11046"}],"version-history":[{"count":0,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/11046\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=11046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=11046"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=11046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}