{"id":11042,"date":"2012-05-21T08:14:00","date_gmt":"2012-05-21T10:14:00","guid":{"rendered":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/05\/bissexta-a-imprensa-brasileira-em-clima-de-fla-x-flu\/"},"modified":"2012-05-21T08:14:00","modified_gmt":"2012-05-21T10:14:00","slug":"bissexta-a-imprensa-brasileira-em-clima-de-fla-x-flu","status":"publish","type":"post","link":"http:\/\/www.pedromigao.com.br\/ourodetolo\/2012\/05\/bissexta-a-imprensa-brasileira-em-clima-de-fla-x-flu\/","title":{"rendered":"Bissexta &#8211; &quot;A Imprensa Brasileira em Clima de Fla x Flu&quot;"},"content":{"rendered":"<div><a href=\"http:\/\/2.bp.blogspot.com\/-aKMA0m4ATFY\/T7hpk-aV4FI\/AAAAAAAAEyo\/NgYTqOm-WCc\/s1600\/Cachoeira.jpg\" imageanchor=\"1\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"504\" src=\"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-content\/uploads\/2012\/05\/Cachoeira.jpg\" width=\"640\"><\/a><\/div>\n<p><\/p>\n<div>Nesta segunda feira, <b>a coluna &#8220;Bissexta&#8221;, do advogado Walter Monteiro<\/b>, mostra o quadro atual do jornalismo de massa brasileiro, suas intera\u00e7\u00f5es com a pol\u00edtica e a necessidade de uma regulamenta\u00e7\u00e3o.<\/div>\n<div><\/div>\n<div>Discordo de alguns pontos do texto, mas \u00e9 um artigo que merece aten\u00e7\u00e3o at\u00e9 por refor\u00e7ar a necessidade de uma regulamenta\u00e7\u00e3o sobre o setor.<\/div>\n<div><\/div>\n<div><b><i>A Imprensa Brasileira em Clima de Fla x Flu<\/i><\/b><\/div>\n<div><\/div>\n<div>Essa semana me contaram que em Belo Horizonte inventaram um jeito novo de transmitir os jogos de futebol nas r\u00e1dios. Quando \u00e9 jogo do Cruzeiro, a transmiss\u00e3o fica a cargo de radialistas cruzeirenses; jogo do Galo, entra uma equipe de atleticanos. Esqueci de perguntar como fazem em cl\u00e1ssicos, talvez misturem os profissionais e cada um puxa a sardinha para a sua brasa.<\/div>\n<div><\/div>\n<div>N\u00e3o sei se a hist\u00f3ria \u00e9 verdadeira: algum leitor mineiro pode depois confirmar para a gente. Mas n\u00e3o duvido que em breve a coisa chegue aqui no Rio Grande do Sul: tem uns loucos que ficam cronometrando a programa\u00e7\u00e3o esportiva e quando descobrem que um time teve dois ou tr\u00eas minutos a mais do que outro, protestam nas redes sociais que a imprensa \u201cse vendeu\u201d ao advers\u00e1rio.<\/div>\n<div><\/div>\n<div>O curioso \u00e9 que no futebol, onde seria totalmente justific\u00e1vel que o sujeito tivesse l\u00e1 suas paix\u00f5es e as deixasse aflorar, a imprensa ainda se esfor\u00e7a para manter neutralidade quase absoluta, para n\u00e3o ferir a sensibilidade dos leitores, ouvintes e telespectadores que torcem para um time diferente.<\/div>\n<div><\/div>\n<div>J\u00e1 no notici\u00e1rio de pol\u00edtica estamos, todos, como os ouvintes de Belo Horizonte: s\u00f3 podemos consumir mat\u00e9rias que coincidam com nossa vis\u00e3o de mundo.<\/div>\n<div><\/div>\n<div>Se voc\u00ea n\u00e3o pode nem ouvir falar no PT, o Globo, a Folha, o Estad\u00e3o e principalmente a VEJA s\u00e3o o Santo Graal da liberdade de express\u00e3o. Est\u00e3o aqui para impedir que os barbudinhos implantem o Stalinismo e transformem a m\u00fasica de Mercedes Sosa, \u201cVolver a Los 17\u201d, no novo hino da Rep\u00fablica Socialista do Brasil. Afinal, estamos na imin\u00eancia de uma revolu\u00e7\u00e3o comunista e n\u00e3o fosse pelo hero\u00edsmo e resist\u00eancia deles, Jos\u00e9 Dirceu j\u00e1 estaria al\u00e7ado ao posto de Secret\u00e1rio Geral do Partido \u00danico dos Trabalhadores e seria uma vers\u00e3o tropical de Kim Jong II.<\/div>\n<div><\/div>\n<div>Mas se do lado esquerdo do seu peito bate um cora\u00e7\u00e3o vermelho, ent\u00e3o nem toque nessa imprensa vendida e manipulada por um baronato elitista. Esta est\u00e1 interessada apenas em dar um golpe contra a democracia, para impedir os avan\u00e7os que a sociedade brasileira experimenta desde 2003 e que retiraram milh\u00f5es de desvalidos da pobreza, revoltando os ricos que nunca se conformaram de ver um metal\u00fargico comandar essa revolu\u00e7\u00e3o social. Leia a Carta Capital, assista a Record, acesse os blogs independentes. \u00c9 a \u00fanica forma de furar o bloqueio maldito da grande imprensa e assim consumir informa\u00e7\u00e3o verdadeira, porque as quatro fam\u00edlias que controlam a m\u00eddia nativa sofrem de indigna\u00e7\u00e3o seletiva e s\u00f3 divulgam aquilo que lhes conv\u00e9m.<\/div>\n<div><\/div>\n<div>Os dois lados sempre se atacando: um chama o outro de PIG (Partido da Imprensa Golpista), o outro revida inventando o PEG (Partido da Esgotosfera Governista). N\u00e3o \u00e9 a Ra\u00e7a Rubro-Negra falando da Young Flu. S\u00e3o jornalistas com anos de experi\u00eancia e um nome a zelar, jogando lama uns nos outros, assegurando ao seu p\u00fablico que a exclusividade da \u00e9tica e da moral lhes pertence e que o outro lado sim, foi corrompido por interesses econ\u00f4micos.<\/div>\n<div><\/div>\n<div>Eu pensei que com o fim da campanha eleitoral de 2010 o \u00e1pice dessa baixaria tivesse ficado para tr\u00e1s, mas estava enganado. Nada se compara em termos de desinforma\u00e7\u00e3o e proselitismo do que o notici\u00e1rio sobre a CPI do Carlinhos Cachoeira.<\/div>\n<div><\/div>\n<div>A pr\u00f3pria exist\u00eancia da CPI j\u00e1 \u00e9 uma aberra\u00e7\u00e3o. Um senador que posava de vestal foi pego com a boca na botija e derreteu seu capital pol\u00edtico, virando um zumbi no Congresso Nacional. Carlinhos Cachoeira, o bandid\u00e3o do momento, estava na cadeia. A Pol\u00edcia Federal tinha tr\u00eas anos de investiga\u00e7\u00e3o, com provas evidentes de crimes profundos. CPI para que? CPI serve para investigar, descobrir aquilo que n\u00e3o se sabe. O que falta mais para descobrir nesse caso que j\u00e1 n\u00e3o fosse de conhecimento da PF?<\/div>\n<div><\/div>\n<div>A CPI s\u00f3 serviria para constranger publicamente advers\u00e1rios pol\u00edticos. Sua instala\u00e7\u00e3o foi um tremendo erro de avalia\u00e7\u00e3o, pois afora o Tiririca (o deputado mais atuante dessa legislatura, com 100% de presen\u00e7a em todas as sess\u00f5es desde 2011 e que at\u00e9 se mudou para Bras\u00edlia com a fam\u00edlia para nunca chegar atrasado), o Jean Wyllys e mais uns gatos pingados, todo mundo tem alguma coisa para esconder naquelas casas de toler\u00e2ncia com o desvio alheio.<\/div>\n<div><\/div>\n<div>N\u00e3o tardou para a CPI desvendar o labirinto que enredava Cachoeira com a construtora Delta, atual campe\u00e3 de obras p\u00fablicas no governo federal e em governos estaduais aliados a este, como no Rio de Janeiro, onde o governador e o dono da Delta dan\u00e7avam animados em Paris e Monte Carlo <i>[N.do.E.: a Delta tamb\u00e9m tem contratos polpudos com o governo paulista, de oposi\u00e7\u00e3o]<\/i>. Mas tamb\u00e9m n\u00e3o tardou para vir \u00e0 tona a umbilical rela\u00e7\u00e3o de Cachoeira com o chefe da sucursal da Veja em Bras\u00edlia, que se valeu do criminoso para produzir reportagens achincalhando o PT.<\/div>\n<div><\/div>\n<div>\u00c9 a\u00ed que entra o ponto que me incomoda profundamente: por acaso algu\u00e9m precisava dessa investiga\u00e7\u00e3o para descobrir que a Veja h\u00e1 muito deixou de ser uma revista informativa para ser um manifesto semanal dos odiadores do Governo? Algum leitor da Veja \u00e9 ing\u00eanuo o suficiente para deixar de perceber o alinhamento da revista ao ajuntamento demo-tucano? \u00d3bvio que n\u00e3o!<\/div>\n<div><\/div>\n<div>O que se quer \u00e9 ir um pouco al\u00e9m: aproveitar a CPI para vingar-se do not\u00f3rio posicionamento pol\u00edtico da revista, anti\u00e9tico quase sempre, flertando com o il\u00edcito em alguns casos, mas dentro do sacrossanto direito de dizer a bobagem e a mentira que bem entender, desde que haja gente disposta a consumir esse lixo travestido de informa\u00e7\u00e3o.<\/div>\n<div><\/div>\n<div>Mas, afinal, qual a extens\u00e3o do envolvimento do agora famoso jornalista Policarpo com Cachoeira? Segundo a turma que n\u00e3o gosta da Veja, h\u00e1 \u201cmais de 200\u201d liga\u00e7\u00f5es entre os dois. J\u00e1 para a Veja, h\u00e1 meras 2 liga\u00e7\u00f5es diretas e 46 men\u00e7\u00f5es ao nome de Policarpo em outras conversas captadas pela Pol\u00edcia Federal.<\/div>\n<div><\/div>\n<div>Por que n\u00f3s, leitores, estamos h\u00e1 duas semanas sem que algu\u00e9m divulgue publicamente o \u00e1udio de, sei l\u00e1, pelo menos umas dez liga\u00e7\u00f5es, com algum tema comprometedor? Ou que Policarpo diga, claramente, qual a raz\u00e3o de ter feito essas duas liga\u00e7\u00f5es que admite e por que seu nome aparece outras tantas em conversas? N\u00e3o sei dizer. Mas suspeito que deixar tudo meio nebuloso conv\u00e9m a ambos os lados, que podem continuar a se acusar mutuamente, pouco se importando em se aproximar da verdade factual.<\/div>\n<div><\/div>\n<div>Em meio a esse quadro desolador, a liga anti-Veja reacende um debate que me \u00e9 muito caro: a regulamenta\u00e7\u00e3o da atividade de imprensa.<\/div>\n<div><\/div>\n<div>Eu coordenava o Departamento Jur\u00eddico do Sindicato dos Jornalistas do Rio de Janeiro quando o ent\u00e3o Presidente Lula apresentou o projeto de cria\u00e7\u00e3o do Conselho Federal de Jornalismo. Jamais vi um tema ser t\u00e3o grosseiramente manipulado pela imprensa, que se revoltou como nunca antes na hist\u00f3ria desse pa\u00eds. Eu escrevi v\u00e1rios artigos chamando aten\u00e7\u00e3o para o total descasamento entre as cr\u00edticas feitas ao projeto e o que ele representava na pr\u00e1tica, pois o que se pretendia era regular t\u00e3o somente o EXERC\u00cdCIO da profiss\u00e3o de jornalista, nunca a atividade de comunica\u00e7\u00e3o. Era uma esp\u00e9cie de OAB ou CREA do jornalismo, para impedir a pr\u00e1tica da atividade por quem n\u00e3o fosse formado em comunica\u00e7\u00e3o social.<\/div>\n<div><\/div>\n<div>Perdemos o debate e passados quase 10 anos, ainda h\u00e1 quem acredite que Lula mandou uma proposta destinada ao controle da imprensa. Uma l\u00e1stima, porque nada \u00e9 mais necess\u00e1rio no Brasil do que aumentar a regula\u00e7\u00e3o dessa atividade.<\/div>\n<div><\/div>\n<div>Regula\u00e7\u00e3o para impedir propriedades cruzadas, monop\u00f3lio excessivo, exclusividade de informa\u00e7\u00e3o. Para impedir que uma TV compre a exclusividade de um evento e dificulte a sua exibi\u00e7\u00e3o. Para impedir que distribuidores de sinal de TV paga se recusem a admitir a entrada de novos produtores de conte\u00fado que concorram com seus controladores &#8211; como recentemente vimos no caso da Fox Sports.<\/div>\n<div><\/div>\n<div>Para resgatar a necessidade de que a profiss\u00e3o de jornalista seja exclusiva de quem possui forma\u00e7\u00e3o espec\u00edfica. Para que n\u00e3o haja pr\u00e1ticas que limitem a concorr\u00eancia mediante a concess\u00e3o de polpudos descontos para anunciantes que se comprometam a n\u00e3o anunciar em ve\u00edculos concorrentes.<\/div>\n<div><\/div>\n<div>Para isso tudo precisamos de regula\u00e7\u00e3o.<\/div>\n<div><\/div>\n<div>Mas quando eu ou\u00e7o vozes a defender regula\u00e7\u00e3o para criar um \u00f3rg\u00e3o que possa interferir de algum modo quando uma revista pilantra se alia a um bicheiro para inventar mat\u00e9rias, eu tremo nas bases. Parece que h\u00e1 mesmo o desejo de calar opini\u00f5es divergentes. Afinal, se h\u00e1 crime envolvido, o caso \u00e9 de pol\u00edcia, n\u00e3o de um \u00f3rg\u00e3o regulador.<\/div>\n<div><\/div>\n<div>Deixem a Veja falar as bobagens dela em paz. H\u00e1 quem acredite em bruxas. H\u00e1 quem goste de Paulo Coelho. H\u00e1 quem se emocione com o Sertanejo Universit\u00e1rio. H\u00e1 quem goste de ser enganado pela Veja. Fazer o que, n\u00e9? Vive la Diff\u00e9rence!<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nesta segunda feira, a coluna &#8220;Bissexta&#8221;, do advogado Walter Monteiro, mostra o quadro atual do jornalismo de massa brasileiro, suas intera\u00e7\u00f5es com a pol\u00edtica eTour Details<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[54,33,24],"class_list":["post-11042","post","type-post","status-publish","format-standard","hentry","category-bissexta","tag-imprensa","tag-jornalismo","tag-politica"],"_links":{"self":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/11042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/comments?post=11042"}],"version-history":[{"count":0,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/posts\/11042\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/media?parent=11042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/categories?post=11042"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pedromigao.com.br\/ourodetolo\/wp-json\/wp\/v2\/tags?post=11042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}